{"id":1072,"date":"2024-02-21T18:43:48","date_gmt":"2024-02-21T18:43:48","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1072"},"modified":"2024-02-21T18:43:48","modified_gmt":"2024-02-21T18:43:48","slug":"chrome-wont-open-on-windows-11-try-these-9-fixes-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/chrome-wont-open-on-windows-11-try-these-9-fixes-it\/","title":{"rendered":"Chrome non si apre su Windows 11? Prova queste 9 soluzioni"},"content":{"rendered":"<p>Windows 11 \u00e8 un nuovo sistema operativo desktop e presenta ancora molti difetti. Sperimenterai pi\u00f9 bug e problemi tecnici se utilizzi build Beta o Dev di Windows 11.<\/p>\n<p>Sebbene Windows 11 abbia il suo browser Web interno, Microsoft Edge, gli utenti continuano a utilizzare Google Chrome. Google Chrome potrebbe presentare imperfezioni, ma \u00e8 comunque il miglior browser web per desktop e dispositivi mobili.<\/p>\n<p>Tuttavia, dopo l&#8217;aggiornamento a Windows 11, molti utenti hanno riscontrato problemi nell&#8217;utilizzo del browser Google Chrome. Molti utenti hanno segnalato che Chrome non si apre in Windows 11. Ogni volta che l&#8217;utente fa doppio clic sull&#8217;icona di Google Chrome, non succede nulla.<\/p>\n<h2><span id=\"How_to_Fix_Chrome_Not_Opening_on_Windows_11\"><strong>Come risolvere il problema con Chrome che non si apre su Windows 11<\/strong><\/span><\/h2>\n<p>Quindi, se anche tu stai affrontando un problema simile, continua a leggere l&#8217;articolo. Di seguito, abbiamo condiviso alcuni dei metodi migliori per correggere che Google Chrome non si apre in Windows 11. Queste sono soluzioni alternative generali e dovrebbero risolvere il problema. Iniziamo.<\/p>\n<h3><span id=\"1_Restart_your_computer\"><strong>1. Riavvia il computer<\/strong><\/span><\/h3>\n<figure class=\"wp-block-image\"><img alt=\"Riavvia il tuo computer\" class=\"wp-image\" decoding=\"async\" height=\"571\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Restart-your-computer-1-9.webp\" title=\"Riavvia il tuo computer\" width=\"600\"\/><\/figure>\n<p>Windows 11 presenta numerosi bug e alcuni di essi possono impedire l&#8217;avvio di Chrome o di altre applicazioni. Riavviare il computer \u00e8 il modo migliore per prevenire tali bug.<\/p>\n<p>Se Chrome non si apre sul tuo computer, devi riavviare il PC. Dopo il riavvio, apri nuovamente Google Chrome. Questa volta il browser Chrome si aprir\u00e0 senza problemi.<\/p>\n<h3><span id=\"2_Close_all_background_processes_related_to_Chrome\"><strong>2. Chiudi tutti i processi in background relativi a Chrome<\/strong><\/span><\/h3>\n<p>Alcuni processi relativi a Chrome sono gi\u00e0 in esecuzione in background, impedendo il riavvio dell&#8217;applicazione. Ci\u00f2 pu\u00f2 verificarsi nel sistema operativo Windows e, quando ci\u00f2 accade, Chrome potrebbe non essere visualizzato sullo schermo, ma viene eseguito silenziosamente in background.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Ultimo compito\" class=\"wp-image\" decoding=\"async\" height=\"482\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Close-all-background-processes-related-to-Chrome.webp\" title=\"Ultimo compito\" width=\"500\"\/><\/figure>\n<p>Pertanto, \u00e8 necessario chiudere tutti i processi in background relativi a Chrome per risolvere il problema di mancata apertura di Chrome su Windows 11. Per chiudere tutti i processi relativi a Chrome, aprire la ricerca di Windows 11 e digitare Task Manager.<\/p>\n<p>Successivamente, apri Task Manager e devi chiudere tutti i processi di Google Chrome. Per chiuderlo, seleziona Google Chrome e &#8221; <strong>Termina operazione<\/strong> &#8221; nell&#8217;angolo in alto a destra.<\/p>\n<h3><span id=\"3_Create_a_new_Google_Chrome_Shortcut\"><strong>3. Crea un nuovo collegamento di Google Chrome<\/strong><\/span><\/h3>\n<p>Windows 11 viene fornito con una versione migliorata di Windows Defender. Sebbene Windows Security o Defender siano piuttosto robusti, presentano alcuni difetti. A volte blocca l&#8217;esecuzione di applicazioni legittime.<\/p>\n<p>Quindi, \u00e8 probabile che abbia bloccato l&#8217;esecuzione di Google Chrome sul computer. Puoi consentire a Google Chrome di accedere a Internet su Defender o creare un nuovo collegamento a Google Chrome sul desktop. Ecco come creare un nuovo collegamento di Google Chrome.<\/p>\n<p>1. Fai clic con il pulsante destro del mouse sull&#8217;icona di Google Chrome sul desktop e seleziona <strong>Apri posizione file<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Aprire la destinazione del file\" class=\"wp-image\" decoding=\"async\" height=\"400\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Create-a-new-Google-Chrome-Shortcut-1.webp\" title=\"Aprire la destinazione del file\" width=\"364\"\/><\/figure>\n<p>2. Quando si apre il percorso del file, fare clic con il pulsante destro del mouse sul file eseguibile di Chrome e selezionare <strong>Crea collegamento<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Creare una scorciatoia\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Create-a-new-Google-Chrome-Shortcut-2.webp\" title=\"Creare una scorciatoia\" width=\"600\"\/><\/figure>\n<p>3. Successivamente, nella richiesta di conferma, fare clic sul pulsante <strong>S\u00ec<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"S\u00cc\" class=\"wp-image\" decoding=\"async\" height=\"128\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Create-a-new-Google-Chrome-Shortcut-3.webp\" title=\"S\u00cc\" width=\"400\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ci\u00f2 creer\u00e0 un nuovo collegamento per Google Chrome sul desktop. Devi avviare questo nuovo collegamento invece di quello vecchio.<\/p>\n<h3><span id=\"4_Open_Chrome_with_Compatibility_Settings\"><strong>4. Apri Chrome con le Impostazioni di compatibilit\u00e0<\/strong><\/span><\/h3>\n<p>Anche se l&#8217;ultima versione di Google Chrome \u00e8 completamente compatibile con Windows 11, forse la versione di Chrome che stai utilizzando \u00e8 obsoleta oppure la build di Windows 11 che stai utilizzando presenta un bug che crea un problema di compatibilit\u00e0 con il browser Chrome.<\/p>\n<p>Puoi eliminare tali problemi aprendo Google Chrome con le impostazioni di compatibilit\u00e0. Ecco cosa devi fare.<\/p>\n<p>1. Fai clic con il pulsante destro del mouse sull&#8217;icona del desktop di Google Chrome e seleziona <strong>Propriet\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Propriet\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"400\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Open-Chrome-with-Compatibility-Settings-2.webp\" title=\"Propriet\u00e0\" width=\"330\"\/><\/figure>\n<p>2. Nelle propriet\u00e0 di Google Chrome, passa alla scheda <strong>Compatibilit\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Compatibilit\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Open-Chrome-with-Compatibility-Settings.webp\" title=\"Compatibilit\u00e0\" width=\"321\"\/><\/figure>\n<p>3. Successivamente, in Modalit\u00e0 compatibilit\u00e0, seleziona Esegui <strong>questo programma in modalit\u00e0 compatibilit\u00e0 per<\/strong> : e seleziona <strong>Windows 8<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui questo programma in modalit\u00e0 compatibilit\u00e0 per\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Open-Chrome-with-Compatibility-Settings-3.webp\" title=\"Esegui questo programma in modalit\u00e0 compatibilit\u00e0 per\" width=\"323\"\/><\/figure>\n<p>4. Dopo aver apportato le modifiche, fare clic sul pulsante <strong>Applica<\/strong> .<\/p>\n<p>Questo \u00e8 tutto! Ora esegui il browser Google Chrome. Questa volta Google Chrome verr\u00e0 avviato immediatamente.<\/p>\n<h3><span id=\"5_Run_the_Compatibility_Troubleshooter\"><strong>5. Eseguire lo strumento di risoluzione dei problemi di compatibilit\u00e0<\/strong><\/span><\/h3>\n<p>Se l&#8217;esecuzione di Google Chrome in modalit\u00e0 compatibilit\u00e0 non ha risolto il problema, puoi provare a eseguire lo strumento di risoluzione dei problemi di compatibilit\u00e0 di Chrome. Ecco come eseguire lo strumento di risoluzione dei problemi di compatibilit\u00e0 nel browser Chrome.<\/p>\n<p>1. Fai clic con il pulsante destro del mouse sull&#8217;icona dell&#8217;app Google Chrome e seleziona <strong>Propriet\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Propriet\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Chrome-Properties-1.webp\" title=\"Propriet\u00e0\" width=\"460\"\/><\/figure>\n<p>2. Nelle Propriet\u00e0 di Chrome, passa alla scheda <strong>Compatibilit\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Compatibilit\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Chrome-Properties-2.webp\" title=\"Compatibilit\u00e0\" width=\"464\"\/><\/figure>\n<p>3. Successivamente, fai clic sul pulsante <strong>Esegui risoluzione dei problemi di compatibilit\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui lo strumento di risoluzione dei problemi di compatibilit\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Chrome-Properties-3.webp\" title=\"Esegui lo strumento di risoluzione dei problemi di compatibilit\u00e0\" width=\"464\"\/><\/figure>\n<p>4. Ora basta seguire le istruzioni visualizzate sullo schermo per completare il processo di risoluzione dei problemi.<\/p>\n<p>Dopo aver apportato le modifiche, apri il browser Google Chrome. Questa volta il browser web dovrebbe aprirsi senza problemi.<\/p>\n<h3><span id=\"6_Prevent_Chrome_from_Restarting_itself\"><strong>6. Impedisci a Chrome di riavviarsi da solo<\/strong><\/span><\/h3>\n<p>Bene, c&#8217;\u00e8 una funzionalit\u00e0 che aiuta a riavviare l&#8217;applicazione quando non risponde. Quindi, se Google Chrome non risponde, la funzionalit\u00e0 di cui stiamo parlando forzer\u00e0 il riavvio del browser.<\/p>\n<p>Questa cosa accade in background e non noterai nulla. Molti utenti hanno affermato di risolvere il problema &#8220;Chrome non si apre su Windows 11&#8221; semplicemente disabilitando questa funzione. Quindi puoi provare anche quello. Ecco cosa devi fare.<\/p>\n<p>1. Fai clic con il pulsante destro del mouse sull&#8217;icona del desktop di Google Chrome e seleziona <strong>Propriet\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Propriet\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"400\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Open-Chrome-with-Compatibility-Settings-2-1.webp\" title=\"Propriet\u00e0\" width=\"330\"\/><\/figure>\n<p>2. Nelle propriet\u00e0 di Google Chrome, passa alla scheda <strong>Compatibilit\u00e0<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Compatibilit\u00e0\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Open-Chrome-with-Compatibility-Settings-1.webp\" title=\"Compatibilit\u00e0\" width=\"321\"\/><\/figure>\n<p>3. Nella sezione Impostazioni, deseleziona <strong>Registra questo programma per il riavvio<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Registra questo programma per il riavvio\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Prevent-Chrome-from-Restarting-itself-1.webp\" title=\"Registra questo programma per il riavvio\" width=\"318\"\/><\/figure>\n<p>4. Dopo aver apportato le modifiche, fare clic sul pulsante <strong>Applica<\/strong> e quindi su <strong>OK<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Registra questo programma per il riavvio\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Prevent-Chrome-from-Restarting-itself-2.webp\" title=\"Registra questo programma per il riavvio\" width=\"322\"\/><\/figure>\n<p>Questo \u00e8 tutto! Dopo aver disabilitato la funzione, apri nuovamente Google Chrome. Se il problema persiste, seguire i metodi successivi.<\/p>\n<h3><span id=\"7_Delete_the_Default_User_Data_in_Chrome\"><strong>7. Elimina i dati utente predefiniti in Chrome<\/strong><\/span><\/h3>\n<p>Google Chrome memorizza tutti i tuoi dati nella cartella Dati utente. Se i dati salvati si corrompono, Google Chrome non si avvier\u00e0. Pertanto, puoi rimuovere la cartella predefinita dei dati utente per risolvere il problema che Chrome non si apre su Windows 11. Ecco cosa devi fare.<\/p>\n<p>1. Premi il tasto Windows + il pulsante R sulla tastiera. Questo aprir\u00e0 la finestra di dialogo ESEGUI.<\/p>\n<p>2. Quando si apre la finestra di dialogo ESEGUI, digitare <strong>Appdata<\/strong> e premere Invio.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Dati dell'app\" class=\"wp-image\" decoding=\"async\" height=\"263\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Delete-the-Default-User-Data-in-Chrome-1.webp\" title=\"Dati dell'app\" width=\"434\"\/><\/figure>\n<p>3. Ora, individua il seguente percorso:<\/p>\n<p> <code><strong>Local\\Google\\Chrome\\User Data<\/strong><\/code><\/p>\n<p>4. Ora, nella cartella Dati utente, fai clic con il pulsante destro del mouse sulla cartella denominata <strong>Predefinita<\/strong> e seleziona <strong>Elimina<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Eliminare\" class=\"wp-image\" decoding=\"async\" height=\"474\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Delete-the-Default-User-Data-in-Chrome-2.webp\" title=\"Eliminare\" width=\"600\"\/><\/figure>\n<p>Questo \u00e8 tutto! Dopo aver apportato le modifiche, chiudi la cartella e apri Google Chrome. Potrebbe essere necessario accedere nuovamente con il tuo account Google.<\/p>\n<h3><span id=\"8_Disable_Windows_DefenderAntivirus_Programs\"><strong>8. Disattiva i programmi Windows Defender\/Antivirus<\/strong><\/span><\/h3>\n<p>I sistemi firewall e i programmi antivirus possono spesso impedire l&#8217;esecuzione di Google Chrome. Quando ci\u00f2 accade, Google Chrome non si aprir\u00e0 su Windows 11.<\/p>\n<p>Il modo migliore per gestire questo problema \u00e8 disabilitare Windows Defender Firewall o qualsiasi software antivirus di terze parti in uso. Ecco come disabilitare Windows Defender.<\/p>\n<p>1. Apri l&#8217;app Sicurezza di Windows e seleziona <strong>Protezione da virus e minacce<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Protezione da virus e minacce\" class=\"wp-image\" decoding=\"async\" height=\"404\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Disable-Antivirus-Programs-1.webp\" title=\"Protezione da virus e minacce\" width=\"600\"\/><\/figure>\n<p>2. Fare clic sul collegamento Gestisci impostazioni nelle impostazioni Protezione da virus e minacce.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Gestisci impostazione\" class=\"wp-image\" decoding=\"async\" height=\"432\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Disable-Antivirus-Programs-2.webp\" title=\"Gestisci impostazione\" width=\"640\"\/><\/figure>\n<p>3. Nella schermata successiva, disattiva la <strong>protezione in tempo reale<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Protezione in tempo reale\" class=\"wp-image\" decoding=\"async\" height=\"434\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Disable-Antivirus-Programs-3.webp\" title=\"Protezione in tempo reale\" width=\"640\"\/><\/figure>\n<p>4. \u00c8 inoltre necessario disabilitare i programmi firewall di terze parti.<\/p>\n<p>Questo \u00e8 tutto! Ecco come puoi disattivare l&#8217;app Sicurezza di Windows su Windows 11 per risolvere il problema con <strong>Google Chrome che non si apre su Windows 11<\/strong> .<\/p>\n<h3><span id=\"9_Reinstall_the_Google_Chrome_browser\"><strong>9. Reinstallare il browser Google Chrome<\/strong><\/span><\/h3>\n<p>Poich\u00e9 non puoi ripristinare Chrome perch\u00e9 non si apre, prova a reinstallarlo sul tuo computer. La reinstallazione escluder\u00e0 qualsiasi danneggiamento dei dati durante l&#8217;installazione.<\/p>\n<p>Pertanto, se Chrome non si apre su Windows 11 a causa di file di installazione danneggiati, la reinstallazione risolver\u00e0 il problema.<\/p>\n<p>Per reinstallare Chrome, apri il Pannello di controllo, fai clic con il pulsante destro del mouse su Chrome e seleziona &#8220;Disinstalla&#8221;. Una volta disinstallato, reinstalla nuovamente Google Chrome.<\/p>\n<p>Quindi, questi sono alcuni dei modi migliori per correggere Chrome che non si apre su Windows 11. Se hai bisogno di ulteriore aiuto per risolvere i problemi di Chrome su Windows, faccelo sapere nei commenti. Inoltre, se l&#8217;articolo ti ha aiutato, assicurati di condividerlo anche con i tuoi amici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Windows 11 \u00e8 un nuovo sistema operativo desktop e presenta ancora molti difetti. Sperimenterai pi\u00f9 bug e problemi tecnici se utilizzi build Beta o Dev di Windows 11. Sebbene Windows 11 abbia il suo browser Web interno, Microsoft Edge, gli utenti continuano a utilizzare Google Chrome. Google Chrome potrebbe presentare imperfezioni, ma \u00e8 comunque il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[56],"class_list":["post-1072","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-tips"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1073,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1073"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}