{"id":1116,"date":"2024-02-24T16:56:15","date_gmt":"2024-02-24T16:56:15","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1116"},"modified":"2024-02-24T16:56:15","modified_gmt":"2024-02-24T16:56:15","slug":"how-to-enable-show-desktop-button-in-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-enable-show-desktop-button-in-windows-11-it\/","title":{"rendered":"Come abilitare Mostra pulsante Desktop in Windows 11"},"content":{"rendered":"<p>Su Windows 10 e 11, hai un pulsante &#8220;Mostra desktop&#8221; che si trova all&#8217;estremit\u00e0 destra della barra delle applicazioni. Lo scopo del pulsante Mostra desktop \u00e8 ridurre a icona tutte le finestre aperte per offrirti una visualizzazione del desktop.<\/p>\n<p>Gli utenti che accedono spesso a vari programmi e file dal desktop fanno eccessivo affidamento sul pulsante Mostra desktop di Windows 10\/11. Tuttavia, cosa succede se il pulsante scompare e sei costretto a ridurre a icona manualmente tutte le finestre?<\/p>\n<p>In realt\u00e0, molti utenti di Windows 11 si trovano ad affrontare questo problema ora. Il recente aggiornamento di Windows 11 ha sostituito Mostra desktop con il pulsante Copilot all&#8217;estremit\u00e0 destra della barra delle applicazioni. Ci\u00f2 significa che se stai utilizzando le ultime build di Windows 11, troverai il pulsante Copilot invece di Mostra desktop.<\/p>\n<h3><span id=\"Why_did_the_Show_Desktop_Button_Disappear\"><strong>Perch\u00e9 il pulsante &#8220;Mostra desktop&#8221; \u00e8 scomparso?<\/strong><\/span><\/h3>\n<p>Il pulsante &#8220;Mostra desktop&#8221; \u00e8 scomparso perch\u00e9 Microsoft desidera che tu utilizzi la sua nuova app di assistente AI, Copilot.<\/p>\n<p>Microsoft di solito apporta modifiche alle impostazioni predefinite di Windows 11 ogni volta che lancia un nuovo prodotto. Anche Windows 11 non ha la classica Gestione dispositivi, la pagina Informazioni di sistema, ecc.<\/p>\n<p>Tuttavia, la cosa buona \u00e8 che l&#8217;opzione &#8220;Mostra desktop&#8221; non \u00e8 stata rimossa da Windows 11; \u00e8 semplicemente disabilitato per impostazione predefinita.<\/p>\n<h2><span id=\"How_to_Enable_Show_Desktop_Button_in_Windows_11_Taskbar\"><strong>Come abilitare Mostra pulsante Desktop nella barra delle applicazioni di Windows 11?<\/strong><\/span><\/h2>\n<p>Poich\u00e9 il pulsante &#8220;Mostra desktop&#8221; \u00e8 semplicemente disabilitato su Windows 11, \u00e8 facile ripristinarlo. Ecco come ripristinare il pulsante Mostra desktop nella barra delle applicazioni di Windows 11.<\/p>\n<p>1. Fare clic con il tasto destro su uno spazio vuoto sulla barra delle applicazioni di Windows 11.<\/p>\n<p>2. Nel menu visualizzato, seleziona <strong>Impostazioni barra delle applicazioni<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni della barra delle applicazioni\" class=\"wp-image\" decoding=\"async\" height=\"217\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Taskbar-Settings.webp\" title=\"Impostazioni della barra delle applicazioni\" width=\"700\"\/><\/figure>\n<p>3. Se non riesci ad accedere alle Impostazioni della barra delle applicazioni, vai su <strong>Impostazioni &gt; Personalizzazione &gt; Barra delle applicazioni<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni &gt; Personalizzazione &gt; Barra delle applicazioni\u201d title=\u201dImpostazioni &gt; Personalizzazione &gt; Barra delle applicazioni\u201d larghezza=\u201d900\u2033 altezza=\u201d645\u2033 caricamento=\u201dlazy\u201d class=\u201dwp-image\u201d src=\u201dhttps:\/\/cdn.howtogeek.blog\/ wp-content\/uploads\/2024\/02\/Taskbar-Settings-2.webp\u201d\/&gt;&lt;\/figure&gt; &lt;p&gt;4. Nelle Impostazioni della barra delle applicazioni, scorri verso il basso e fai clic su &lt;strong&gt;Comportamenti della barra delle applicazioni&lt;\/strong&gt;.&lt;\/p&gt; &lt;figure class=\" wp-block-image=\"\"\/><img alt=\"Comportamenti della barra delle applicazioni\" class=\"wp-image\" decoding=\"async\" height=\"366\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Taskbar-Settings-3.webp\" title=\"Comportamenti della barra delle applicazioni\" width=\"900\"\/><\/figure>\n<p>5. Nei comportamenti della barra delle applicazioni, <strong>seleziona<\/strong> l&#8217;opzione &#8220;Seleziona l&#8217;angolo pi\u00f9 lontano della barra delle applicazioni per mostrare il desktop&#8221;.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Seleziona l'angolo pi\u00f9 lontano della barra delle applicazioni per mostrare il desktop\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Taskbar-Settings-4.webp\" title=\"Seleziona l'angolo pi\u00f9 lontano della barra delle applicazioni per mostrare il desktop\" width=\"900\"\/><\/figure>\n<p>6. Una volta apportata la modifica, noterai che appare una <strong>piccola barra argentata trasparente<\/strong> nell&#8217;angolo destro della barra delle applicazioni.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"piccola barra d'argento trasparente\" class=\"wp-image\" decoding=\"async\" height=\"364\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Taskbar-Settings-5.webp\" title=\"piccola barra d'argento trasparente\" width=\"707\"\/><\/figure>\n<p>Assicurati di riavviare il computer se non vedi il pulsante Mostra desktop. Dopo il riavvio, puoi utilizzare il vecchio pulsante Mostra desktop su Windows 11.<\/p>\n<p>Quindi, questa guida riguarda l&#8217;attivazione del pulsante &#8220;Mostra desktop&#8221; nella barra delle applicazioni di Windows 11. Dovresti seguire i nostri passaggi condivisi per ripristinare l&#8217;icona mancante su Windows 11. Se hai bisogno di ulteriore aiuto per abilitare il pulsante &#8220;Mostra desktop&#8221; in Windows 11, faccelo sapere nei commenti qui sotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su Windows 10 e 11, hai un pulsante &#8220;Mostra desktop&#8221; che si trova all&#8217;estremit\u00e0 destra della barra delle applicazioni. Lo scopo del pulsante Mostra desktop \u00e8 ridurre a icona tutte le finestre aperte per offrirti una visualizzazione del desktop. Gli utenti che accedono spesso a vari programmi e file dal desktop fanno eccessivo affidamento sul [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[56],"class_list":["post-1116","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-tips"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1116"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1116\/revisions"}],"predecessor-version":[{"id":1117,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1116\/revisions\/1117"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}