{"id":1138,"date":"2024-02-26T16:08:14","date_gmt":"2024-02-26T16:08:14","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1138"},"modified":"2024-02-26T16:08:14","modified_gmt":"2024-02-26T16:08:14","slug":"how-to-remove-objects-from-photos-in-windows-10-and-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-remove-objects-from-photos-in-windows-10-and-11-it\/","title":{"rendered":"Come rimuovere oggetti dalle foto in Windows 10 e 11"},"content":{"rendered":"<p>Potresti aver notato come smartphone come <u>Google Pixel<\/u> e Samsung Galaxy serie S possano rimuovere oggetti dalle foto utilizzando l&#8217;intelligenza artificiale. Ora, gli utenti Windows possono rimuovere oggetti dalle proprie foto utilizzando l&#8217;app Foto nativa. Tieni presente che per ora \u00e8 disponibile per Windows Insider ma in seguito verr\u00e0 rilasciato a tutti gli utenti. Detto questo, ecco come rimuovere oggetti da una foto in Windows 10 e 11.<\/p>\n<h2>Cancella oggetti dalle foto in Windows<\/h2>\n<p>Prima di iniziare, assicurati di utilizzare la versione pi\u00f9 recente di <a href=\"https:\/\/blogs.windows.com\/windows-insider\/2024\/02\/14\/announcing-windows-11-insider-preview-build-26058-canary-and-dev-channels\/\" rel=\"noreferrer noopener\" target=\"_blank\">Windows Insider Preview<\/a> (build 26058 o successiva) e di disporre della versione aggiornata dell&#8217;app <a href=\"https:\/\/apps.microsoft.com\/detail\/9wzdncrfjbh4\" rel=\"noreferrer noopener\" target=\"_blank\"><strong>Foto<\/strong><\/a> . Se quella parte \u00e8 coperta, seguire i passaggi seguenti:<\/p>\n<p><strong>1.<\/strong> Apri l&#8217; <strong>immagine<\/strong> utilizzando l&#8217; app <strong>Foto<\/strong> e fai clic sull&#8217;icona <strong>Modifica immagine<\/strong> (Ctrl + E).<\/p>\n<figure class=\"wp-block-image\"><img alt=\"fare clic sull'icona Modifica immagine\" class=\"wp-image\" decoding=\"async\" height=\"681\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/click-the-Edit-Image-icon.webp\" title=\"fare clic sull'icona Modifica immagine\" width=\"909\"\/><\/figure>\n<p><strong>2.<\/strong> Successivamente, fai clic sullo strumento <strong>Cancella<\/strong> . Da l\u00ec, regola le <strong>dimensioni del pennello<\/strong> e quindi maschera l&#8217; <strong>oggetto<\/strong> che desideri rimuovere dall&#8217;immagine.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"fare clic sullo strumento Cancella\" class=\"wp-image\" decoding=\"async\" height=\"623\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/click-on-the-Erase-tool-1024x623-1.webp\" title=\"fare clic sullo strumento Cancella\" width=\"1024\"\/><\/figure>\n<p>Come puoi vedere, ha rimosso l&#8217;oggetto (smartphone) dall&#8217;immagine.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Oggetto rimosso dalla foto\" class=\"wp-image\" decoding=\"async\" height=\"702\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Object-removed-from-the-photo-1024x702-1.webp\" title=\"Oggetto rimosso dalla foto\" width=\"1024\"\/><\/figure>\n<p><strong>3.<\/strong> Nel caso in cui desideri rimuovere pi\u00f9 oggetti contemporaneamente, devi disattivare l&#8217; impostazione <strong>Applicazione automatica<\/strong> e selezionare <strong>ciascun oggetto<\/strong> uno per uno. Una volta completato, premi il pulsante <strong>Cancella<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"rimuovere pi\u00f9 oggetti da una foto in una volta sola\" class=\"wp-image\" decoding=\"async\" height=\"612\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/remove-multiple-objects-from-a-photo-in-one-go-1-1024x612-1.webp\" title=\"rimuovere pi\u00f9 oggetti da una foto in una volta sola\" width=\"1024\"\/><\/figure>\n<p>Come mostrato nell&#8217;immagine seguente, gli oggetti sono stati rimossi dall&#8217;immagine.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Pi\u00f9 oggetti sono stati rimossi dalle foto\" class=\"wp-image\" decoding=\"async\" height=\"584\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Multiple-objects-has-been-removed-from-the-photos-1024x584-1.webp\" title=\"Pi\u00f9 oggetti sono stati rimossi dalle foto\" width=\"1024\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Cancella oggetti da una foto: prima e dopo\" class=\"wp-image\" decoding=\"async\" height=\"910\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Erase-objects-from-a-photo-Before-and-After-1024x910-1.webp\" title=\"Cancella oggetti da una foto: prima e dopo\" width=\"1024\"\/><\/figure>\n<p><strong>4.<\/strong> Ora, per salvare l&#8217;immagine, fare clic sul pulsante <strong>Salva<\/strong> e selezionare <strong>Salva come copia<\/strong> dal menu.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"749\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/click-on-the-Save-options.webp\" title=\"\" width=\"1007\"\/><\/figure>\n<p><strong>5.<\/strong> Successivamente, scegli la <strong>posizione<\/strong> in cui desideri salvare l&#8217;immagine e quindi premi il pulsante <strong>Salva<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"scegli la posizione di salvataggio\" class=\"wp-image\" decoding=\"async\" height=\"587\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/choose-the-save-location.webp\" title=\"scegli la posizione di salvataggio\" width=\"940\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"annullare o ripetere le modifiche durante la modifica\" class=\"wp-image\" decoding=\"async\" height=\"572\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/undo-or-redo-changes.webp\" title=\"annullare o ripetere le modifiche durante la modifica\" width=\"792\"\/><\/figure>\n<p>Abbiamo anche confrontato la capacit\u00e0 di Windows, Samsung Galaxy e Google Pixel di rimuovere oggetti da un&#8217;immagine. Ecco un confronto fianco a fianco dei risultati.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Confronto tra Google Pixel, Samsung Galaxy e PC Windows\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Comparison-between-Google-Pixel-Samsung-Galaxy-and-Windows-PC-1-1024x1024-1.webp\" title=\"Confronto tra Google Pixel, Samsung Galaxy e PC Windows\" width=\"1024\"\/><\/figure>\n<p>Su Google Pixel la bottiglia \u00e8 stata rimossa con successo; su Windows la tabella appariva molto pi\u00f9 pulita; e nel Samsung Galaxy \u00e8 stato raggiunto un rendimento bilanciato.<\/p>\n<h2>Addio oggetti indesiderati!<\/h2>\n<p>Ora non devi pi\u00f9 fare affidamento su strumenti o app online di terze parti per cancellare oggetti dalle foto. Ti manca solo un clic per rimuoverli dal tuo PC Windows. Ci auguriamo che la guida qui sopra ti abbia reso tutto pi\u00f9 semplice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Potresti aver notato come smartphone come Google Pixel e Samsung Galaxy serie S possano rimuovere oggetti dalle foto utilizzando l&#8217;intelligenza artificiale. Ora, gli utenti Windows possono rimuovere oggetti dalle proprie foto utilizzando l&#8217;app Foto nativa. Tieni presente che per ora \u00e8 disponibile per Windows Insider ma in seguito verr\u00e0 rilasciato a tutti gli utenti. Detto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[139,7],"class_list":["post-1138","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-microsoft-photos","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1138"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1138\/revisions"}],"predecessor-version":[{"id":1139,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1138\/revisions\/1139"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}