{"id":1319,"date":"2024-03-12T16:47:27","date_gmt":"2024-03-12T16:47:27","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1319"},"modified":"2024-03-12T16:47:27","modified_gmt":"2024-03-12T16:47:27","slug":"6-fixes-for-bluetooth-device-connected-but-no-sound-on-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/6-fixes-for-bluetooth-device-connected-but-no-sound-on-windows-11-it\/","title":{"rendered":"6 correzioni per il dispositivo Bluetooth connesso ma senza audio su Windows 11"},"content":{"rendered":"<p>I dispositivi audio Bluetooth offrono un modo conveniente per guardare streaming live, partecipare a riunioni e ascoltare musica senza il fastidio dei cavi aggrovigliati. Ma cosa succede se colleghi le tue cuffie o <u>altoparlanti Bluetooth preferiti al tuo PC Windows 11<\/u> senza audio? Non preoccuparti; non \u00e8 necessario tornare alle connessioni cablate. Ecco alcuni suggerimenti per risolvere il problema quando il dispositivo Bluetooth \u00e8 connesso ma sul PC Windows 11 non viene emesso alcun suono.<\/p>\n<h2><span id=\"1-Check-the-Default-Audio-Device-and-Volume-Level\">1. Controllare il dispositivo audio predefinito e il livello del volume<\/span><\/h2>\n<p>Prima di affrontare qualsiasi suggerimento avanzato per la risoluzione dei problemi presente in questo elenco, \u00e8 una buona idea controllare il livello del volume e il dispositivo di uscita audio predefinito sul tuo PC Windows 11. Ecco come farlo.<\/p>\n<p><strong>1.<\/strong> Fare clic con il pulsante destro del mouse sull&#8217;icona <strong>dell&#8217;altoparlante<\/strong> nell&#8217;angolo in basso a destra sulla barra delle applicazioni e selezionare <strong>Impostazioni audio<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Apri Impostazioni audio su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"581\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Open-Sound-Settings-on-Windows-11.webp\" title=\"Apri Impostazioni audio su Windows 11\" width=\"967\"\/><\/figure>\n<p><strong>2.<\/strong> Seleziona il tuo dispositivo Bluetooth nella sezione <strong>Uscita<\/strong> . Quindi, utilizza il cursore del volume per aumentarlo a tuo piacimento.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Controlla il dispositivo di uscita audio predefinito su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"634\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Check-Default-Audio-Output-Device-on-Windows-11.webp\" title=\"Controlla il dispositivo di uscita audio predefinito su Windows 11\" width=\"1001\"\/><\/figure>\n<h2><span id=\"2-Change-Audio-Format-and-Disable-Sound-Enhancements\">2. Modifica il formato audio e disattiva i miglioramenti audio<\/span><\/h2>\n<p>Se Windows non riproduce l&#8217;audio tramite le cuffie o gli altoparlanti Bluetooth anche dopo averlo impostato come opzione predefinita, il problema potrebbe risiedere nel formato audio impostato. Ci\u00f2 pu\u00f2 verificarsi anche se hai abilitato le funzionalit\u00e0 di miglioramento audio su Windows e il tuo dispositivo audio Bluetooth non le supporta. Ecco come risolvere il problema.<\/p>\n<p><strong>1.<\/strong> Fare clic con il pulsante destro del mouse <strong>sull&#8217;icona dell&#8217;altoparlante<\/strong> sulla barra delle applicazioni e selezionare <strong>Impostazioni audio<\/strong> .<\/p>\n<p><strong>2.<\/strong> Fare clic sulla freccia accanto al dispositivo audio Bluetooth.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Dispositivo di uscita audio su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"605\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Audio-Output-Device-on-Windows-11.webp\" title=\"Dispositivo di uscita audio su Windows 11\" width=\"1006\"\/><\/figure>\n<p><strong>3.<\/strong> Utilizza il menu a discesa accanto a <strong>Formato<\/strong> per selezionare diverse opzioni e verificare se funzionano. Utilizzare il pulsante <strong>Test<\/strong> per controllare l&#8217;uscita audio dopo aver modificato il formato.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cambia il formato di uscita audio su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"635\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Change-Audio-Output-Format-on-Windows-11.webp\" title=\"Cambia il formato di uscita audio su Windows 11\" width=\"1025\"\/><\/figure>\n<p><strong>4.<\/strong> Scorrere verso il basso e impostare <strong>Miglioramenti audio<\/strong> e <strong>Suono spaziale<\/strong> su <strong>Disattivato<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Disattiva i miglioramenti audio su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"633\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Turn-Off-Audio-Enhancements-on-Windows-11-1024x633-1.webp\" title=\"Disattiva i miglioramenti audio su Windows 11\" width=\"1024\"\/><\/figure>\n<p>Successivamente prova a riprodurre l&#8217;audio sul tuo PC e controlla se il problema persiste.<\/p>\n<h2><span id=\"3-Unpair-and-Pair-the-Bluetooth-Device\">3. Disaccoppia e accoppia il dispositivo Bluetooth<\/span><\/h2>\n<p>Anche le cuffie o gli altoparlanti audio Bluetooth potrebbero rifiutarsi di riprodurre l&#8217;audio o <u>continuare a interrompersi se non sono accoppiati correttamente<\/u> . Pertanto, puoi risolvere tali problemi disaccoppiando il dispositivo problematico e associandolo nuovamente. Ecco i passaggi per farlo.<\/p>\n<p><strong>1.<\/strong> Premi il <strong>tasto Windows + I<\/strong> scorciatoia da tastiera per aprire l&#8217; <strong>app Impostazioni<\/strong> . Passa alla scheda <strong>Bluetooth e dispositivi<\/strong> nella barra laterale di sinistra e fai clic su <strong>Dispositivi<\/strong> nel riquadro di destra.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Dispositivi Bluetooth su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"628\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Bluetooth-Devices-on-Windows-11-1024x628-1.webp\" title=\"Dispositivi Bluetooth su Windows 11\" width=\"1024\"\/><\/figure>\n<p><strong>2.<\/strong> Nella sezione <strong>Audio<\/strong> , fai clic <strong>sull&#8217;icona del menu con tre punti<\/strong> accanto al tuo dispositivo Bluetooth e seleziona <strong>Rimuovi dispositivo<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Rimuovere il dispositivo Bluetooth da Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"602\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Remove-Bluetooth-Device-From-Windows-11.webp\" title=\"Rimuovere il dispositivo Bluetooth da Windows 11\" width=\"1004\"\/><\/figure>\n<p><strong>3.<\/strong> Fare clic sul pulsante <strong>Aggiungi dispositivo<\/strong> in alto e selezionare <strong>Bluetooth<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Aggiungi un dispositivo Bluetooth a Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"575\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Add-Bluetooth-Device-to-Windows-11-1024x575-1.webp\" title=\"Aggiungi un dispositivo Bluetooth a Windows 11\" width=\"1024\"\/><\/figure>\n<p><strong>4.<\/strong> Metti le cuffie o gli altoparlanti Bluetooth in modalit\u00e0 di accoppiamento, quindi selezionali quando vengono visualizzati in Windows 11 sul tuo PC.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Associa il dispositivo Bluetooth a Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"511\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Pair-Bluetooth-Device-to-Windows-11.webp\" title=\"Associa il dispositivo Bluetooth a Windows 11\" width=\"821\"\/><\/figure>\n<p>Quando il tuo dispositivo Bluetooth si connette, impostalo come opzione predefinita per verificare se riproduce l&#8217;audio.<\/p>\n<h2><span id=\"4-Run-the-Bluetooth-and-Audio-Troubleshooters\">4. Eseguire gli strumenti di risoluzione dei problemi audio e Bluetooth<\/span><\/h2>\n<p>Un&#8217;altra cosa che puoi fare \u00e8 eseguire gli strumenti di risoluzione dei problemi Bluetooth e audio. Ci\u00f2 consentir\u00e0 a Windows di diagnosticare l&#8217;audio comune e risolvere eventuali problemi relativi al Bluetooth.<\/p>\n<p><strong>1.<\/strong> Premere il <strong>tasto Windows + S<\/strong> scorciatoia da tastiera per aprire il menu di ricerca. Digitare <strong>le impostazioni per la risoluzione dei problemi<\/strong> nella casella e premere <strong>Invio<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Risolvere i problemi delle impostazioni su Windows\" class=\"wp-image\" decoding=\"async\" height=\"631\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Troubleshoot-Settings-on-Windows.webp\" title=\"Risolvere i problemi delle impostazioni su Windows\" width=\"1019\"\/><\/figure>\n<p><strong>2.<\/strong> Fare clic su <strong>Altri strumenti per la risoluzione dei problemi<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Altri strumenti per la risoluzione dei problemi su Windows\" class=\"wp-image\" decoding=\"async\" height=\"599\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Other-Troubleshooters-on-Windows-1024x599-1.webp\" title=\"Altri strumenti per la risoluzione dei problemi su Windows\" width=\"1024\"\/><\/figure>\n<p><strong>3.<\/strong> Fare clic sul pulsante <strong>Esegui<\/strong> accanto ad <strong>Audio<\/strong> e seguire le istruzioni visualizzate sullo schermo per eseguire lo strumento. Allo stesso modo, esegui lo strumento di risoluzione dei problemi <strong>Bluetooth<\/strong> dallo stesso menu.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Risoluzione dei problemi audio e Bluetooth su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"629\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Audio-and-Bluetooth-Troubleshooters-on-Windows-11-1024x629-1.webp\" title=\"Risoluzione dei problemi audio e Bluetooth su Windows 11\" width=\"1024\"\/><\/figure>\n<h2><span id=\"5-Restart-the-Bluetooth-Support-Service\">5. Riavviare il servizio di supporto Bluetooth<\/span><\/h2>\n<p>Il servizio di supporto Bluetooth aiuta Windows a individuare e comunicare con i dispositivi Bluetooth nelle vicinanze. Se questo servizio non funziona correttamente sul tuo PC Windows 11, le cuffie o gli altoparlanti Bluetooth non emetteranno alcun suono.<\/p>\n<p>\u00c8 possibile riavviare manualmente il servizio di supporto Bluetooth.<\/p>\n<p><strong>1.<\/strong> Premere il <strong>tasto Windows + R<\/strong> scorciatoia da tastiera per aprire la finestra di dialogo Esegui. Digita services.msc nella casella e premi <strong>Invio<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Apri l'app Servizi su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"476\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Open-Services-App-on-Windows-11.webp\" title=\"Apri l'app Servizi su Windows 11\" width=\"700\"\/><\/figure>\n<p><strong>2.<\/strong> Fare clic con il pulsante destro del mouse sul <strong>Servizio di supporto Bluetooth<\/strong> e selezionare <strong>Riavvia<\/strong> . Se non \u00e8 in esecuzione, seleziona <strong>Start<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Riavvia il servizio audio Bluetooth su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"496\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Restart-Bluetooth-Audio-Service-on-Windows-11.webp\" title=\"Riavvia il servizio audio Bluetooth su Windows 11\" width=\"862\"\/><\/figure>\n<p>Dopo aver completato i passaggi precedenti, prova a riprodurre qualsiasi audio sul tuo dispositivo Bluetooth.<\/p>\n<h2><span id=\"6-Reinstall-Bluetooth-Drivers\">6. Reinstallare i driver Bluetooth<\/span><\/h2>\n<p>I driver Bluetooth sul PC facilitano la comunicazione tra Windows e i dispositivi Bluetooth, come cuffie e altoparlanti wireless. Se questi driver sono danneggiati, il tuo <u>dispositivo audio Bluetooth potrebbe non funzionare<\/u> .<\/p>\n<p>Per risolvere questo problema, puoi provare a reinstallare il driver problematico seguendo questi passaggi:<\/p>\n<p><strong>1.<\/strong> Fare clic con il tasto destro sull&#8217;icona <strong>Start<\/strong> e selezionare <strong>Gestione dispositivi<\/strong> dall&#8217;elenco.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Apri Gestione dispositivi su Windows\" class=\"wp-image\" decoding=\"async\" height=\"620\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Open-Device-Manager-on-Windows-1024x620-1.webp\" title=\"Apri Gestione dispositivi su Windows\" width=\"1024\"\/><\/figure>\n<p><strong>2.<\/strong> Espandi <strong>Bluetooth<\/strong> , fai clic con il pulsante destro del mouse sull&#8217;adattatore Bluetooth e seleziona <strong>Disinstalla dispositivo<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Disinstallare il driver Bluetooth su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"579\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Uninstall-Bluetooth-Driver-on-Windows-11.webp\" title=\"Disinstallare il driver Bluetooth su Windows 11\" width=\"965\"\/><\/figure>\n<p><strong>3.<\/strong> Selezionare <strong>Disinstalla<\/strong> per confermare.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Conferma la disinstallazione del driver Bluetooth su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"561\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Confirm-Uninstall-Bluetooth-Driver-on-Windows-11.webp\" title=\"Conferma la disinstallazione del driver Bluetooth su Windows 11\" width=\"897\"\/><\/figure>\n<p><u>Riavvia il PC<\/u> dopo aver completato i passaggi precedenti. Windows installer\u00e0 automaticamente i driver Bluetooth mancanti. Successivamente non dovresti riscontrare alcun problema.<\/p>\n<h2><span id=\"Unleash-the-Sound\">Scatena il suono<\/span><\/h2>\n<p>Quando ti abitui alla comodit\u00e0 di utilizzare cuffie o altoparlanti Bluetooth, pu\u00f2 essere difficile tornare alle alternative cablate. Ci auguriamo che seguire i suggerimenti sopra riportati abbia contribuito a risolvere il problema di fondo e che il dispositivo audio Bluetooth riproduca l&#8217;audio come previsto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dispositivi audio Bluetooth offrono un modo conveniente per guardare streaming live, partecipare a riunioni e ascoltare musica senza il fastidio dei cavi aggrovigliati. Ma cosa succede se colleghi le tue cuffie o altoparlanti Bluetooth preferiti al tuo PC Windows 11 senza audio? Non preoccuparti; non \u00e8 necessario tornare alle connessioni cablate. Ecco alcuni suggerimenti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5,28,6,7,9],"class_list":["post-1319","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-bluetooth","tag-sound","tag-troubleshooting","tag-windows","tag-windows-11"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1319"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1319\/revisions"}],"predecessor-version":[{"id":1320,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1319\/revisions\/1320"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}