{"id":1327,"date":"2024-03-13T16:18:10","date_gmt":"2024-03-13T16:18:10","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1327"},"modified":"2024-03-13T16:18:10","modified_gmt":"2024-03-13T16:18:10","slug":"what-do-icons-and-symbols-mean-in-messages-app-on-android-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/what-do-icons-and-symbols-mean-in-messages-app-on-android-it\/","title":{"rendered":"Cosa significano icone e simboli nell&#8217;app Messaggi su Android"},"content":{"rendered":"<p>Stavi mandando un messaggio a qualcuno quando all&#8217;improvviso hai visto un&#8217;icona sconosciuta nell&#8217;app di messaggistica del tuo telefono Android? Forse ti starai chiedendo cosa significano il campanello, la puntina, la stella o altre icone nell&#8217;app Messaggi. Ecco una guida dettagliata sul significato di varie icone e simboli nell&#8217;app Google Messaggi e Samsung Messaggi sui telefoni Android.<\/p>\n<h2><span id=\"Google-Messages-Symbols-and-Icons-Meaning\">Significato dei simboli e delle icone di Google Messaggi<\/span><\/h2>\n<h3>Icone della schermata iniziale<\/h3>\n<p><strong>Icona di ricerca:<\/strong> tocca questa icona per aprire la schermata di ricerca in cui puoi cercare qualsiasi messaggio digitando il testo o utilizzando opzioni di filtro come Immagini, Video, ecc.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-search-926x1024-1.webp\" title=\"\" width=\"926\"\/><\/figure>\n<p><strong>Umano in cerchio:<\/strong> tocca questa icona per passare da un account Google all&#8217;altro e modificare le impostazioni di Google Messaggi.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-settings-screen-926x1024-1.webp\" title=\"\" width=\"926\"\/><\/figure>\n<p><strong>Icona a fumetto sulla foto del profilo:<\/strong> se vedi un&#8217;icona a fumetto sull&#8217;immagine del profilo di un contatto, significa che il contatto sta utilizzando RCS. Per chi non lo sapesse, RCS sta per Rich Communication Services e consente di inviare messaggi via Internet. Puoi persino inviare foto, video, note vocali, GIF e altri contenuti multimediali di grandi dimensioni proprio come le altre app di messaggistica istantanea.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"657\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-chat-icon-on-contact.webp\" title=\"\" width=\"540\"\/><\/figure>\n<p><strong>Icona Appunta:<\/strong> l&#8217;icona Appunta indica che la conversazione \u00e8 bloccata e verr\u00e0 visualizzata in cima all&#8217;elenco dei messaggi anche se viene visualizzato un nuovo messaggio da qualsiasi altra chat.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"657\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-Pin-icon.webp\" title=\"\" width=\"540\"\/><\/figure>\n<p><strong>Casella con freccia<\/strong> : se scorri verso destra o sinistra su qualsiasi thread di messaggi, verr\u00e0 visualizzata una casella con una freccia rivolta verso il basso. Questa icona ti consente di archiviare il thread dei messaggi. Per chi non lo sapesse, l&#8217;archiviazione di un thread di messaggi lo nasconde dall&#8217;elenco principale. \u00c8 diverso dall&#8217;eliminazione poich\u00e9 nasconder\u00e0 solo il thread e non lo eliminer\u00e0 in modo permanente. Puoi annullare l&#8217;archiviazione del thread in qualsiasi momento. Scopri come <u>modificare il gesto di scorrimento<\/u> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-archive-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<h3>Icone che appaiono dopo aver premuto a lungo un thread di chat<\/h3>\n<p>Vedrai le seguenti icone se premi a lungo qualsiasi thread della chat:<\/p>\n<p><strong>Appunta:<\/strong> questa icona ti consente di appuntare il thread di messaggi selezionato.<\/p>\n<p><strong>Casella con freccia:<\/strong> tocca questa icona per archiviare il thread della chat.<\/p>\n<p><strong>Icona cestino:<\/strong> utilizza questa icona per eliminare la chat selezionata.<\/p>\n<p><strong>Cerchio con una barra:<\/strong> tocca questa icona per bloccare il contatto di cui hai selezionato il thread di messaggi.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-chat-thread-icons-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<h3>Icone in una chat<\/h3>\n<p>Quando apri qualsiasi thread di messaggi, vedrai le seguenti icone:<\/p>\n<p><strong>Videocamera:<\/strong> tocca questa icona per videochiamare il contatto. La chiamata verr\u00e0 effettuata tramite l&#8217;app Google Meet, precedentemente nota come Google Duo.<\/p>\n<p><strong>Telefono:<\/strong> utilizza questa icona per chiamare audio la persona utilizzando la normale app Telefono.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-message-call-icons-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<p><strong>Icona a forma di stella su un messaggio:<\/strong> l&#8217;icona a forma di stella viola su un messaggio indica che il messaggio \u00e8 stato aggiunto a Speciali per un accesso rapido.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-message-starred-message-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<p><strong>+ Icona:<\/strong> tocca questa icona per rivelare cose interessanti che puoi inviare nei messaggi di testo come GIF, foto, adesivi, <u>posizione<\/u> , ecc. Troverai anche un pulsante per programmare il messaggio.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-chat-icons-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<p><strong>Galleria con fotocamera<\/strong> : toccare questa icona per inviare le foto esistenti nella galleria o nuove immagini scattate utilizzando la fotocamera.<\/p>\n<p><strong>Faccina:<\/strong> toccando l&#8217;icona Faccina si aprir\u00e0 il pannello emoji dove troverai emoji, GIF, adesivi e Photomoji.<\/p>\n<p><strong>Onde:<\/strong> l&#8217;icona delle onde rappresenta le note vocali. Tocca questa icona per registrare note vocali.<\/p>\n<p><strong>Orologio con timer:<\/strong> il tuo messaggio \u00e8 in fase di invio ma non \u00e8 stato ancora inviato a causa di un problema di rete. Una volta inviato, l&#8217;icona cambier\u00e0 in un singolo segno di spunta.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-timer-icon-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<p><strong>Icona busta:<\/strong> quando digiti qualcosa nella casella di digitazione, l&#8217;icona delle onde cambier\u00e0 nell&#8217;icona della busta. Toccalo per inviare il messaggio alla persona o premi a lungo questa icona per programmare il messaggio.<\/p>\n<p><strong>Pulsante Invia con simbolo di blocco:<\/strong> il pulsante Invia con il simbolo di un lucchetto indica che il messaggio verr\u00e0 inviato come messaggio RCS. In tali messaggi viene utilizzata la crittografia end-to-end.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-envelope-icon-926x1024-1.webp\" title=\"\" width=\"926\"\/><\/figure>\n<h3>Icone che appaiono dopo aver premuto a lungo un messaggio<\/h3>\n<p>Se tieni premuto e premi un singolo messaggio in un thread di testo, verranno visualizzate le seguenti icone:<\/p>\n<p><strong>Icona Copia:<\/strong> tocca questa icona per copiare il messaggio selezionato negli appunti del telefono.<\/p>\n<p><strong>Icona del cestino:<\/strong> tocca questa icona per eliminare il messaggio selezionato.<\/p>\n<p><strong>Speciali:<\/strong> utilizzare questa icona per contrassegnare come Speciali il messaggio selezionato. Una volta aggiunto agli Speciali, sul messaggio speciale verr\u00e0 visualizzata l&#8217;icona di una stella. Tocca la barra di ricerca seguita dal pulsante Speciali per trovare i messaggi speciali.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-star-and-copy-icons-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<h2><span id=\"RCS-Message-Symbols-Meaning\">Significato dei simboli dei messaggi RCS<\/span><\/h2>\n<p>Ecco cosa <a href=\"https:\/\/support.google.com\/messages\/thread\/206241765\/update-new-read-receipt-icons?hl=en\" rel=\"noreferrer noopener\" target=\"_blank\">significa ciascun segno di spunta<\/a> nei messaggi RCS:<\/p>\n<p><strong>Segno di spunta singolo:<\/strong> il messaggio \u00e8 stato inviato con successo dal tuo lato.<\/p>\n<p><strong>Due segni di spunta:<\/strong> il messaggio \u00e8 stato consegnato al destinatario.<\/p>\n<p><strong>Due segni di spunta colorati:<\/strong> il messaggio \u00e8 stato letto dal destinatario.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/google-messages-checkmark-icons-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<p>Di seguito sono riportati alcuni altri simboli che vedrai nelle chat di RCS:<\/p>\n<p><strong>Icona Galleria nel menu Reazioni:<\/strong> quando premi a lungo un messaggio nella chat di RCS, verranno visualizzati gli emoji di reazione. Qui vedrai un&#8217;icona Galleria. Questa icona ti consente di creare una fotomoji, ovvero una reazione personalizzata realizzata utilizzando una qualsiasi delle foto nella tua galleria oppure puoi anche catturare una nuova immagine.<\/p>\n<p><strong>Faccina con simbolo +<\/strong> : questa icona rappresenta un&#8217;emoji personalizzata. Tocca questa icona per selezionare qualsiasi emoji personalizzata per reagire al messaggio. Sapere cosa fare se <u>le reazioni non funzionano<\/u> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Google-messages-custom-emoji-reactions-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<h2><span id=\"Samsung-Messages-Icons-Meaning\">Significato delle icone dei messaggi Samsung<\/span><\/h2>\n<h3>Icone della schermata iniziale<\/h3>\n<p><strong>Fumetto della chat:<\/strong> il fumetto mobile nell&#8217;angolo in basso a destra ti consente di creare una nuova conversazione.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-new-chat-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<p><strong>Icona filtro:<\/strong> tocca questa icona per personalizzare se desideri vedere tutti i messaggi o solo quelli che non sono aggiunti ad alcuna categoria.<\/p>\n<p><strong>Icona di ricerca:<\/strong> questa icona ti consente di cercare nei tuoi messaggi.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-filter-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<p><strong>Segno pi\u00f9 (+):<\/strong> il segno pi\u00f9 accanto alle categorie ti consente di creare una nuova categoria per organizzare i tuoi messaggi.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-Add-category-icon-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<p><strong>Icona puntina:<\/strong> l&#8217;icona puntina accanto a una chat significa che \u00e8 fissata in alto. Per appuntare una chat, premi a lungo e tocca l&#8217;icona a tre punti seguita da Appunta in alto.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-pin-icon-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<p><strong>Icona a forma di campana con una barra<\/strong> : l&#8217;icona a forma di campana indica che il thread dei messaggi \u00e8 disattivato e, di conseguenza, non riceverai notifiche su eventuali nuovi messaggi provenienti da quella chat. Ecco cosa fare se <u>non ricevi le notifiche dei messaggi di testo.<\/u> <\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-bell-icon-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<p><strong>Freccia su:<\/strong> quando scorri leggermente verso il basso nell&#8217;elenco dei messaggi, verr\u00e0 visualizzata una freccia su nella parte inferiore centrale dell&#8217;app. Tocca questa icona per andare in cima all&#8217;elenco dei messaggi.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-go-to-top-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<h3>Icone nella schermata della chat<\/h3>\n<h4>Icone in alto<\/h4>\n<p><strong>Freccia gi\u00f9 accanto al nome del contatto:<\/strong> tocca questa icona per visualizzare altre opzioni come chiamate audio, ecc.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-call-icons-805x1024-1.webp\" title=\"\" width=\"805\"\/><\/figure>\n<p><strong>Icona telefono:<\/strong> tocca questa icona per effettuare una normale chiamata telefonica alla persona.<\/p>\n<p><strong>Icona videocamera<\/strong> : questa icona rappresenta in realt\u00e0 Google Meet e ti consente di videochiamare la persona utilizzando l&#8217;app Google Meet preinstallata.<\/p>\n<h4>Icone in basso<\/h4>\n<p><strong>Icona Galleria<\/strong> : tocca questa icona per visualizzare le foto sul tuo telefono. Tocca una foto per inviarla nel messaggio. Ecco una guida se <u>non riesci a inviare foto nei messaggi sul tuo smartphone Galaxy<\/u> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-gallery-On-off-cloud-icon-805x1024-1.webp\" title=\"\" width=\"805\"\/><\/figure>\n<p><strong>Icona nuvola (attiva o disattiva):<\/strong> quando vengono visualizzate le foto, vedrai un&#8217;icona nuvola nell&#8217;angolo in basso a destra, come mostrato nell&#8217;immagine sopra. Questa icona rappresenta la funzionalit\u00e0 di condivisione dei collegamenti. Tocca questa icona per abilitare la <u>funzione di condivisione dei collegamenti<\/u> . Ci\u00f2 che fa \u00e8 che invece di inviare l&#8217;immagine vera e propria nel messaggio, l&#8217;immagine verr\u00e0 caricata su Samsung Cloud e il suo collegamento verr\u00e0 condiviso nel messaggio. Ci\u00f2 \u00e8 utile se desideri inviare l&#8217;immagine come un normale SMS anzich\u00e9 come MMS poich\u00e9 verr\u00e0 inviato solo il collegamento in formato testo. Questo metodo aiuta anche a ridurre le dimensioni dell&#8217;immagine inviata nel messaggio.<\/p>\n<p>Ecco come verr\u00e0 visualizzato il messaggio su altri telefoni, che possono essere un telefono Android o un iPhone.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-link-sharing-463x1024-1.webp\" title=\"\" width=\"463\"\/><\/figure>\n<p><strong>Icona della fotocamera:<\/strong> tocca l&#8217;icona della fotocamera per acquisire una nuova foto o un nuovo video che desideri inviare nel messaggio.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/03\/Samsung-messages-voice-note-402x1024-1.webp\" title=\"\" width=\"402\"\/><\/figure>\n<p><strong>Segno pi\u00f9<\/strong> : tocca il segno pi\u00f9 (+) per visualizzare funzionalit\u00e0 di messaggistica aggiuntive come la pianificazione dei messaggi, la posizione, l&#8217;audio, i contatti, ecc.<\/p>\n<p><strong>Icona emoticon:<\/strong> tocca l&#8217;icona emoticon per aprire il pannello emoticon e vedere emoji, adesivi e GIF. Questo pannello verr\u00e0 visualizzato solo se Samsung Keyboard \u00e8 la tastiera predefinita sul tuo telefono, altrimenti riceverai un errore che dice di passare a Samsung Keyboard.<\/p>\n<p><strong>Onde:<\/strong> premi a lungo l&#8217;icona dell&#8217;onda per registrare un messaggio audio.<\/p>\n<h2><span id=\"Make-Messages-Automatic\">Rendi i messaggi automatici<\/span><\/h2>\n<p>Ho cercato di coprire il significato di tutte le icone e i simboli dei messaggi di testo pi\u00f9 diffusi delle app Google e Samsung Messaggi. Nel caso in cui manchi qualche simbolo, fatecelo sapere. Prima di andare, come <u>eliminare automaticamente i messaggi OTP<\/u> sui telefoni Android.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stavi mandando un messaggio a qualcuno quando all&#8217;improvviso hai visto un&#8217;icona sconosciuta nell&#8217;app di messaggistica del tuo telefono Android? Forse ti starai chiedendo cosa significano il campanello, la puntina, la stella o altre icone nell&#8217;app Messaggi. Ecco una guida dettagliata sul significato di varie icone e simboli nell&#8217;app Google Messaggi e Samsung Messaggi sui telefoni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,44,160,161,162,163],"class_list":["post-1327","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-explained","tag-google-messages","tag-icons","tag-samsung-messages","tag-symbols"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"predecessor-version":[{"id":1328,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1327\/revisions\/1328"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}