{"id":13812,"date":"2026-02-16T03:46:31","date_gmt":"2026-02-16T03:46:31","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=13812"},"modified":"2026-02-16T03:46:31","modified_gmt":"2026-02-16T03:46:31","slug":"come-risolvere-i-link-pdf-che-non-funzionano","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/come-risolvere-i-link-pdf-che-non-funzionano\/","title":{"rendered":"Come risolvere i link PDF che non funzionano"},"content":{"rendered":"<p>A volte, cliccare sui link nei PDF non funziona come dovrebbe. Magari si aprono in un&#8217;app che non li riconosce o semplicemente non fanno nulla.\u00c8 frustrante perch\u00e9 se si condivide un PDF con link cliccabili, come navigazione, citazioni o riferimenti, si desidera che siano affidabili. A quanto pare, ci sono un sacco di piccoli dettagli che possono compromettere i link dei PDF, anche se a prima vista sembrano a posto. Di solito, si tratta di un mix di problemi di formattazione dei link, impostazioni del browser o persino di come \u00e8 stato convertito il PDF. Questa guida illustrer\u00e0 alcune soluzioni pratiche, gi\u00e0 sperimentate in passato, in modo che i link tornino a funzionare senza troppi problemi.<\/p>\n<h2>Come risolvere il problema dei link PDF che non funzionano?<\/h2>\n<h3>Valuta e correggi gli URL inseriti<\/h3>\n<p>Potrebbe sembrare ovvio, ma ricontrollare gli URL \u00e8 un primo passo comune. A volte, i link non funzionano perch\u00e9 sono semplicemente sbagliati, magari a causa di un errore di battitura o perch\u00e9 manca http:\/\/ o https:\/\/ all&#8217;inizio. Puoi aprire il documento originale in cui sono stati creati i link (come un documento Word), fare clic con il pulsante destro del mouse sul link errato, selezionare <strong>Modifica collegamento ipertestuale<\/strong> e verificare l&#8217;URL. Assicurati soprattutto di includere l&#8217;indirizzo completo: alcuni browser o visualizzatori non risolvono gli URL senza http(s) davanti. Dopo l&#8217;aggiornamento, riesporta o salva nuovamente il PDF. In alcune configurazioni, questa singola modifica \u00e8 sufficiente per correggere i link interrotti. Ma attenzione: alcuni PDF hanno i link interrotti durante la conversione o se il file \u00e8 corrotto. Quindi, andiamo avanti&#8230;<\/p>\n<h3>Correggi i collegamenti di ancoraggio durante la conversione PDF<\/h3>\n<p>Hai link di ancoraggio come &#8220;#section1&#8221;? S\u00ec, sono molto utili nei PDF, ma spesso si rompono durante il processo. In pratica, durante la conversione da Word o altre fonti, il carattere &#8220;#&#8221; pu\u00f2 trasformarsi in &#8220;%23&#8221; a causa della codifica. Non so perch\u00e9 funzioni, ma se modifichi i PDF in Adobe Acrobat, puoi in un certo senso annullare manualmente questa operazione. Apri il PDF, vai su <strong>File &gt; Propriet\u00e0<\/strong>, quindi <strong>Azioni<\/strong>. Trova i link con %23 e sostituiscili di nuovo con #.Per correzioni di massa, tuttavia, dovrai avere dimestichezza con la modifica in Acrobat Pro DC, il che \u00e8 un po&#8217; fastidioso, ma ne vale la pena se i tuoi link sono cruciali.<\/p>\n<p>Un modo pi\u00f9 semplice \u00e8 durante il processo di esportazione. Quando salvi il tuo documento Word o un altro documento sorgente come PDF, scegli <strong>File &gt; Salva con nome<\/strong> &gt; seleziona PDF, quindi in <strong>Ottimizza per<\/strong>, seleziona <strong>Standard<\/strong>. Questo tende a mantenere intatti i link di ancoraggio meglio delle impostazioni predefinite. Ricorda: se i tuoi link non funzionano, correggere la codifica durante l&#8217;esportazione potrebbe aiutarti a mantenerli attivi.<\/p>\n<h3>Imposta correttamente il tuo visualizzatore PDF predefinito<\/h3>\n<p>Ecco un altro problema strano che pu\u00f2 far inciampare la gente: Windows spesso apre i PDF in <strong>Microsoft Edge<\/strong> per impostazione predefinita, il che non sempre funziona bene con i link. Se i link non funzionano, vale la pena installare un lettore PDF dedicato come <strong>Adobe Acrobat Reader<\/strong>. Una volta installato, impostalo come app predefinita: vai su <strong>Impostazioni &gt; App &gt; App predefinite<\/strong> &gt; *Scegli app predefinite per tipo di file*, quindi trova.pdf e seleziona Adobe Acrobat o il visualizzatore PDF che preferisci. Dopodich\u00e9, prova ad aprire di nuovo il PDF e a cliccare sui link. Su alcuni computer, \u00e8 necessario un riavvio o la riapertura del file affinch\u00e9 la modifica venga applicata. Questo ha funzionato su diversi computer perch\u00e9, per qualche motivo, Edge non gestisce i link in modo affidabile in alcuni PDF.<\/p>\n<h3>Carica e converti tramite Google Drive<\/h3>\n<p>Se i link continuano a non funzionare nei PDF locali, prova a caricare il file su <strong>Google Drive<\/strong>. A volte, il visualizzatore PDF di Google \u00e8 pi\u00f9 intelligente nella gestione dei link, soprattutto quando si convertono i PDF in Google Docs e di nuovo in PDF. Basta caricare il PDF (trascinandolo e rilasciandolo in Drive o utilizzando <strong>Nuovo &gt; Caricamento file<\/strong>), quindi fare clic con il pulsante destro del mouse e scegliere <strong>Apri con &gt; Google Docs<\/strong>. Quando il documento si apre in Google Docs, vai su <strong>File &gt; Scarica &gt; Microsoft Word<\/strong>. Apri il documento Word, assicurati che i link siano corretti, quindi esporta nuovamente in PDF (preferibilmente scegliendo l&#8217; opzione Dimensione <strong>standard<\/strong> per una migliore conservazione dei link).Questo metodo non \u00e8 perfetto, ma \u00e8 una buona soluzione alternativa se i link del PDF sono stati danneggiati durante la conversione iniziale o il download.<\/p>\n<h3>Crea collegamenti ipertestuali reali per una migliore compatibilit\u00e0<\/h3>\n<p>Alcuni visualizzatori PDF, soprattutto quelli meno recenti o minimali come Apple Preview o le app per dispositivi mobili, non rilevano automaticamente i link. La soluzione? Creare veri e propri collegamenti ipertestuali all&#8217;interno del documento sorgente. Ad esempio, in Word, \u00e8 possibile inserire i link normalmente e poi esportarli in PDF. Quando si apre il PDF (ad esempio in Adobe Acrobat Pro DC), utilizzare la funzione <strong>Strumenti &gt; Collegamento<\/strong> per aggiungere o modificare manualmente i link.\u00c8 disponibile un&#8217;opzione chiamata &#8221; <strong>Aggiungi\/Modifica collegamento Web o Documento&#8221;<\/strong> o <strong>&#8220;Crea automaticamente link Web da URL&#8221;<\/strong>. In questo modo, i link vengono incorporati come collegamenti ipertestuali reali e cliccabili, anzich\u00e9 come semplice testo che sembra un link. Non \u00e8 una soluzione perfetta, ma rende i link pi\u00f9 affidabili per tutti i visualizzatori.<\/p>\n<h3>Cancella la cache del browser (se i link si aprono nel browser)<\/h3>\n<p>A volte, cliccando sui link nei PDF si apre il browser web predefinito e, se la cache \u00e8 danneggiata, i link potrebbero non caricarsi o aprire pagine vuote. In Chrome, ad esempio, vai su <strong>Impostazioni &gt; Altri strumenti &gt; Cancella dati di navigazione<\/strong>. Scegli un intervallo di tempo recente, seleziona le caselle per i cookie e le immagini memorizzate nella cache, quindi fai clic su <strong>Cancella dati<\/strong>.\u00c8 un po&#8217; un tentativo azzardato, ma la cancellazione della cache ha gi\u00e0 risolto strani problemi con i link, ad esempio alcuni dati salvati in conflitto o cookie che bloccavano il caricamento della pagina. Puoi provare anche con altri browser come Firefox o Edge, giusto per essere pi\u00f9 scrupoloso.<\/p>\n<h3>Ricontrolla e correggi l&#8217;URL di pagamento<\/h3>\n<p>Avviso di piccolo problema: se l&#8217;URL non inizia con <code>http:\/\/<\/code>o <code>https:\/\/<\/code>, cliccare sul link potrebbe non sortire alcun effetto. D&#8217;altra parte, se l&#8217;URL inizia con <code>http:\/\/<\/code>, ma non funziona, prova a sostituirlo con <code>https:\/\/<\/code>. A volte, una rapida modifica al documento sorgente per correggere il formato dell&#8217;URL pu\u00f2 evitare l&#8217;intera procedura di esportazione del PDF. In sostanza, assicurati sempre che gli URL siano completamente qualificati.<\/p>\n<h3>Prova un browser diverso<\/h3>\n<p>Se i link non si aprono in un browser, cambiate le impostazioni. Ad esempio, se non funzionano in Edge o Chrome, aprite il PDF in <strong>Mozilla Firefox<\/strong> o <strong>Google Chrome<\/strong> (se non lo avete gi\u00e0 fatto).Scaricate e installate un browser come Chrome da <a href=\"https:\/\/www.google.com\/intl\/en_us\/chrome\/\" rel=\"noreferrer noopener\" target=\"_blank\">qui<\/a>, se necessario. A volte, la semplice apertura del PDF in un ambiente diverso fa la differenza. La gestione dei link da parte del browser pu\u00f2 variare, soprattutto se le impostazioni di sicurezza o di sicurezza sono restrittive. Quindi, vale la pena provare.<\/p>\n<h3>Aggiorna il tuo visualizzatore PDF<\/h3>\n<p>Le app PDF obsolete possono essere la causa, soprattutto se non vengono aggiornate da anni. Controlla la presenza di aggiornamenti in Adobe Acrobat, Foxit o nel visualizzatore che stai utilizzando. Per Adobe, consulta <a href=\"https:\/\/helpx.adobe.com\/acrobat\/kb\/install-updates-reader-acrobat.html\" rel=\"noreferrer noopener\" target=\"_blank\">la guida agli aggiornamenti<\/a>. Le versioni pi\u00f9 recenti di solito dispongono di patch di correzione per i bug nella gestione dei link. Su alcuni computer, l&#8217;aggiornamento ha risolto il problema quando nient&#8217;altro ha funzionato, quindi vale la pena provare se i tuoi link sono ostinati.<\/p>\n<p>Spero che questo vi dia qualche spunto per far funzionare di nuovo i link PDF senza dover fare i conti con un problema. Spesso, si tratta solo di una piccola modifica al modo in cui il file viene creato, salvato o visualizzato. Niente di troppo elaborato, ma sufficiente a far funzionare i link.<\/p>\n<h2>Riepilogo<\/h2>\n<ul>\n<li>Controlla attentamente i tuoi URL e assicurati che inizino con http(s)<\/li>\n<li>Se necessario, correggi i collegamenti di ancoraggio durante l&#8217;esportazione<\/li>\n<li>Imposta come predefinito un visualizzatore PDF affidabile come Adobe Acrobat<\/li>\n<li>Utilizza Google Drive per riesportare il PDF<\/li>\n<li>Creare collegamenti ipertestuali reali all&#8217;interno del documento di origine prima dell&#8217;esportazione<\/li>\n<li>Cancella la cache del browser se i link si aprono nel browser ma non vengono caricati<\/li>\n<li>Prova browser diversi o aggiorna il tuo visualizzatore PDF<\/li>\n<\/ul>\n<h2>Incartare<\/h2>\n<p>Far funzionare questi link potrebbe richiedere un po&#8217; di tentativi ed errori, ma la maggior parte dei problemi si riduce a come \u00e8 stato creato il PDF o a come viene visualizzato. Correggere i formati URL, regolare le impostazioni di esportazione o cambiare visualizzatore pu\u00f2 fare miracoli. Speriamo che questo ti aiuti a risparmiare tempo e grattacapi, e che renda i tuoi PDF effettivamente cliccabili in modo pratico. Buona fortuna e che i tuoi link rimangano attivi e felici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A volte, cliccare sui link nei PDF non funziona come dovrebbe. Magari si aprono in un&#8217;app che non li riconosce o semplicemente non fanno nulla.\u00c8 frustrante perch\u00e9 se si condivide un PDF con link cliccabili, come navigazione, citazioni o riferimenti, si desidera che siano affidabili. A quanto pare, ci sono un sacco di piccoli dettagli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13812","post","type-post","status-publish","format-standard","hentry","category-how-to"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/13812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=13812"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/13812\/revisions"}],"predecessor-version":[{"id":13813,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/13812\/revisions\/13813"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=13812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=13812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=13812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}