{"id":1451,"date":"2024-04-02T08:35:14","date_gmt":"2024-04-02T08:35:14","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1451"},"modified":"2024-04-02T08:35:14","modified_gmt":"2024-04-02T08:35:14","slug":"how-to-fix-screen-goes-black-for-a-second-on-windows-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-fix-screen-goes-black-for-a-second-on-windows-it\/","title":{"rendered":"Come risolvere il problema dello schermo che diventa nero per un secondo su Windows"},"content":{"rendered":"<p>Ammettiamolo: non c&#8217;\u00e8 niente di pi\u00f9 frustrante di un monitor che continua ad oscurarsi all&#8217;improvviso e senza motivo. Se sei un giocatore, questo pu\u00f2 rovinare completamente la tua esperienza di gioco su un PC Windows 11.<\/p>\n<p>Continuiamo a ricevere messaggi da utenti di Windows 11 che chiedono lo stesso problema, quindi abbiamo finalmente creato questo articolo contenente potenziali soluzioni.<\/p>\n<p>Di seguito, abbiamo condiviso alcuni semplici metodi per risolvere il problema Il monitor diventa nero ogni pochi secondi.<\/p>\n<h3><span id=\"Possible_Reasons_for_Monitor_Going_Black_for_a_Second\"><strong>Possibili ragioni per cui il monitor diventa nero per un secondo<\/strong><\/span><\/h3>\n<p>Non esiste un motivo specifico da individuare, ma generalmente il problema si verifica quando qualcosa interferisce con la connessione. Ecco alcuni possibili motivi per cui il monitor diventa nero per alcuni secondi.<\/p>\n<ul>\n<li>Cavi smarriti, montati male o danneggiati che collegano il monitor al PC.<\/li>\n<li>Driver grafici obsoleti o danneggiati.<\/li>\n<li>Configurazione errata delle impostazioni di alimentazione.<\/li>\n<li>Problemi di incompatibilit\u00e0 e stabilit\u00e0.<\/li>\n<li>Problemi hardware nel monitor o nel PC.<\/li>\n<\/ul>\n<h2><span id=\"How_to_Fix_Screen_Goes_Black_for_a_Second_Issue\"><strong>Come risolvere lo schermo diventa nero per un secondo problema?<\/strong><\/span><\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Correzione dello schermo che diventa nero per un secondo su Windows\" class=\"wp-image\" decoding=\"async\" height=\"576\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Fix-Screen-Goes-Black-For-a-Second-on-Windows-1-1024x576-1.webp\" title=\"Correzione dello schermo che diventa nero per un secondo su Windows\" width=\"1024\"\/><\/figure>\n<p>Poich\u00e9 non conosciamo il motivo effettivo che attiva il problema dello schermo nero su un PC Windows, dobbiamo seguire tutti i metodi di risoluzione dei problemi che riguardano il monitor, i driver grafici e i file di sistema. Ecco cosa puoi fare<\/p>\n<h3><span id=\"1_Closely_Examine_the_Cable_Connections\"><strong>1. Esaminare attentamente i collegamenti dei cavi<\/strong><\/span><\/h3>\n<p>Se il monitor continua a diventare nero ogni paio di secondi o minuti, di solito \u00e8 il risultato di collegamenti dei cavi allentati, mal montati o difettosi.<\/p>\n<p>Quindi, la prima cosa da fare \u00e8 esaminare i collegamenti dei cavi. \u00c8 necessario verificare il cavo che collega il monitor alla CPU.<\/p>\n<p>Controlla se il cavo \u00e8 danneggiato, inserito nella porta giusta, ecc. Se non sei sicuro, prova un cavo e un monitor diversi e vedi se aiuta.<\/p>\n<h3><span id=\"2_Update_your_PCs_Graphics_Driver\"><strong>2. Aggiorna il driver grafico del tuo PC<\/strong><\/span><\/h3>\n<p>I driver grafici obsoleti o incompatibili sono tra i motivi pi\u00f9 importanti per cui lo schermo diventa nero. Pertanto, ti consigliamo di aggiornare anche il driver grafico del tuo PC e vedere se aiuta. Ecco come aggiornare il driver grafico del tuo PC.<\/p>\n<p>1. Digita Gestione dispositivi nella ricerca di Windows 11. Successivamente, apri l&#8217; app <strong>Gestione dispositivi<\/strong> dall&#8217;elenco dei migliori risultati di corrispondenza.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Gestore dispositivi\" class=\"wp-image\" decoding=\"async\" height=\"507\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Device-Manager.webp\" title=\"Gestore dispositivi\" width=\"600\"\/><\/figure>\n<p>2. Quando si apre Gestione dispositivi, espandere la struttura <strong>Schede video<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Adattatori di visualizzazione\" class=\"wp-image\" decoding=\"async\" height=\"264\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Device-Manager-2.webp\" title=\"Adattatori di visualizzazione\" width=\"382\"\/><\/figure>\n<p>3. Fare clic con il pulsante destro del mouse sull&#8217;adattatore grafico corrente e selezionare <strong>Propriet\u00e0<\/strong> . Nelle Propriet\u00e0, fare clic su <strong>Aggiorna driver<\/strong> . Oppure, fai clic con il pulsante destro del mouse sul driver grafico e seleziona <strong>Aggiorna driver<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Aggiorna driver\" class=\"wp-image\" decoding=\"async\" height=\"437\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Graphics-Card.webp\" title=\"Aggiorna driver\" width=\"600\"\/><\/figure>\n<p>5. Nella sezione Come cercare i conducenti? richiesta, seleziona &#8220;Cerca automaticamente i driver&#8221;.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cerca automaticamente i conducenti\" class=\"wp-image\" decoding=\"async\" height=\"439\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Update-your-Graphics-Driver-4-1.webp\" title=\"Cerca automaticamente i conducenti\" width=\"600\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ora Windows 11 cercher\u00e0 automaticamente gli aggiornamenti dei driver grafici disponibili. Se \u00e8 disponibile un aggiornamento, verr\u00e0 scaricato e installato automaticamente.<\/p>\n<h3><span id=\"3_Roll_back_your_Graphics_Drivers\"><strong>3. Ripristina i driver grafici<\/strong><\/span><\/h3>\n<p>Se l&#8217;aggiornamento del driver non aiuta e causa ulteriori problemi, \u00e8 meglio ripristinare il driver della scheda grafica. Ecco cosa devi fare.<\/p>\n<p>1. Digita Gestione dispositivi nella ricerca di Windows 11. Successivamente, apri l&#8217; app <strong>Gestione dispositivi<\/strong> dall&#8217;elenco dei migliori risultati di corrispondenza.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Gestore dispositivi\" class=\"wp-image\" decoding=\"async\" height=\"662\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Update-the-WiFi-Adapter-Drivers-1-min-2.webp\" title=\"Gestore dispositivi\" width=\"700\"\/><\/figure>\n<p>2. Quando si apre Gestione dispositivi, espandere la struttura <strong>Schede video<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Adattatori di visualizzazione\" class=\"wp-image\" decoding=\"async\" height=\"566\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Update-the-Graphics-Drivers-2.webp\" title=\"Adattatori di visualizzazione\" width=\"774\"\/><\/figure>\n<p>3. Fare clic con il pulsante destro del mouse sull&#8217;adattatore grafico corrente e selezionare <strong>Propriet\u00e0<\/strong> .<\/p>\n<p>4. Nelle Propriet\u00e0, fare clic su Ripristina driver (se disponibile)<\/p>\n<p>5. Ora devi seguire le istruzioni visualizzate sullo schermo per completare il processo di ripristino del driver.<\/p>\n<p>Questo \u00e8 tutto! Ecco come puoi ripristinare i driver grafici sul tuo computer Windows 11.<\/p>\n<p>4. Apporta modifiche alle impostazioni di alimentazione del PC<\/p>\n<p>Puoi modificare le impostazioni del piano di risparmio energia per evitare che lo schermo diventi nero dopo alcuni secondi. Ecco cosa devi fare.<\/p>\n<p>1. Digitare Pannello di controllo nella ricerca di Windows. Successivamente, apri l&#8217;app Pannello di controllo dall&#8217;elenco dei migliori risultati di corrispondenza.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Pannello di controllo\" class=\"wp-image\" decoding=\"async\" height=\"645\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Make-Sure-that-the-WiFi-Adapter-is-Enabled-1-min-2.webp\" title=\"Pannello di controllo\" width=\"700\"\/><\/figure>\n<p>2. Quando si apre il Pannello di controllo, digitare <strong>Hardware e suoni<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Hardware e suono\" class=\"wp-image\" decoding=\"async\" height=\"368\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Enable-the-Fast-Startup-1.webp\" title=\"Hardware e suono\" width=\"640\"\/><\/figure>\n<p>3. Sul lato destro, fare clic su <strong>Opzioni risparmio energia<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Opzioni di risparmio energia\" class=\"wp-image\" decoding=\"async\" height=\"350\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Enable-the-Fast-Startup-2.webp\" title=\"Opzioni di risparmio energia\" width=\"640\"\/><\/figure>\n<p>4. Seleziona <strong>Modifica impostazioni piano<\/strong> accanto al piano di risparmio energia selezionato.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Modifica le impostazioni del piano\" class=\"wp-image\" decoding=\"async\" height=\"300\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Disable-Hibernation-Mode-via-Power-Plan-Settings-2.webp\" title=\"Modifica le impostazioni del piano\" width=\"640\"\/><\/figure>\n<p>5. Successivamente, seleziona <strong>Mai<\/strong> sia per <strong>A batteria<\/strong> che <strong>Collegato<\/strong> a Spegni lo schermo e metti il \u200b\u200bcomputer in stato di stop.<\/p>\n<p>6. Dopo aver apportato la modifica, fare clic sul pulsante Salva modifiche.<\/p>\n<p>Questo \u00e8 tutto! Ecco come puoi modificare le impostazioni del piano di risparmio energia su Windows 11 per correggere il monitor che continua a diventare nero per un secondo.<\/p>\n<h3><span id=\"5_Perform_a_Clean_Boot\"><strong>5. Eseguire un avvio parziale<\/strong><\/span><\/h3>\n<p>L&#8217;esecuzione di un avvio pulito ti aiuter\u00e0 a risolvere il problema Lo schermo diventa nero eliminando i conflitti tra app di terze parti. \u00c8 necessario eseguire un avvio pulito e verificare se il problema persiste.<\/p>\n<p>1. Premi il tasto Windows + R sulla tastiera. Questo aprir\u00e0 la finestra di dialogo ESEGUI. Nella finestra di dialogo ESEGUI, digitare <strong>msconfig<\/strong> e premere Invio.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"msconfig\" class=\"wp-image\" decoding=\"async\" height=\"317\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/How-to-Clean-Boot-Windows-11-1.webp\" title=\"msconfig\" width=\"476\"\/><\/figure>\n<p>2. Nell&#8217;utilit\u00e0 Configurazione di sistema, passare alla scheda <strong>Servizi<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Servizi\" class=\"wp-image\" decoding=\"async\" height=\"404\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/How-to-Clean-Boot-Windows-11-2.webp\" title=\"Servizi\" width=\"592\"\/><\/figure>\n<p>3. Successivamente, <strong>seleziona<\/strong> &#8220;Nascondi tutti i servizi Microsoft&#8221; e fai clic su <strong>Disabilita tutto<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Disabilitare tutto\" class=\"wp-image\" decoding=\"async\" height=\"419\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/How-to-Clean-Boot-Windows-11-4-1.webp\" title=\"Disabilitare tutto\" width=\"616\"\/><\/figure>\n<p>4. Successivamente, apri Task Manager e passa alla scheda <strong>Avvio<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Avviare\" class=\"wp-image\" decoding=\"async\" height=\"584\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/How-to-Clean-Boot-Windows-11-6.webp\" title=\"Avviare\" width=\"576\"\/><\/figure>\n<p>5. Fare clic con il tasto destro sui problemi di avvio abilitati e selezionare <strong>Disabilita<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"disattivare\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/How-to-Clean-Boot-Windows-11-7-1.webp\" title=\"disattivare\" width=\"577\"\/><\/figure>\n<p>6. Infine, fare clic su <strong>Applica<\/strong> nell&#8217;utilit\u00e0 Configurazione di sistema e chiuderla.<\/p>\n<p>Questo \u00e8 tutto! Ora riavvia il tuo computer Windows 11. Ci\u00f2 avvier\u00e0 il tuo PC in uno stato pulito senza app o servizi di terze parti. Ora controlla se lo schermo diventa ancora nero dopo un secondo o un minuto.<\/p>\n<h3><span id=\"6_Disable_the_Overclocking\"><strong>6. Disabilitare l&#8217;overclocking<\/strong><\/span><\/h3>\n<p>L&#8217;overclocking della GPU o della CPU migliora le prestazioni del sistema. I giocatori spesso overcloccano le frequenze della GPU e della CPU per migliorare le prestazioni di gioco.<\/p>\n<p>Tuttavia, l&#8217;overclocking presenta i suoi svantaggi, come blocchi del sistema, arresti anomali, problemi di riscaldamento e altro ancora.<\/p>\n<p>Il monitor del tuo PC potrebbe diventare nero all&#8217;improvviso a causa dell&#8217;overclocking. Pertanto, si consiglia di annullare qualsiasi overclock e vedere se aiuta.<\/p>\n<h3><span id=\"7_Perform_a_System_Restore\"><strong>7. Eseguire un ripristino del sistema<\/strong><\/span><\/h3>\n<p>Se ancora non riesci a risolvere il problema della schermata nera, \u00e8 meglio eseguire un ripristino del sistema. Un Ripristino configurazione di sistema riporter\u00e0 le impostazioni del dispositivo a una data precedente in cui tutto funzionava correttamente. Ecco come eseguire un ripristino del sistema su Windows.<\/p>\n<p>1. Digita Recovery nella ricerca di Windows 11. Successivamente, apri l&#8217; app <strong>Recovery<\/strong> dall&#8217;elenco dei migliori risultati di corrispondenza.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Recupero\" class=\"wp-image\" decoding=\"async\" height=\"511\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Recovery-1-1.webp\" title=\"Recupero\" width=\"600\"\/><\/figure>\n<p>2. Nella schermata Ripristino, fare clic su <strong>Apri Ripristino configurazione di sistema<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Apri Ripristino configurazione di sistema\" class=\"wp-image\" decoding=\"async\" height=\"337\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Recovery-2-1.webp\" title=\"Apri Ripristino configurazione di sistema\" width=\"700\"\/><\/figure>\n<p>3. Nella schermata successiva, seleziona <strong>Scegli un punto di ripristino diverso<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Scegli un punto di ripristino diverso\" class=\"wp-image\" decoding=\"async\" height=\"410\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Recovery-app-1-1.webp\" title=\"Scegli un punto di ripristino diverso\" width=\"500\"\/><\/figure>\n<p>4. Selezionare un <strong>punto di ripristino<\/strong> creato in una data in cui il PC funziona correttamente e fare clic su <strong>Avanti<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Prossimo\" class=\"wp-image\" decoding=\"async\" height=\"412\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Recovery-app-2-1.webp\" title=\"Prossimo\" width=\"500\"\/><\/figure>\n<p>5. Nella richiesta di conferma, fare clic su <strong>Fine<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Fine\" class=\"wp-image\" decoding=\"async\" height=\"411\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Recovery-app-3-1.webp\" title=\"Fine\" width=\"500\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ecco come eseguire un ripristino del sistema sul tuo PC. Dopo il ripristino del sistema, controlla se il monitor diventa ancora nero.<\/p>\n<h3><span id=\"8_Rule_out_the_SMPS_Issues\"><strong>8. Escludere i problemi SMPS<\/strong><\/span><\/h3>\n<p>I problemi SMPS o PSU sono spesso noti per innescare tali problemi. Se sospetti che il tuo alimentatore faccia rumore o abbia molta polvere, puoi farlo controllare da un tecnico.<\/p>\n<p>Un problema SMPS pu\u00f2 non riuscire a fornire alimentazione alla scheda grafica o anche al monitor, causando ritardi frequenti o lo schermo diventa nero per un secondo.<\/p>\n<p>Se nulla ha funzionato a tuo favore, devi escludere problemi hardware. Presta particolare attenzione alla GPU, all&#8217;SMPS e, ovviamente, al monitor.<\/p>\n<p>Quindi, questi sono alcuni dei metodi migliori per risolvere lo schermo continua a diventare nero per un secondo. Spero che i metodi che abbiamo condiviso ti abbiano aiutato a risolvere il problema. Se il problema persiste, ti consigliamo di contattare il team di supporto di Microsoft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ammettiamolo: non c&#8217;\u00e8 niente di pi\u00f9 frustrante di un monitor che continua ad oscurarsi all&#8217;improvviso e senza motivo. Se sei un giocatore, questo pu\u00f2 rovinare completamente la tua esperienza di gioco su un PC Windows 11. Continuiamo a ricevere messaggi da utenti di Windows 11 che chiedono lo stesso problema, quindi abbiamo finalmente creato questo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-1451","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1451"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1451\/revisions"}],"predecessor-version":[{"id":1452,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1451\/revisions\/1452"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}