{"id":1543,"date":"2024-04-09T11:44:27","date_gmt":"2024-04-09T11:44:27","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1543"},"modified":"2024-04-09T11:44:27","modified_gmt":"2024-04-09T11:44:27","slug":"how-to-get-imessage-on-android-and-windows-using-airmessage-server-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-get-imessage-on-android-and-windows-using-airmessage-server-it\/","title":{"rendered":"Come ottenere iMessage su Android e Windows utilizzando AirMessage Server"},"content":{"rendered":"<p>iMessage \u00e8 sempre stato un servizio esclusivo per gli utenti che possiedono prodotti Apple. Sebbene ci siano molti servizi di messaggistica istantanea che rivaleggiano con iMessage, nessuno di loro \u00e8 riuscito a detronizzarlo dal pi\u00f9 esclusivo.<\/p>\n<p>Fortunatamente, non \u00e8 necessario abbonarsi all&#8217;intero farsa dell&#8217;ecosistema Apple solo per provare iMessage o essere in costante contatto con il proprio amico che usa un iPhone. &#8220;AirMessage&#8221; \u00e8 un ottimo software che ti consentir\u00e0 di provare iMessage su qualsiasi dispositivo abilitato a Internet.<\/p>\n<p>Detto questo, l&#8217;unico avvertimento di AirMessage \u00e8 che richiede un MacBook per funzionare e deve essere acceso e connesso a Internet per poter inviare e ricevere iMessage poich\u00e9 funziona come un server privato.<\/p>\n<p>Se hai seguito la FOMO su iMessage o desideri sorprendere il tuo amico proprietario di iPhone con un iMessage inaspettato, AirMessage \u00e8 adatto a te. Quindi, senza ulteriori indugi, cominciamo.<\/p>\n<h2 id=\"h-setup-airmessage-server-on-your-macbook\">Configura AirMessage Server sul tuo MacBook<\/h2>\n<p>Prima di poter utilizzare il tuo dispositivo Android per inviare e ricevere iMessage, dovrai installare un server AirMessage sul tuo MacBook che possa facilitare la funzionalit\u00e0.<\/p>\n<p>Per fare ci\u00f2, vai su airmessage.org utilizzando il tuo browser preferito. Quindi, scorri verso il basso fino alla fine della pagina e fai clic sul riquadro &#8220;AirMessage Server per macOS&#8221; per scaricare il server AirMessage per MacBook Intel.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Se possiedi un MacBook M1, fai clic sull&#8217;opzione &#8220;Disponibile anche per Mac in silicone&#8221; e il download dovrebbe iniziare immediatamente.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Una volta scaricato, fare doppio clic sul file. zip per estrarre l&#8217;app.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Dopo l&#8217;estrazione, copia il <code>.app<\/code>file scaricato e incollalo nella cartella &#8220;Applicazioni&#8221; sul tuo MacBook utilizzando rispettivamente le scorciatoie da tastiera <kbd>Command<\/kbd>+ <kbd>C<\/kbd>e poi <kbd>Command<\/kbd>+ <kbd>V<\/kbd>.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Per continuare, dovrai fornire l&#8217;accesso completo al disco &#8220;AirMessage&#8221; per inoltrare iMessage al tuo dispositivo.<\/p>\n<p>Per fare ci\u00f2, vai all&#8217;app &#8220;Preferenze di Sistema&#8221; dal dock o dal launchpad del tuo dispositivo.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Successivamente, fai clic sul riquadro &#8220;Sicurezza e privacy&#8221; presente nella finestra Preferenze di Sistema.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora fai clic sulla scheda &#8220;Privacy&#8221; per continuare.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Quindi, dalla barra laterale sinistra, scorri verso il basso per individuare e fare clic sull&#8217;opzione &#8220;Accesso completo al disco&#8221;. Successivamente, fai clic sull&#8217;icona &#8220;Blocco&#8221; presente nell&#8217;angolo in basso a destra della finestra &#8220;Sicurezza e privacy&#8221; e autenticati utilizzando il metodo di autenticazione preferito.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Una volta autenticato, clicca sull&#8217;icona &#8216;+&#8217; presente nella finestra. Questo aprir\u00e0 una finestra separata sullo schermo.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora individua e fai doppio clic sull&#8217;opzione &#8220;AirMessage&#8221; dall&#8217;elenco per concedere all&#8217;app l&#8217;accesso completo al disco del tuo dispositivo macOS.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Poich\u00e9 il tuo MacBook funzioner\u00e0 essenzialmente come server, deve essere sempre attivo per inviare e ricevere messaggi sui tuoi dispositivi non Apple. Per raggiungere questo obiettivo, dovrai modificare le impostazioni di sospensione del tuo dispositivo macOS.<\/p>\n<p>Dalla pagina &#8220;Sicurezza e Privacy&#8221; delle Preferenze di Sistema, fai clic sull&#8217;icona &#8220;Griglia&#8221; per tornare alla home page delle Preferenze di Sistema.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora, fai clic sull&#8217;icona &#8220;Risparmio energetico&#8221; dalla griglia delle opzioni per continuare.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Successivamente, fai clic sull&#8217;opzione &#8220;Adattatore di alimentazione&#8221; per continuare.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Successivamente, fai clic sulla casella di controllo che precede l&#8217;opzione &#8220;impedisci al computer di andare in stop automaticamente quando lo schermo \u00e8 spento&#8221;.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora vai al launchpad e avvia l&#8217;app &#8220;AirMessage&#8221;.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Successivamente, dalla finestra aperta separatamente, fai clic sul pulsante &#8220;Connetti un account&#8221; per procedere. Questo aprir\u00e0 una finestra separata sullo schermo.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora fai clic sul pulsante &#8220;Accedi con Google&#8221; per connettere il tuo account Google con AirMessage.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Una volta connesso, riceverai un messaggio che indica lo stesso sullo schermo.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>E questo \u00e8 tutto: hai installato il server sul tuo dispositivo macOS. \u00c8 giunto il momento di preparare il tuo dispositivo Android o Windows che desideri utilizzare per inviare\/ricevere iMessage.<\/p>\n<h2 id=\"h-download-install-airmessage-app-on-your-android-device\">Scarica e installa l&#8217;app AirMessage sul tuo dispositivo Android<\/h2>\n<p>Una volta che il server AirMessage \u00e8 attivo e funzionante, ora devi scaricare l&#8217;app Android dal PlayStore e iniziare a utilizzare il servizio per inviare e ricevere iMessage dal tuo dispositivo Android.<\/p>\n<p>Per fare ci\u00f2, apri innanzitutto l&#8217;app PlayStore dalla schermata principale o dalla libreria delle app del tuo dispositivo Android.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Successivamente, tocca la &#8220;Barra di ricerca&#8221; presente nella sezione pi\u00f9 in alto dello schermo e digita <kbd>Air Message<\/kbd>. Quindi, fai clic sul pulsante &#8220;Cerca&#8221; nell&#8217;angolo in basso a destra della tastiera su schermo per eseguire la ricerca.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora, dai risultati della ricerca, fai clic sul pulsante &#8220;Installa&#8221; per scaricare e installare l&#8217;app AirMessage sul tuo dispositivo Android.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Una volta installata, apri l&#8217;app dal collegamento della schermata iniziale o dal cassetto delle app del tuo dispositivo Android.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Successivamente, tocca l&#8217;opzione &#8220;Accedi con Google&#8221; e accedi utilizzando lo stesso account Google con cui hai effettuato l&#8217;accesso sull&#8217;app server AirMessage sul tuo dispositivo macOS.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora sarai in grado di vedere tutta la cronologia dei tuoi messaggi. Ora puoi inviare o ricevere iMessage sul tuo dispositivo Android purch\u00e9 il tuo dispositivo macOS sia attivo e connesso a Internet.<\/p>\n<h2 id=\"h-use-airmessage-web-app-to-send-receive-imessages-on-your-windows-device\">Utilizza l&#8217;app Web AirMessage per inviare\/ricevere iMessage sul tuo dispositivo Windows<\/h2>\n<p>Usare l&#8217;app AirMessage sul tuo dispositivo Windows \u00e8 piuttosto semplice e diretto. Inoltre, AirMessage fornisce un&#8217;interfaccia web, quindi non \u00e8 nemmeno necessario scaricare un&#8217;app e puoi semplicemente accedere utilizzando uno qualsiasi dei tuoi browser preferiti.<\/p>\n<p>Per fare ci\u00f2, apri uno dei tuoi browser preferiti sul tuo computer Windows. Quindi, vai su web.airmessage.org. Una volta caricato il sito, fai clic sul pulsante &#8220;Accedi con Google&#8221;.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ora accedi con lo stesso account utilizzato per accedere all&#8217;app del server AirMessage sul tuo dispositivo macOS. Una volta effettuato l&#8217;accesso, dovresti essere in grado di vedere tutta la cronologia dei messaggi insieme alla possibilit\u00e0 di inviare\/ricevere iMessage sul tuo dispositivo Windows.<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<p>Ecco gente, ora puoi utilizzare i tuoi dispositivi Android e\/o Windows per inviare\/ricevere iMessage utilizzando questa guida in un modo super conveniente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>iMessage \u00e8 sempre stato un servizio esclusivo per gli utenti che possiedono prodotti Apple. Sebbene ci siano molti servizi di messaggistica istantanea che rivaleggiano con iMessage, nessuno di loro \u00e8 riuscito a detronizzarlo dal pi\u00f9 esclusivo. Fortunatamente, non \u00e8 necessario abbonarsi all&#8217;intero farsa dell&#8217;ecosistema Apple solo per provare iMessage o essere in costante contatto con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,166],"class_list":["post-1543","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-imessage"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1543"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1543\/revisions"}],"predecessor-version":[{"id":1544,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1543\/revisions\/1544"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}