{"id":1591,"date":"2024-04-09T12:45:21","date_gmt":"2024-04-09T12:45:21","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1591"},"modified":"2024-04-09T12:45:21","modified_gmt":"2024-04-09T12:45:21","slug":"how-to-fix-windows-metadata-and-internet-services-issue-with-errors-0x80070490-and-0x80072efe-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-fix-windows-metadata-and-internet-services-issue-with-errors-0x80070490-and-0x80072efe-it\/","title":{"rendered":"Come risolvere il problema dei metadati di Windows e dei servizi Internet con errori 0x80070490 e 0x80072EFE"},"content":{"rendered":"<p>Ci sono diversi motivi per cui Microsoft Windows \u00e8 uno dei sistemi operativi pi\u00f9 popolari al mondo. \u00c8 facile da usare, \u00e8 compatibile con diversi hardware e ha un numero enorme di applicazioni software disponibili.<\/p>\n<p>Tuttavia, poich\u00e9 il sistema operativo \u00e8 progettato per funzionare su un&#8217;ampia variet\u00e0 di macchine di diversi produttori, a volte pu\u00f2 riscontrare problemi. Un problema comune riguarda i metadati di Windows e i servizi Internet. Quando si verificano, vengono visualizzati i seguenti codici di errore: 0x80070490 e 0x80072EFE nel Visualizzatore eventi di Windows.<\/p>\n<p>A seconda del sistema, questi errori possono causare il malfunzionamento dei driver audio e video o causare problemi di blocco e arresto anomalo. Se ti sei imbattuto in questi errori e vuoi sapere come risolverli, abbiamo messo insieme questa guida per aiutarti.<\/p>\n<h2 id=\"1-update-windows\">1. Aggiorna Windows<\/h2>\n<p>Gli errori 0x80070490 e 0x80072EFE a volte possono verificarsi a causa di un aggiornamento Windows difettoso. In tal caso, Microsoft potrebbe aver rilasciato aggiornamenti aggiuntivi per risolvere il problema che puoi installare sul tuo computer.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;Windows Update&#8221; a sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"466\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/18-1.webp\" title=\"\" width=\"829\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante &#8220;Verifica aggiornamenti&#8221; nella pagina di Windows Update. Se sono disponibili aggiornamenti, Windows li scaricher\u00e0 e li installer\u00e0. Potrebbe essere necessario riavviare il PC per completare l&#8217;aggiornamento.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"429\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/19-2-1-1.webp\" title=\"\" width=\"762\"\/><\/figure>\n<h2 id=\"2-troubleshoot-windows-updates\">2. Risolvere i problemi relativi agli aggiornamenti di Windows<\/h2>\n<p>Se ricevi il codice di errore 0x80070490, pu\u00f2 indicare un problema con Window Update. In una situazione del genere, \u00e8 necessario eseguire lo strumento di risoluzione dei problemi di Windows Update.<\/p>\n<ul>\n<li>Vai all&#8217;app Impostazioni sul tuo PC Windows 11 e digita <code>troubleshoot<\/code>nella casella di ricerca sul lato sinistro.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"524\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/w0-1.webp\" title=\"\" width=\"932\"\/><\/figure>\n<ul>\n<li>Fare clic sull&#8217;opzione &#8220;Impostazioni risoluzione problemi&#8221; per accedere alle impostazioni di risoluzione dei problemi.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"524\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/w0-2-1.webp\" title=\"\" width=\"932\"\/><\/figure>\n<ul>\n<li>Nella pagina che si apre troverai alcune opzioni. Fare clic su &#8220;Altri strumenti per la risoluzione dei problemi&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"494\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/w1-1.webp\" title=\"\" width=\"879\"\/><\/figure>\n<ul>\n<li>Puoi risolvere diversi problemi, ad esempio audio, rete, stampante e aggiornamento di Windows. Fare clic sul pulsante &#8220;Esegui&#8221; a destra dell&#8217;opzione Windows Update.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"561\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/w2-1.webp\" title=\"\" width=\"997\"\/><\/figure>\n<ul>\n<li>Quando fai clic sul pulsante &#8220;Esegui&#8221;, lo strumento di risoluzione dei problemi verificher\u00e0 la presenza di problemi e tenter\u00e0 di risolverli.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/w3-1.webp\" title=\"\" width=\"889\"\/><\/figure>\n<ul>\n<li>Una volta che lo strumento di risoluzione dei problemi avr\u00e0 completato le sue operazioni, ti mostrer\u00e0 un messaggio. Fai clic sul pulsante &#8220;Chiudi&#8221; e, si spera, il problema sar\u00e0 stato risolto.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"470\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/w4-1-1.webp\" title=\"\" width=\"836\"\/><\/figure>\n<h2 id=\"3-perform-a-clean-boot\">3. Eseguire un avvio parziale<\/h2>\n<p>A volte l&#8217;errore 0x80070490 pu\u00f2 essere causato da un&#8217;applicazione di terze parti e potresti visualizzare messaggi di errore come &#8220;Staging metadati non riuscito&#8221; quando si verifica. Per risolverlo, puoi provare a eseguire un avvio pulito che disabilita tutti i servizi tranne quelli di Microsoft.<\/p>\n<ul>\n<li>Apri il menu Start, digita <code>msconfig<\/code>e fai clic sull&#8217;opzione &#8220;Configurazione di sistema&#8221; nei risultati visualizzati.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"560\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/e2-1.webp\" title=\"\" width=\"996\"\/><\/figure>\n<ul>\n<li>Nell&#8217;utilit\u00e0 Configurazione di sistema, fai clic sulla scheda &#8220;Servizi&#8221; in alto.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"525\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/00-1.webp\" title=\"\" width=\"933\"\/><\/figure>\n<ul>\n<li>Nella scheda &#8220;Servizi&#8221; vedrai tutti i servizi attivi sul tuo PC. Fare clic sulla casella di controllo &#8220;Nascondi tutti i servizi Microsoft&#8221; per visualizzare solo i servizi di terze parti.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/01-1.webp\" title=\"\" width=\"888\"\/><\/figure>\n<ul>\n<li>Ora fai clic sul pulsante &#8220;Disabilita tutto&#8221; a destra per disabilitare tutti i servizi di terze parti, quindi fai clic sul pulsante &#8220;Applica&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"524\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/e5-2-1-1.webp\" title=\"\" width=\"931\"\/><\/figure>\n<ul>\n<li>Vai alla scheda &#8220;Avvio&#8221; in alto e fai clic sull&#8217;opzione &#8220;Apri Task Manager&#8221; ora.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"490\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/e6-1.webp\" title=\"\" width=\"871\"\/><\/figure>\n<ul>\n<li>Quando si apre Task Manager, vai alla scheda &#8220;App di avvio&#8221; per visualizzare le applicazioni che si avviano all&#8217;avvio del sistema.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"535\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/02-1.webp\" title=\"\" width=\"951\"\/><\/figure>\n<ul>\n<li>Ora dovrai disabilitare ciascun elemento abilitato da questo elenco facendo clic con il pulsante destro del mouse su di esso e facendo clic sull&#8217;opzione &#8220;Disabilita&#8221;. Prendi nota degli elementi che stai disabilitando.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"572\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/03-1.webp\" title=\"\" width=\"1017\"\/><\/figure>\n<ul>\n<li>Chiudere il Task Manager dopo aver disabilitato i servizi, quindi fare clic sul pulsante &#8220;OK&#8221; nell&#8217;utilit\u00e0 Configurazione di sistema.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"490\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/e6-2-1.webp\" title=\"\" width=\"871\"\/><\/figure>\n<ul>\n<li>Riavvia il computer dopo aver eseguito tutti questi passaggi e si avvier\u00e0 in un ambiente pulito. Avvia nuovamente Task Manager, come spiegato sopra, e prova ad abilitare i servizi che hai disabilitato in precedenza dalla scheda &#8220;App di avvio&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"584\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/04-1.webp\" title=\"\" width=\"1038\"\/><\/figure>\n<h2 id=\"4-disable-metadata-staging\">4. Disabilitare la gestione temporanea dei metadati<\/h2>\n<p>Errori nel registro possono anche causare errori 0x80070490 e 0x80072EFE. Disabilitare lo staging dei metadati \u00e8 un&#8217;altra possibile soluzione che potrebbe aiutare in una situazione del genere.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;Sistema&#8221; sul lato sinistro.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"467\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/05-1.webp\" title=\"\" width=\"831\"\/><\/figure>\n<ul>\n<li>Nella pagina &#8220;Sistema&#8221;, scorri fino in fondo e fai clic sull&#8217;opzione &#8220;Informazioni&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"461\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/06-1.webp\" title=\"\" width=\"820\"\/><\/figure>\n<ul>\n<li>Successivamente, fai clic sull&#8217;opzione &#8220;Impostazioni di sistema avanzate&#8221; per accedere alle propriet\u00e0 del sistema.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"473\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/07-1-1.webp\" title=\"\" width=\"840\"\/><\/figure>\n<ul>\n<li>Quando viene visualizzata la finestra &#8220;Propriet\u00e0 del sistema&#8221;, fare clic sulla scheda &#8220;Hardware&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"465\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/08-1.webp\" title=\"\" width=\"826\"\/><\/figure>\n<ul>\n<li>Fare clic su &#8220;Impostazioni installazione dispositivo&#8221; nella scheda &#8220;Hardware&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"483\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/09-1.webp\" title=\"\" width=\"858\"\/><\/figure>\n<ul>\n<li>Il popup visualizzato ti consentir\u00e0 di controllare se desideri che Windows cerchi e installi automaticamente le applicazioni dei produttori. Sar\u00e0 abilitato per impostazione predefinita. Fare clic sul pulsante &#8220;No&#8221; per disabilitarlo. Tieni presente che ci\u00f2 pu\u00f2 causare un funzionamento anomalo della macchina.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"513\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/10-1.webp\" title=\"\" width=\"912\"\/><\/figure>\n<ul>\n<li>Riavvia il dispositivo per verificare se il problema \u00e8 ancora presente.<\/li>\n<\/ul>\n<h2 id=\"5-edit-the-registry\">5. Modifica il registro<\/h2>\n<p>Una soluzione temporanea al problema \u00e8 modificare il registro, cosa che puoi fare tramite l&#8217;editor del registro.<\/p>\n<ul>\n<li>Apri il menu Start, digita <code>regedit<\/code>e seleziona l&#8217;opzione &#8220;Editor del Registro di sistema&#8221; dai risultati.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"538\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/11-1.webp\" title=\"\" width=\"956\"\/><\/figure>\n<ul>\n<li>Quando l&#8217;editor si apre, digita o incolla <code>HKEY_LOCAL_MACHINE\\SOFTWARE\\Microsoft\\Windows\\CurrentVersion\\WINEVT\\Channels\\Microsoft-Windows-DeviceSetupManager\/Admin<\/code>nella barra degli indirizzi in alto e premi il tasto &#8220;Invio&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"527\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/12-1.webp\" title=\"\" width=\"937\"\/><\/figure>\n<ul>\n<li>In questa chiave di registro, cerca la voce di registro &#8220;Abilitato&#8221;. Quando lo trovi, fai doppio clic su di esso per modificarne il valore.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"439\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/13-2-1.webp\" title=\"\" width=\"780\"\/><\/figure>\n<ul>\n<li>Inserisci il valore &#8220;00000000&#8221; dove dice &#8220;Valore&#8221; nella casella pop-up che appare quando fai doppio clic sulla voce e quindi fai clic sul pulsante &#8220;OK&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/14-1.webp\" title=\"\" width=\"888\"\/><\/figure>\n<ul>\n<li>Ora vai di nuovo alla barra degli indirizzi e incolla questo indirizzo <code>HKEY_LOCAL_MACHINE\\SOFTWARE\\Microsoft\\Windows\\CurrentVersion\\Device Metadata<\/code>prima di premere il tasto &#8220;Invio&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"455\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/15-2-1.webp\" title=\"\" width=\"808\"\/><\/figure>\n<ul>\n<li>Sul lato destro, cerca la voce &#8220;PreventDeviceMetadataFromNetwork&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"462\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/16-1.webp\" title=\"\" width=\"822\"\/><\/figure>\n<ul>\n<li>Fare doppio clic su di esso e modificarne il valore in &#8220;00000001&#8221; prima di fare clic sul pulsante &#8220;OK&#8221; e chiudere l&#8217;editor del registro.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"452\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/17-1.webp\" title=\"\" width=\"803\"\/><\/figure>\n<ul>\n<li>Riavvia il PC per applicare le modifiche e scoprire se hanno avuto qualche effetto nel prevenire gli errori.<\/li>\n<\/ul>\n<h2 id=\"6-perform-sfc-and-dism-scans\">6. Eseguire scansioni SFC e DISM<\/h2>\n<p>Windows \u00e8 dotato di un&#8217;utilit\u00e0 di controllo file integrata in grado di eseguire la scansione del computer e identificare i problemi che ne causano il malfunzionamento. Puoi usarlo tramite il prompt dei comandi.<\/p>\n<ul>\n<li>Apri il menu Start e digita <code>cmd<\/code>o <code>command prompt<\/code>e fai clic sull&#8217;opzione &#8220;Esegui come amministratore&#8221; per aprirlo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"507\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/20-2-1.webp\" title=\"\" width=\"901\"\/><\/figure>\n<ul>\n<li>Digita <code>sfc \/scannow<\/code>e premi il tasto &#8220;Invio&#8221; nella finestra del prompt dei comandi per avviare la scansione del tuo file system.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"585\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/21-1.webp\" title=\"\" width=\"1040\"\/><\/figure>\n<ul>\n<li>Ci vorr\u00e0 del tempo prima che il controllo file esegua la scansione dell&#8217;intero sistema. Se rileva problemi, prover\u00e0 a risolverli. Attendi fino al completamento della scansione al 100%, quindi passa alla scansione DISM.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"426\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/22-2-1.webp\" title=\"\" width=\"757\"\/><\/figure>\n<ul>\n<li>Per avviare la scansione DISM, digitare <code>DISM.exe \/Online \/Cleanup-image \/Scanhealth<\/code>nella finestra del prompt dei comandi e premere il tasto &#8220;Invio&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"479\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/23-1.webp\" title=\"\" width=\"851\"\/><\/figure>\n<ul>\n<li>Attendi il completamento della scansione, quindi digita <code> DISM.exe \/Online \/Cleanup-image \/Restorehealth<\/code>nella finestra prima di premere il tasto &#8220;Invio&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"550\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/24-1.webp\" title=\"\" width=\"978\"\/><\/figure>\n<ul>\n<li>Una volta completata la scansione, chiudi la finestra e riavvia il computer per vedere se il problema \u00e8 stato risolto.<\/li>\n<\/ul>\n<h2 id=\"7-check-your-pcs-firewall\">7. Controlla il firewall del tuo PC<\/h2>\n<p>Se il firewall non funziona correttamente o \u00e8 disabilitato, possono verificarsi errori 0x80070490 e 0x80072EFE. Per prevenirli, controlla il tuo firewall e abilitalo se necessario.<\/p>\n<ul>\n<li>Apri il menu Start e digita <code>services<\/code>prima di fare clic sull&#8217;opzione &#8220;Esegui come amministratore&#8221; sulla destra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"482\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/25-1.webp\" title=\"\" width=\"857\"\/><\/figure>\n<ul>\n<li>Cerca &#8220;Windows Defender Firewall&#8221; nei servizi e assicurati che lo stato sia &#8220;In esecuzione&#8221; e che il tipo di avvio sia &#8220;Automatico&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"458\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/26-2-1.webp\" title=\"\" width=\"815\"\/><\/figure>\n<ul>\n<li>In caso contrario, fai doppio clic su di esso e modifica il tipo di avvio in &#8220;Automatico&#8221; e lo stato in &#8220;In esecuzione&#8221;. Quindi fare clic sul pulsante &#8220;OK&#8221; e chiudere l&#8217;utilit\u00e0.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"466\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/27-1-1.webp\" title=\"\" width=\"828\"\/><\/figure>\n<h2 id=\"8-reset-your-pc\">8. Ripristina il tuo PC<\/h2>\n<p>Il ripristino del computer ti consente di ripristinarlo in modo che appaia come se avessi eseguito una nuova installazione di Windows. Tuttavia, tutti i tuoi file personali non sono interessati, il che significa che questo pu\u00f2 essere un metodo utile per eliminare errori come 0x80070490 e 0x80072EFE.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;Sistema&#8221; sul lato sinistro.<\/li>\n<li>Nella pagina &#8220;Sistema&#8221;, scorri verso il basso fino all&#8217;opzione &#8220;Ripristino&#8221; e fai clic su di essa.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"447\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/28-1.webp\" title=\"\" width=\"794\"\/><\/figure>\n<ul>\n<li>Troverai l&#8217;opzione per ripristinare il tuo PC in questa pagina. Fare clic sul pulsante &#8220;Ripristina PC&#8221; a destra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"569\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/29-1.webp\" title=\"\" width=\"1012\"\/><\/figure>\n<ul>\n<li>Verr\u00e0 visualizzata la finestra &#8220;Ripristina PC&#8221;, che ha due opzioni. Puoi scegliere di conservare i tuoi file o rimuovere tutto. Ti consigliamo di optare per la seconda opzione.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"516\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/30-1.webp\" title=\"\" width=\"918\"\/><\/figure>\n<ul>\n<li>Nella pagina successiva potrai scegliere se reinstallare Windows dal cloud o localmente. Fare clic sull&#8217;opzione &#8220;Reinstallazione locale&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"523\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/31-1.webp\" title=\"\" width=\"930\"\/><\/figure>\n<ul>\n<li>Puoi rivedere le impostazioni scelte nella pagina successiva. Se sei soddisfatto, fai clic sul pulsante &#8220;Avanti&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"509\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/32-1.webp\" title=\"\" width=\"905\"\/><\/figure>\n<ul>\n<li>Infine, fai clic sul pulsante &#8220;Ripristina&#8221;. In questo modo, Windows si riavvier\u00e0 e inizier\u00e0 il processo di ripristino, che pu\u00f2 richiedere del tempo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"474\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/33-1.webp\" title=\"\" width=\"843\"\/><\/figure>\n<h2 id=\"9-disable-the-device-setup-manager-service\">9. Disabilitare il servizio Gestione configurazione dispositivo<\/h2>\n<p>Per garantire che vari dispositivi siano installati e configurati correttamente, Windows viene fornito con un servizio di gestione della configurazione dei dispositivi. A volte, questo servizio pu\u00f2 causare problemi e portare a errori 0x80070490 e 0x80072EFE. Puoi disabilitare il servizio per verificare se questo risolve il problema.<\/p>\n<ul>\n<li>Aprire il menu Start, digitare <code>services<\/code>e fare clic sull&#8217;utilit\u00e0 per aprirla.<\/li>\n<li>Cerca &#8220;Gestione configurazione dispositivo&#8221; nell&#8217;elenco dei servizi e fai doppio clic su di esso.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"443\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/34-1.webp\" title=\"\" width=\"787\"\/><\/figure>\n<ul>\n<li>Per impostazione predefinita, il Tipo di avvio \u00e8 Manuale e il servizio \u00e8 abilitato. \u00c8 necessario modificare il tipo di avvio in &#8220;Disabilitato&#8221; e interrompere il servizio facendo clic sul pulsante &#8220;Stop&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"502\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/35-1.webp\" title=\"\" width=\"893\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante &#8220;OK&#8221; e chiudere l&#8217;utilit\u00e0 Servizi. Ora non dovresti pi\u00f9 ricevere gli errori 0x80070490 e 0x80072EFE.<\/li>\n<\/ul>\n<h2 id=\"10-update-or-reinstall-your-graphics-card-driver\">10. Aggiorna o reinstalla il driver della scheda grafica<\/h2>\n<p>I problemi di blocco e arresto anomalo relativi agli errori 0x80070490 e 0x80072EFE possono talvolta essere causati da problemi con il driver della scheda grafica. La soluzione migliore in questi casi \u00e8 aggiornare il driver o reinstallarlo se non sono disponibili aggiornamenti.<\/p>\n<h3 id=\"update-your-gpu-driver\">Aggiorna il tuo driver GPU<\/h3>\n<ul>\n<li>Fare clic sull&#8217;icona &#8216;^&#8217; sulla barra delle applicazioni per visualizzare le icone nascoste. Che tu stia utilizzando driver Intel, AMD o Nvidia, puoi accedervi da qui.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"439\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/36-1.webp\" title=\"\" width=\"781\"\/><\/figure>\n<ul>\n<li>Il tuo driver GPU sar\u00e0 visibile qui. Facendo clic con il tasto destro su di esso ti verranno fornite alcune opzioni.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"413\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/37-2-1.webp\" title=\"\" width=\"735\"\/><\/figure>\n<ul>\n<li>Seleziona l&#8217;opzione per aprirlo. L&#8217;opzione esatta potrebbe essere formulata in modo diverso a seconda del produttore della GPU, ma ti consentir\u00e0 di accedere alle impostazioni del driver.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"424\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/38-1.webp\" title=\"\" width=\"754\"\/><\/figure>\n<ul>\n<li>Quando i controlli del driver grafico si aprono, cerca un&#8217;opzione per verificare la presenza di aggiornamenti. Nel caso dei driver AMD, appare nella scheda Home nella sezione &#8220;Driver e software&#8221; a destra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"519\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/39-1.webp\" title=\"\" width=\"923\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante &#8220;Verifica aggiornamenti&#8221; e il software cercher\u00e0 le versioni pi\u00f9 recenti dei driver. Se \u00e8 disponibile un aggiornamento, fare clic sul pulsante &#8220;Download&#8221; per scaricarlo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"519\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/39-2-1.webp\" title=\"\" width=\"923\"\/><\/figure>\n<ul>\n<li>Una volta scaricato, fare clic sul pulsante &#8220;Installa&#8221; per avviare l&#8217;installazione del nuovo driver.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"511\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/40-1.webp\" title=\"\" width=\"908\"\/><\/figure>\n<ul>\n<li>Una volta completata l&#8217;installazione, fare clic sul pulsante &#8220;Fine&#8221; e riavviare il computer.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"592\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/42-1.webp\" title=\"\" width=\"1053\"\/><\/figure>\n<h3 id=\"reinstall-the-driver\">Reinstallare il driver<\/h3>\n<p>Se l&#8217;aggiornamento del driver grafico non funziona, prova a rimuovere il driver esistente e a reinstallare quello pi\u00f9 recente.<\/p>\n<ul>\n<li>Apri il Pannello di controllo del tuo PC e fai clic sull&#8217;opzione &#8220;Programmi e funzionalit\u00e0&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"464\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/43-1.webp\" title=\"\" width=\"825\"\/><\/figure>\n<ul>\n<li>Cerca i tuoi driver grafici nell&#8217;elenco dei programmi e fai clic su di essi per selezionarli.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"464\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/44-1.webp\" title=\"\" width=\"824\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante &#8220;Disinstalla\/Cambia&#8221; in alto per rimuovere il driver. Una volta rimosso il driver, riavvia il computer prima di avviare una nuova installazione.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"506\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/45-1.webp\" title=\"\" width=\"900\"\/><\/figure>\n<ul>\n<li>Per reinstallare il driver grafico, visitare il sito Web del produttore del driver grafico per scaricare il driver pi\u00f9 recente.<\/li>\n<li>Nella maggior parte dei casi, i produttori offrono un&#8217;utilit\u00e0 in grado di rilevare automaticamente il driver pi\u00f9 adatto al proprio sistema e di scaricarlo. Per i driver AMD, puoi visitare il sito Web e fare clic sul pulsante &#8220;Scarica driver Windows&#8221; per ottenere l&#8217;utilit\u00e0.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"488\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/41-1.webp\" title=\"\" width=\"867\"\/><\/figure>\n<ul>\n<li>Una volta che l&#8217;utilit\u00e0 ha trovato il driver, seguire la stessa procedura sopra descritta per scaricarlo e installarlo prima di riavviare il PC.<\/li>\n<\/ul>\n<h2 id=\"11-change-the-internet-time-server\">11. Modificare il server orario Internet<\/h2>\n<p>La modifica dell&#8217;Internet Time Server \u00e8 un&#8217;altra possibile soluzione che pu\u00f2 aiutarti a correggere gli errori 0x80070490 e 0x80072EFE. Windows si sincronizza con time.windows.com per impostazione predefinita, ma puoi modificarne facilmente la configurazione.<\/p>\n<ul>\n<li>Fare clic con il tasto destro sulla sezione data e ora sulla barra delle applicazioni e fare clic sull&#8217;opzione &#8220;Regola data e ora&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"465\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/46-1-1.webp\" title=\"\" width=\"827\"\/><\/figure>\n<ul>\n<li>Nella pagina Impostazioni data e ora, scorri verso il basso e fai clic sull&#8217;opzione &#8220;Orologi aggiuntivi&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"479\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/47-1.webp\" title=\"\" width=\"852\"\/><\/figure>\n<ul>\n<li>Dalla finestra pop-up visualizzata, vai alla scheda &#8220;Ora Internet&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"535\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/48-1.webp\" title=\"\" width=\"951\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante &#8220;Modifica impostazioni&#8221; in questa scheda.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"523\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/49-1.webp\" title=\"\" width=\"929\"\/><\/figure>\n<ul>\n<li>Ora puoi configurare Internet Time Server. Cambialo da &#8220;time.windows.com&#8221; a &#8220;time.nist.gov&#8221; e fai clic sul pulsante &#8220;Aggiorna ora&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"509\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/50-1.webp\" title=\"\" width=\"904\"\/><\/figure>\n<ul>\n<li>Infine, fai clic sul pulsante &#8220;OK&#8221; su entrambe le finestre e chiudi l&#8217;app Impostazioni.<\/li>\n<\/ul>\n<p>Gli errori 0x80070490 e 0x80072EFE possono verificarsi a causa di una serie di cause, come aggiornamenti di Windows difettosi, driver non aggiornati, impostazioni dell&#8217;ora errate, ecc. I metodi che abbiamo condiviso qui possono aiutarti a risolvere il problema se gli errori sono che si verificano a causa di queste cause comuni.<\/p>\n<p>Detto questo, alcune di queste soluzioni sono temporanee e potrebbero funzionare solo per un breve periodo. Se riscontri nuovamente questi errori, l&#8217;unica opzione rimasta \u00e8 attendere fino a quando Microsoft non rilascia gli aggiornamenti che contengono correzioni che risolvono il problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sono diversi motivi per cui Microsoft Windows \u00e8 uno dei sistemi operativi pi\u00f9 popolari al mondo. \u00c8 facile da usare, \u00e8 compatibile con diversi hardware e ha un numero enorme di applicazioni software disponibili. Tuttavia, poich\u00e9 il sistema operativo \u00e8 progettato per funzionare su un&#8217;ampia variet\u00e0 di macchine di diversi produttori, a volte pu\u00f2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[130,7],"class_list":["post-1591","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-microsoft","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1591"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1591\/revisions"}],"predecessor-version":[{"id":1592,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1591\/revisions\/1592"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}