{"id":1723,"date":"2024-04-17T11:53:50","date_gmt":"2024-04-17T11:53:50","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1723"},"modified":"2024-04-17T11:53:50","modified_gmt":"2024-04-17T11:53:50","slug":"how-to-fix-time-sync-failed-on-windows-8-methods-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-fix-time-sync-failed-on-windows-8-methods-it\/","title":{"rendered":"Come risolvere la sincronizzazione dell&#8217;ora non riuscita su Windows (8 metodi)"},"content":{"rendered":"<p>La data e l&#8217;ora impostate sul tuo PC Windows sono cruciali per molte cose. Le app utilizzano queste informazioni per fornirti informazioni, promemoria e app timer dipendono da esse, ecc.<\/p>\n<p>Tuttavia, a volte potresti scoprire che tali servizi non funzionano correttamente perch\u00e9 l&#8217;orologio del sistema Windows non \u00e8 sincronizzato. Quando l&#8217;orologio di sistema non \u00e8 sincronizzato, potresti visualizzare una data e un&#8217;ora errate e un messaggio di errore che dice &#8220;Sincronizzazione dell&#8217;ora non riuscita&#8221;.<\/p>\n<p>Se ultimamente hai ricevuto lo stesso messaggio di errore, segui questa guida. Di seguito, abbiamo condiviso alcuni semplici metodi per correggere l&#8217;errore Sincronizzazione dell&#8217;ora non riuscita in Windows. Iniziamo.<\/p>\n<h3><span id=\"Why_Windows_Time_Failed_to_Sync\"><strong>Perch\u00e9 l&#8217;ora di Windows non \u00e8 riuscita a sincronizzarsi?<\/strong><\/span><\/h3>\n<p>Diversi motivi possono causare il fallimento della sincronizzazione dell&#8217;ora su Windows. Di seguito sono riportati i motivi pi\u00f9 comuni.<\/p>\n<ul>\n<li>Impostazioni di data e ora errate.<\/li>\n<li>Virus o infezione da malware.<\/li>\n<li>Problema con il servizio Ora di Windows.<\/li>\n<li>Impostazioni firewall errate.<\/li>\n<li>Sistema di corruzione dei file.<\/li>\n<li>Problema con la batteria CMOS.<\/li>\n<\/ul>\n<h2><span id=\"How_to_Fix_Time_Sync_Failed_in_Windows\"><strong>Come risolvere la sincronizzazione dell&#8217;ora non riuscita in Windows<\/strong><\/span><\/h2>\n<p>Poich\u00e9 non conosciamo il motivo effettivo per cui la sincronizzazione dell&#8217;ora non \u00e8 riuscita in Windows, dovremo seguire diversi metodi di risoluzione dei problemi. Ecco cosa puoi fare per risolvere il problema del tempo su Windows.<\/p>\n<h3><span id=\"1_Check_the_Date_Time_Settings_on_Windows\"><strong>1. Controlla le impostazioni di data e ora su Windows<\/strong><\/span><\/h3>\n<p>La prima cosa che dovresti fare \u00e8 assicurarti che la data e l&#8217;ora siano impostate per l&#8217;aggiornamento automatico. Ecco come puoi controllare le impostazioni di data e ora del tuo PC Windows.<\/p>\n<p>1. Avvia l&#8217; app <strong>Impostazioni<\/strong> sul tuo PC.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni\" class=\"wp-image\" decoding=\"async\" height=\"800\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Settings-1-1-9.webp\" title=\"Impostazioni\" width=\"708\"\/><\/figure>\n<p>2. Quando si apre l&#8217;app Impostazioni, passa a <strong>Ora e lingua<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Tempo e linguaggio\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Allow-Windows-11-to-Update-Time-Automatically-2.webp\" title=\"Tempo e linguaggio\" width=\"288\"\/><\/figure>\n<p>3. Sul lato destro, fare clic su <strong>Data e ora<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Appuntamento\" class=\"wp-image\" decoding=\"async\" height=\"398\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Allow-Windows-11-to-Update-Time-Automatically-3.webp\" title=\"Appuntamento\" width=\"600\"\/><\/figure>\n<p>4. Successivamente, attiva l&#8217;interruttore accanto a <strong>Imposta ora automaticamente<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Imposta l'ora automaticamente\" class=\"wp-image\" decoding=\"async\" height=\"357\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Allow-Windows-11-to-Update-Time-Automatically-4.webp\" title=\"Imposta l'ora automaticamente\" width=\"700\"\/><\/figure>\n<p>5. Successivamente, scorri fino alla sezione Impostazioni aggiuntive e fai clic <strong>su Sincronizza ora<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Sincronizza ora\" class=\"wp-image\" decoding=\"async\" height=\"208\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Sync-Now.webp\" title=\"Sincronizza ora\" width=\"900\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ecco come puoi controllare le impostazioni di data e ora su Windows 11 per risolvere il problema della sincronizzazione dell&#8217;ora non riuscita.<\/p>\n<h3><span id=\"2_Change_the_Time_Server\"><strong>2. Modificare il server dell&#8217;ora<\/strong><\/span><\/h3>\n<p>La prossima cosa migliore che puoi fare per risolvere il problema della sincronizzazione dell&#8217;ora non riuscita \u00e8 cambiare il server dell&#8217;ora su Windows 11. Ecco come puoi modificare il server dell&#8217;ora sul tuo PC Windows in semplici passaggi.<\/p>\n<p>1. Apri la ricerca di Windows e digita le impostazioni di data e ora. Successivamente, apri l&#8217; opzione <strong>delle impostazioni Data e ora<\/strong> dall&#8217;elenco dei risultati della ricerca.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni di data e ora\" class=\"wp-image\" decoding=\"async\" height=\"743\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Change-the-Time-Server-1.webp\" title=\"Impostazioni di data e ora\" width=\"800\"\/><\/figure>\n<p>2. Nella schermata Data e ora, scorrere verso il basso e fare clic su <strong>Orologi aggiuntivi<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Orologi aggiuntivi\" class=\"wp-image\" decoding=\"async\" height=\"412\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Change-the-Time-Server-2.webp\" title=\"Orologi aggiuntivi\" width=\"1000\"\/><\/figure>\n<p>3. Alla richiesta Data e ora, selezionare <strong>Orario Internet<\/strong> .<\/p>\n<p>4. Successivamente, fai clic sul pulsante <strong>Modifica impostazioni<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cambia impostazioni\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Change-the-Time-Server-3.webp\" title=\"Cambia impostazioni\" width=\"530\"\/><\/figure>\n<p>5. Fare clic sul menu a discesa Server e selezionare <strong>time.windows.com<\/strong> . Una volta terminato, fai clic sul pulsante <strong>Aggiorna ora<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"time.windows.com\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Change-the-Time-Server-4.webp\" title=\"time.windows.com\" width=\"539\"\/><\/figure>\n<p>Questo \u00e8 tutto! Dopo aver apportato la modifica, riavvia il PC. Ci\u00f2 dovrebbe risolvere il problema che stai riscontrando con la sincronizzazione dell&#8217;ora non riuscita.<\/p>\n<h3><span id=\"3_Restart_the_Windows_Time_Service\"><strong>3. Riavviare il servizio Ora di Windows<\/strong><\/span><\/h3>\n<p>Affinch\u00e9 la sincronizzazione dell&#8217;ora funzioni, il servizio Ora di Windows deve essere costantemente in esecuzione in background. Se si verificano problemi con questo servizio, la sincronizzazione dell&#8217;ora fallir\u00e0 e causer\u00e0 errori. Quindi, puoi provare a riavviare il servizio Ora di Windows e vedere se aiuta.<\/p>\n<p>1. Premi il <strong>tasto Windows + R<\/strong> sulla tastiera. Questo aprir\u00e0 la finestra di dialogo ESEGUI.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Finestra di dialogo ESEGUI\" class=\"wp-image\" decoding=\"async\" height=\"409\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/System-Properties-1.webp\" title=\"Finestra di dialogo ESEGUI\" width=\"600\"\/><\/figure>\n<p>2. Quando si apre la finestra di dialogo ESEGUI, digitare <strong>services.msc<\/strong> e premere Invio.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"services.msc\" class=\"wp-image\" decoding=\"async\" height=\"452\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Enable-the-WLAN-AutoConfig-Service-2-min-1.webp\" title=\"services.msc\" width=\"677\"\/><\/figure>\n<p>3. Trova l&#8217;ora di Windows.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Ora di Windows\" class=\"wp-image\" decoding=\"async\" height=\"406\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Check-the-Windows-Time-Service-Status-2.webp\" title=\"Ora di Windows\" width=\"600\"\/><\/figure>\n<p>4. Fare clic con il tasto destro su Ora di Windows e selezionare Start. Se \u00e8 gi\u00e0 in esecuzione, fare clic con il pulsante destro del mouse e selezionare <strong>Interrompi<\/strong> , quindi <strong>Avvia<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Inizio\" class=\"wp-image\" decoding=\"async\" height=\"611\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Windows-Time.webp\" title=\"Inizio\" width=\"900\"\/><\/figure>\n<p>Questo \u00e8 tutto! Assicurati di riavviare il computer dopo aver riavviato il servizio Ora di Windows.<\/p>\n<h3><span id=\"4_Add_More_Time_Servers\"><strong>4. Aggiungi altri time server<\/strong><\/span><\/h3>\n<p>L&#8217;aggiunta di pi\u00f9 servizi temporali potrebbe correggere l&#8217;errore di sincronizzazione dell&#8217;ora non riuscita su Windows. Se aggiungi pi\u00f9 server dell&#8217;ora, Windows prover\u00e0 diversi server a mantenere l&#8217;ora sincronizzata. Ecco come puoi aggiungere pi\u00f9 time server su Windows.<\/p>\n<p>1. Digitare Editor del Registro di sistema nella ricerca di Windows. Successivamente, apri l&#8217; app <strong>Editor del Registro di sistema<\/strong> dall&#8217;elenco dei migliori risultati di corrispondenza.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Editor del registro\" class=\"wp-image\" decoding=\"async\" height=\"606\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Turn-off-Copilit-by-Editing-the-Windows-11-Registry-1.webp\" title=\"Editor del registro\" width=\"700\"\/><\/figure>\n<p>2. Quando si apre l&#8217;Editor del Registro di sistema, accedere a questo percorso:<\/p>\n<p> <code><strong>HKEY_LOCAL_MACHINE\\SOFTWARE\\Microsoft\\Windows\\CurrentVersion\\DateTime\\Servers<\/strong><\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"navigare verso questo percorso\" class=\"wp-image\" decoding=\"async\" height=\"373\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Add-More-time-servers-1.webp\" title=\"navigare verso questo percorso\" width=\"900\"\/><\/figure>\n<p>3. Fare clic con il pulsante destro del mouse su Server e selezionare <strong>Nuovo &gt; Valore stringa<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Nuovo &gt; Valore stringa\u201d title=\u201dNuovo &gt; Valore stringa\u201d larghezza=\u201d900\u2033 altezza=\u201d552\u2033 caricamento=\u201dlazy\u201d class=\u201dwp-image\u201d src=\u201dhttps:\/\/cdn.howtogeek.blog\/wp- content\/uploads\/2024\/04\/Add-More-time-servers-2.webp\u201d\/&gt;&lt;\/figure&gt; &lt;p&gt;4. Assegna un nome al nuovo valore String come preferisci, ad esempio Server nuovo, Server 3 e cos\u00ec via. Fai doppio clic sul valore String. Nel campo dei dati del valore, digita &lt;strong&gt;time.google.com&lt;\/strong&gt; e fai clic su &lt;strong&gt;OK&lt;\/strong&gt;.&lt;\/p&gt; &lt;figure class=\" wp-block-image=\"\"\/><img alt=\"time.google.com\" class=\"wp-image\" decoding=\"async\" height=\"552\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Add-More-time-servers-3.webp\" title=\"time.google.com\" width=\"900\"\/><\/figure>\n<p>Questo \u00e8 tutto! Seguendo gli stessi passaggi, puoi aggiungere pi\u00f9 time server al tuo PC.<\/p>\n<h3><span id=\"5_Force_the_Time_Sync_with_CMD\"><strong>5. Forza la sincronizzazione dell&#8217;ora con CMD<\/strong><\/span><\/h3>\n<p>Se ricevi ancora il messaggio di errore di sincronizzazione dell&#8217;ora non riuscita, puoi provare a forzare la sincronizzazione dell&#8217;ora tramite il prompt dei comandi. Ci\u00f2 costringer\u00e0 Windows a sincronizzare immediatamente l&#8217;ora.<\/p>\n<p>1. Digitare <strong>Prompt dei comandi<\/strong> nella ricerca di Windows. Successivamente, fai clic con il pulsante destro del mouse sul CMD e seleziona <strong>Esegui come amministratore<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui come amministratore\" class=\"wp-image\" decoding=\"async\" height=\"659\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Search-for-Apps-on-Windows-11-using-Winget-1-3.webp\" title=\"Esegui come amministratore\" width=\"700\"\/><\/figure>\n<p>2. Quando si apre il prompt dei comandi, eseguire questi comandi uno per uno.<\/p>\n<p> <code>net stop w32time<\/code><\/p>\n<p>w32tm \/annulla registrazione<\/p>\n<p>w32tm\/register<\/p>\n<p>inizio netto w32time<\/p>\n<p>w32tm \/risincronizzazione<\/p>\n<figure class=\"wp-block-image\"><img alt=\"arresto netto w32time\" class=\"wp-image\" decoding=\"async\" height=\"453\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Force-Time-Sync-with-CMD.webp\" title=\"arresto netto w32time\" width=\"900\"\/><\/figure>\n<p>Dopo aver eseguito tutti i comandi, chiudi il prompt dei comandi e riavvia il tuo PC Windows. Ci\u00f2 costringer\u00e0 Windows a sincronizzare l&#8217;ora.<\/p>\n<h3><span id=\"6_Run_the_SFC_and_DISM_Command\"><strong>6. Eseguire il comando SFC e DISM<\/strong><\/span><\/h3>\n<p>La corruzione dei file di sistema potrebbe essere un altro motivo per cui Windows non riesce a sincronizzare l&#8217;ora. Puoi trovare e sostituire i file di sistema danneggiati eseguendo i comandi SFC e DISM. Ecco come farlo.<\/p>\n<p>1. Digita CMD nella ricerca di Windows 11. Fare clic con il tasto destro sul CMD e selezionare <strong>Esegui come amministratore<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui come amministratore.\" class=\"wp-image\" decoding=\"async\" height=\"520\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Open-Device-Manager-via-Command-Prompt-1.webp\" title=\"Esegui come amministratore.\" width=\"600\"\/><\/figure>\n<p>2. Quando si apre il prompt dei comandi, eseguire questo comando:<\/p>\n<p> <code><strong>sfc \/scannow<\/strong><\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"sfc\/scannow\" class=\"wp-image\" decoding=\"async\" height=\"272\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Corrupted-System-Files-1-5.webp\" title=\"sfc\/scannow\" width=\"501\"\/><\/figure>\n<p>3. Se la scansione SFC restituisce un errore, eseguire questo comando:<\/p>\n<p> <code><strong>DISM \/Online \/Cleanup-Image \/RestoreHealth<\/strong><\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Ripara i file di sistema danneggiati\" class=\"wp-image\" decoding=\"async\" height=\"531\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/DISM-3.webp\" title=\"Ripara i file di sistema danneggiati\" width=\"900\"\/><\/figure>\n<p>Questo \u00e8 tutto! I comandi precedenti troveranno e sostituiranno tutti i file di sistema danneggiati.<\/p>\n<h3><span id=\"7_Disable_any_Firewall_or_Third-Party_Security_Program\"><strong>7. Disabilitare qualsiasi firewall o programma di sicurezza di terze parti<\/strong><\/span><\/h3>\n<p>I firewall e le app di sicurezza di terze parti che potresti utilizzare possono impedire l&#8217;esecuzione del servizio Ora di Windows e creare problemi con la sincronizzazione dell&#8217;ora.<\/p>\n<p>Pertanto, se di recente hai aggiunto una protezione firewall o un&#8217;app di sicurezza, puoi disabilitarla temporaneamente e verificare.<\/p>\n<h3><span id=\"8_Run_a_full_antivirus_scan\"><strong>8. Esegui una scansione antivirus completa<\/strong><\/span><\/h3>\n<p>I software dannosi a volte possono interrompere il processo di sincronizzazione dell&#8217;ora e causare errori. Pertanto, se tutti gli altri metodi sopra elencati non sono riusciti a risolvere i problemi di sincronizzazione dell&#8217;ora, \u00e8 tempo di cercare programmi dannosi.<\/p>\n<p>1. Digitare <strong>Sicurezza di Windows<\/strong> nella ricerca di Windows. Successivamente, apri l&#8217;app Sicurezza di Windows dall&#8217;elenco dei risultati con la corrispondenza migliore.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Sicurezza di Windows\" class=\"wp-image\" decoding=\"async\" height=\"657\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Run-an-Antivirus-Scan-1.webp\" title=\"Sicurezza di Windows\" width=\"773\"\/><\/figure>\n<p>2. Quando si apre l&#8217;app Sicurezza di Windows, passa alla scheda <strong>Protezione da virus e minacce<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Protezione da virus e minacce\" class=\"wp-image\" decoding=\"async\" height=\"432\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Windows-Security-Exclusions-2.webp\" title=\"Protezione da virus e minacce\" width=\"640\"\/><\/figure>\n<p>3. Sul lato destro, fare clic su <strong>Opzioni di scansione<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Opzioni di scansione\" class=\"wp-image\" decoding=\"async\" height=\"590\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Run-an-Antivirus-Scan-3-1.webp\" title=\"Opzioni di scansione\" width=\"654\"\/><\/figure>\n<p>4. Successivamente, seleziona Scansione completa e fai clic <strong>su Scansione ora<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Scansione completa\" class=\"wp-image\" decoding=\"async\" height=\"432\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Run-an-Antimalware-Scan-4.webp\" title=\"Scansione completa\" width=\"640\"\/><\/figure>\n<p>Il completamento della scansione completa potrebbe richiedere del tempo, quindi sii paziente. Una volta completata la scansione, riavvia il tuo PC Windows 11 e controlla se ricevi ancora l&#8217;errore.<\/p>\n<p>Questi sono i pochi modi migliori per gestire il problema della sincronizzazione dell&#8217;ora non riuscita su PC\/laptop Windows. Se hai bisogno di ulteriore aiuto per risolvere questo problema, faccelo sapere nei commenti. Inoltre, se trovi utile questa guida, non dimenticare di condividerla con gli altri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La data e l&#8217;ora impostate sul tuo PC Windows sono cruciali per molte cose. Le app utilizzano queste informazioni per fornirti informazioni, promemoria e app timer dipendono da esse, ecc. Tuttavia, a volte potresti scoprire che tali servizi non funzionano correttamente perch\u00e9 l&#8217;orologio del sistema Windows non \u00e8 sincronizzato. Quando l&#8217;orologio di sistema non \u00e8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-1723","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1723"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1723\/revisions"}],"predecessor-version":[{"id":1724,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1723\/revisions\/1724"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}