{"id":1725,"date":"2024-04-17T11:57:26","date_gmt":"2024-04-17T11:57:26","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1725"},"modified":"2024-04-17T11:57:26","modified_gmt":"2024-04-17T11:57:26","slug":"11-fixes-for-iphone-not-receiving-calls-but-can-make-them-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/11-fixes-for-iphone-not-receiving-calls-but-can-make-them-it\/","title":{"rendered":"11 correzioni per iPhone che non riceve chiamate ma pu\u00f2 effettuarle"},"content":{"rendered":"<p><a href=\"https:\/\/support.apple.com\/en-us\/HT204027\" rel=\"noreferrer noopener\" target=\"_blank\">Non riesci a ricevere chiamate<\/a> su iPhone quando puoi chiamare altri? Risulta che ci sono alcune impostazioni che possono silenziare le chiamate in arrivo o inviarle direttamente alla segreteria telefonica. Per fortuna, invertire queste impostazioni pu\u00f2 risolvere il problema. Lascia che ti mostri come.<\/p>\n<h2><span id=\"1-Begin-by-Checking-Various-Focus-Mode-Settings\">1. Inizia controllando le varie impostazioni della modalit\u00e0 di messa a fuoco<\/span><\/h2>\n<p>La prima cosa che dovresti controllare se il tuo iPhone non riceve chiamate \u00e8 dare un&#8217;occhiata alle varie impostazioni della modalit\u00e0 Focus. Ecco alcune cose da provare:<\/p>\n<ul>\n<li><strong>Disattiva la modalit\u00e0 Focus attiva:<\/strong> apri Centro di controllo e cerca il riquadro Focus. Se dice On, toccalo e tocca nuovamente la modalit\u00e0 Focus attiva per disattivarla.<\/li>\n<li><strong>Riattiva la modalit\u00e0 Focus<\/strong> : attiva qualsiasi modalit\u00e0 Focus per alcuni secondi, quindi disattivala.<\/li>\n<li><strong>Disattiva la pianificazione della messa a fuoco<\/strong> : vai su <strong>Impostazioni &gt; Messa a fuoco<\/strong> e tocca ciascun profilo uno per uno. Cerca la sezione <strong>Imposta una pianificazione<\/strong> . Assicurati che non sia abilitata alcuna pianificazione automatica per nessun profilo, <strong>specialmente in Sleep Focus<\/strong> . Sugli iPhone pi\u00f9 vecchi, vai su Impostazioni &gt; Messa a fuoco &gt; Sonno. Disattiva l&#8217;interruttore accanto ad Attiva prima di andare a dormire.<\/li>\n<li><strong>Disattiva Condividi su dispositivi<\/strong> : se disponi di pi\u00f9 dispositivi Apple, controlla se la modalit\u00e0 Focus \u00e8 abilitata su qualcuno di essi. Questo perch\u00e9 le impostazioni di Focus sono condivise su tutti i dispositivi. Per disattivarlo, vai su <strong>Impostazioni &gt; Messa a fuoco<\/strong> . Disattiva l&#8217;interruttore accanto a <strong>Condividi su tutti i dispositivi<\/strong> .<\/li>\n<\/ul>\n<p>Se desideri mantenere attiva la modalit\u00e0 Focus senza influire sulle chiamate in arrivo, prova questi suggerimenti:<\/p>\n<ul>\n<li>Vai su Impostazioni &gt; Messa a fuoco. Tocca la modalit\u00e0 Focus attiva e vai su Persone. Seleziona Consenti notifiche e scegli Tutti in Consenti chiamate da.<\/li>\n<li>Se le chiamate vengono silenziate per un solo contatto, vai alla modalit\u00e0 Focus attiva e tocca Persone seguito da Notifiche silenzio. Rimuovilo dall&#8217;elenco.<\/li>\n<\/ul>\n<h2><span id=\"2-Basic-Yet-Important-Fixes-to-Try\">2. Correzioni basilari ma importanti da provare<\/span><\/h2>\n<p>Prima di passare alla modifica di altre impostazioni o ad approfondire, dovresti provare le seguenti soluzioni:<\/p>\n<ol>\n<li><strong>Riavvia il tuo iPhone<\/strong> : spegni e riaccendi il telefono.<\/li>\n<li><strong>Attivare e disattivare la modalit\u00e0 aereo:<\/strong> vai su <strong>Impostazioni<\/strong> e attiva l&#8217;interruttore accanto a Modalit\u00e0 <strong>aereo<\/strong> . Utilizza lo stesso interruttore per spegnerlo dopo alcuni secondi.<\/li>\n<li><strong>Rimuovere e reinserire la scheda SIM:<\/strong> rimuovere la scheda SIM dal telefono per alcuni secondi. Pulirlo con un panno in microfibra o soffiarvi sopra un po&#8217; d&#8217;aria. Quindi rimettilo nel telefono.<\/li>\n<li><strong>Aggiorna iPhone<\/strong> : installa eventuali aggiornamenti software in sospeso sul tuo iPhone il prima possibile. Spesso anche l&#8217;utilizzo di vecchi software pu\u00f2 causare questo problema. Vai su <strong>Impostazioni &gt; Generali &gt; Software<\/strong> per verificare e installare gli ultimi aggiornamenti.<\/li>\n<\/ol>\n<h2><span id=\"3-Check-for-Blocked-Numbers\">3. Controlla i numeri bloccati<\/span><\/h2>\n<p>Se non ricevi chiamate da un contatto, dovresti controllare l&#8217;elenco bloccato dell&#8217;iPhone. Potresti averli aggiunti accidentalmente laggi\u00f9. Per farlo, vai su <strong>Impostazioni &gt; Telefono &gt; Contatti bloccati<\/strong> . Se viene visualizzato un numero, scorri su di esso e premi l&#8217; opzione <strong>Sblocca<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"908\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/iphone-check-blocked-list-1024x908-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<h2><span id=\"4-Turn-off-Silence-Unknown-Callers-Setting\">4. Disattiva l&#8217;impostazione Silenzia chiamanti sconosciuti<\/span><\/h2>\n<p>Se non ricevi chiamate da numeri sconosciuti, potrebbe essere perch\u00e9 hai attivato l&#8217;impostazione Silenzia chiamanti sconosciuti. Quando questa opzione \u00e8 attivata, le chiamate provenienti da numeri sconosciuti vengono instradate alla segreteria telefonica. Vai su <strong>Impostazioni &gt; Telefono &gt; Silenzia chiamanti sconosciuti<\/strong> e disattivalo.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"538\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Fix-iPhone-Cannot-Receive-Calls-Turn-off-silence-Unknown-Callers.webp\" title=\"\" width=\"304\"\/><\/figure>\n<h2><span id=\"5-Turn-off-Call-Forwarding\">5. Disattiva l&#8217;inoltro delle chiamate<\/span><\/h2>\n<p>\u00c8 possibile che tu abbia abilitato l&#8217;inoltro delle chiamate e ti sia dimenticato di disattivarlo. Per chi non lo sapesse, le chiamate verranno instradate al numero specificato nell&#8217;elenco Inoltro chiamate invece di arrivare al tuo iPhone. Per disattivarlo, vai su <strong>Impostazioni &gt; Telefono &gt; Inoltro chiamate<\/strong> e disattivalo.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"538\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Fix-iPhone-Cannot-Receive-Calls-Call-Forwarding.webp\" title=\"\" width=\"304\"\/><\/figure>\n<h2><span id=\"6-Change-Network-Band\">6. Cambia banda di rete<\/span><\/h2>\n<p>Spesso, la banda di rete del tuo operatore pu\u00f2 impedire al tuo iPhone di ricevere chiamate. Per risolverlo, dovrai passare a una banda di rete diversa. Se utilizzi una rete 5G, passa a 4G o 3G e cos\u00ec via. Vai <strong>a Impostazioni &gt; Dati mobili &gt; Opzioni dati mobili &gt; Voce e dati<\/strong> . Seleziona la banda. Dovresti anche <strong>attivare o disattivare l&#8217;opzione VoLTE<\/strong> per vedere se risolve il problema.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"596\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/04\/Fix-iPhone-Cannot-Receive-Calls-Change-Network-Band.webp\" title=\"\" width=\"675\"\/><\/figure>\n<h2><span id=\"7-iPhone-Not-Ringing-for-Incoming-Calls-But-Calls-Appear-in-Recents\">7. L&#8217;iPhone non squilla per le chiamate in arrivo ma le chiamate vengono visualizzate in Recenti<\/span><\/h2>\n<p>Se ricevi una notifica di chiamata persa e la vedi nei Recenti sul tuo iPhone ma non la senti, il problema potrebbe riguardare le impostazioni audio del tuo telefono. Ecco alcune cose da provare:<\/p>\n<ul>\n<li><strong>Controlla il pulsante audio fisico<\/strong> : inizia controllando il pulsante fisico Mute sul lato sinistro del telefono. Se \u00e8 premuto, l&#8217;audio del telefono \u00e8 disattivato. Spingerlo verso l&#8217;alto per disattivare la modalit\u00e0 silenziosa.<\/li>\n<li><strong>Controlla il livello del volume:<\/strong> controlla il livello del volume della suoneria. Se \u00e8 troppo basso, non sentirai la suoneria. Per aumentare il volume, vai su Impostazioni &gt; Suono e feedback tattile. Sposta il cursore verso l&#8217;alto presente nella sezione Suoneria e avvisi.<\/li>\n<li><strong>Controlla se la suoneria <\/strong> <strong>funziona o meno:<\/strong> in Impostazioni &gt; Suono e tatto, tocca l&#8217;opzione Suoneria. Innanzitutto, assicurati che un suono sia stato assegnato alla suoneria. Successivamente, per vedere se la suoneria assegnata funziona, toccala. Puoi anche sperimentare cambiando la suoneria per verificare se riesci a sentire le chiamate in arrivo.<\/li>\n<li><strong>Controllare le impostazioni delle notifiche:<\/strong> vai su Impostazioni &gt; Telefono &gt; Notifiche. Innanzitutto, assicurati che l&#8217;interruttore Consenti notifiche sia attivo e controlla che altre impostazioni come schermata di blocco, banner, ecc. siano abilitate.<\/li>\n<li><strong>Disconnetti gli accessori Bluetooth:<\/strong> quando un accessorio Bluetooth, ad esempio una cuffia, \u00e8 collegato al tuo iPhone, le chiamate in arrivo squilleranno tramite esso anzich\u00e9 tramite il telefono. Per ascoltare la suoneria sul telefono, disconnettere il dispositivo Bluetooth o disattivare completamente il Bluetooth.<\/li>\n<\/ul>\n<h2><span id=\"8-More-Solutions-to-Try-Before-Reset\">8. Altre soluzioni da provare prima del ripristino<\/span><\/h2>\n<ul>\n<li><strong>Disattiva Consenti chiamate su altri dispositivi<\/strong> : vai su Impostazioni &gt; Cellulare\/Cellulare &gt; Chiamate su altri dispositivi e disattivalo nella schermata successiva.<\/li>\n<li><strong>Disattiva le chiamate Wi-Fi<\/strong> : vai su Impostazioni &gt; Cellulare\/Cellulare &gt; Chiamate Wi-Fi e disattivalo.<\/li>\n<li><strong>Disattivare la risposta automatica alle chiamate<\/strong> : vai su Impostazioni &gt; Accessibilit\u00e0 &gt; Tocco &gt; Instradamento audio chiamata &gt; Chiamate con risposta automatica e disattivala.<\/li>\n<li><strong>Controllare i limiti di comunicazione\/tempo di utilizzo:<\/strong> vai su Impostazioni &gt; Tempo di utilizzo &gt; Limiti di comunicazione. Tocca Durante lo schermo e seleziona Tutti. Fai lo stesso per Durante i tempi di inattivit\u00e0.<\/li>\n<li><strong>Aggiungi nuovamente contatto:<\/strong> prova ad aggiungere nuovamente il contatto se non ricevi chiamate da un solo contatto. Per questo, elimina prima il contatto e poi crea un nuovo contatto.<\/li>\n<\/ul>\n<h2><span id=\"9-Reset-Network-Settings\">9. Ripristina le impostazioni di rete<\/span><\/h2>\n<p>Infine, se non funziona nulla, dovresti ripristinare le impostazioni di rete sul tuo telefono. Per farlo, vai su <strong>Impostazioni &gt; Generali &gt; Trasferisci o Ripristina iPhone &gt; Ripristina<\/strong> . Scegli <strong>Ripristina impostazioni di rete<\/strong> . In questo modo verranno rimosse le password Wi-Fi, le connessioni Bluetooth, le impostazioni VPN e altri elementi simili relativi alla rete attualmente salvati.<\/p>\n<h2><span id=\"10-Check-Social-Media\">10. Controlla i social media<\/span><\/h2>\n<p>Se il problema persiste, controlla i social media come Twitter o Google cerca eventuali interruzioni di rete nella tua citt\u00e0 dovute a cicloni o altre condizioni meteorologiche.<\/p>\n<h2><span id=\"11-Contact-the-Service-Provider\">11. Contattare il fornitore di servizi<\/span><\/h2>\n<p>L&#8217;ultima risorsa \u00e8 contattare il fornitore del servizio cellulare e informarlo del problema. Potrebbero aver aggiunto il numero nella propria app di filtro delle chiamate oppure <a href=\"https:\/\/www.reddit.com\/r\/verizon\/comments\/161hztg\/switched_phone_companies_can_make_phone_calls_but\/\" rel=\"noreferrer noopener\" target=\"_blank\">potrebbe essere necessario modificare una porta<\/a> .<\/p>\n<p>Una volta che le cose sono tornate alla normalit\u00e0, scopri come aggiungere contatti alla schermata principale e come registrare le chiamate su iPhone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non riesci a ricevere chiamate su iPhone quando puoi chiamare altri? Risulta che ci sono alcune impostazioni che possono silenziare le chiamate in arrivo o inviarle direttamente alla segreteria telefonica. Per fortuna, invertire queste impostazioni pu\u00f2 risolvere il problema. Lascia che ti mostri come. 1. Inizia controllando le varie impostazioni della modalit\u00e0 di messa a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[47,17,18,6],"class_list":["post-1725","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-apple","tag-ios","tag-iphone","tag-troubleshooting"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1725"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1725\/revisions"}],"predecessor-version":[{"id":1726,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1725\/revisions\/1726"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}