{"id":1965,"date":"2024-05-09T11:28:17","date_gmt":"2024-05-09T11:28:17","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=1965"},"modified":"2024-05-09T11:28:17","modified_gmt":"2024-05-09T11:28:17","slug":"how-to-reset-display-settings-in-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-reset-display-settings-in-windows-11-it\/","title":{"rendered":"Come ripristinare le impostazioni dello schermo in Windows 11"},"content":{"rendered":"<p>A volte potresti voler provare a modificare le impostazioni dello schermo sul tuo computer, per una migliore leggibilit\u00e0, meno sforzo o per altri motivi. Tuttavia, non vi \u00e8 alcuna garanzia che i risultati siano quelli desiderati e, se non sai come ripristinare le impostazioni dello schermo al loro stato predefinito, potresti ritrovarti con una risoluzione dello schermo strana, colori imprecisi o un carattere illeggibile. misurare.<\/p>\n<p>In alternativa, potresti riscontrare problemi con lo schermo del tuo PC Windows 11 e stai cercando una soluzione che possa aiutarti a risolverli. In tal caso, spiegheremo come ripristinare le impostazioni dello schermo in Windows 11 qui. Il processo \u00e8 abbastanza semplice e non richiede molto tempo. Quindi, veniamo al dunque!<\/p>\n<h2 id=\"reset-the-display-resolution\">Ripristina la risoluzione dello schermo<\/h2>\n<p>Se ritieni che vari elementi del tuo PC Windows 11 siano troppo grandi o piccoli o non siano sufficientemente chiari, la causa pi\u00f9 probabile \u00e8 che la risoluzione del display non \u00e8 corretta per il tuo schermo. La soluzione migliore in questo caso \u00e8 reimpostare la risoluzione su quella consigliata dal sistema operativo.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;Sistema&#8221; a sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"490\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d0-2-1.webp\" title=\"\" width=\"871\"\/><\/figure>\n<ul>\n<li>Fai clic sull&#8217;opzione &#8220;Schermo&#8221; visualizzata a destra per accedere a tutte le impostazioni relative allo schermo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"490\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d0-3-1-1.webp\" title=\"\" width=\"871\"\/><\/figure>\n<ul>\n<li>Nella pagina successiva, scorri verso il basso fino alla sezione &#8220;Scala e layout&#8221; e fai clic sul menu a discesa a destra dell&#8217;opzione &#8220;Risoluzione dello schermo&#8221;. Seleziona la risoluzione consigliata dal sistema cliccandoci sopra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"582\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d1-2-1.webp\" title=\"\" width=\"1034\"\/><\/figure>\n<p>Ora i vari oggetti sullo schermo, come icone e testo, dovrebbero apparire correttamente.<\/p>\n<h2 id=\"reset-the-scaling-settings\">Ripristina le impostazioni di ridimensionamento<\/h2>\n<p>Oltre alla risoluzione del display, le impostazioni di ridimensionamento possono influenzare la grandezza o la dimensione dei vari elementi visualizzati sullo schermo. Puoi provare a reimpostarli se il ripristino della risoluzione non funziona.<\/p>\n<ul>\n<li>Nella pagina Display dell&#8217;app Impostazioni, scorri verso il basso fino alla sezione &#8220;Scala e layout&#8221;.<\/li>\n<li>Fai clic sul menu a discesa a destra dell&#8217;opzione &#8220;Scala&#8221; e imposta l&#8217;impostazione consigliata, che pu\u00f2 essere 100% o 125%, a seconda dell&#8217;hardware.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"561\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d2-2-1.webp\" title=\"\" width=\"997\"\/><\/figure>\n<h2 id=\"reset-the-display-orientation\">Reimpostare l&#8217;orientamento dello schermo<\/h2>\n<p>Windows 11 ti consente di modificare la rotazione dello schermo, il che pu\u00f2 essere molto utile se hai un monitor rotante. Tuttavia, se il display rimane bloccato nell&#8217;orientamento sbagliato, pu\u00f2 causare problemi. Puoi risolvere questo problema seguendo questi passaggi.<\/p>\n<ul>\n<li>Apri le Impostazioni schermo e scorri verso il basso fino alla sezione &#8220;Scala e layout&#8221;.<\/li>\n<li>Fai clic sul menu a discesa a destra dell&#8217;opzione &#8220;Orientamento schermo&#8221; e seleziona l&#8217;impostazione che corrisponde all&#8217;orientamento dello schermo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"588\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d3-3-1.webp\" title=\"\" width=\"1045\"\/><\/figure>\n<h2 id=\"reset-hdr-calibration\">Ripristina la calibrazione HDR<\/h2>\n<p>Se disponi di un monitor che supporta l&#8217;HDR, potresti averlo calibrato e apportato modifiche per prestazioni migliori, ma non hai visto i risultati attesi. In una situazione del genere, si consiglia di reimpostare lo schermo prima di provare a calibrarlo nuovamente.<\/p>\n<ul>\n<li>Apri la pagina Display nell&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;HDR&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"531\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d4-2-1.webp\" title=\"\" width=\"944\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante &#8220;Ripristina impostazioni predefinite&#8221; a destra dell&#8217;opzione &#8220;Ripristina impostazioni di calibrazione predefinite&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"576\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d5-2-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<h2 id=\"reset-night-light-settings\">Ripristina le impostazioni della luce notturna<\/h2>\n<p>Night Light \u00e8 una funzionalit\u00e0 molto utile che riduce la luce blu emessa dal display, contribuendo a ridurre l&#8217;affaticamento degli occhi e a migliorare il sonno. Detto questo, se hai regolato l&#8217;intensit\u00e0 del filtro su un livello estremamente alto o basso, ci\u00f2 pu\u00f2 influenzare il modo in cui i colori appaiono sullo schermo. Ecco come puoi reimpostarlo.<\/p>\n<ul>\n<li>Apri la pagina Display nell&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;Luce notturna&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"488\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d6-2-1.webp\" title=\"\" width=\"867\"\/><\/figure>\n<ul>\n<li>Sposta il cursore che regola l&#8217;intensit\u00e0 del filtro su un valore vicino al centro, ad esempio 48.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"586\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d7-2-1.webp\" title=\"\" width=\"1042\"\/><\/figure>\n<h2 id=\"reset-the-os-colors\">Ripristina i colori del sistema operativo<\/h2>\n<p>Windows ti consente di personalizzare facilmente l&#8217;aspetto e la sensazione del sistema operativo regolando i colori, i bordi, gli accenti, ecc. Se riscontri problemi relativi al display, una possibile soluzione \u00e8 ripristinare i colori del sistema operativo sulle impostazioni predefinite.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sull&#8217;opzione &#8220;Personalizzazione&#8221; a sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"494\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d8-1.webp\" title=\"\" width=\"879\"\/><\/figure>\n<ul>\n<li>Successivamente, fai clic sull&#8217;opzione &#8220;Colori&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"494\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d8-2-1-1.webp\" title=\"\" width=\"879\"\/><\/figure>\n<ul>\n<li>Utilizza il menu a discesa a destra dell&#8217;opzione &#8220;Scegli la tua modalit\u00e0&#8221; per selezionare &#8220;Luce&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"574\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d9-1.webp\" title=\"\" width=\"1020\"\/><\/figure>\n<ul>\n<li>Assicurati che gli &#8220;Effetti di trasparenza&#8221; siano abilitati. In caso contrario, fare clic sul pulsante a destra per attivarli. E imposta l&#8217;opzione &#8220;Accent Color&#8221; su &#8220;Manuale&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"575\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d10-1.webp\" title=\"\" width=\"1023\"\/><\/figure>\n<ul>\n<li>Dopo aver impostato il colore in risalto su &#8220;Manuale&#8221;, seleziona Blu da &#8220;Colori di Windows&#8221;. Scorri verso il basso e assicurati che &#8220;Mostra colore in risalto all&#8217;avvio e sulla barra delle applicazioni&#8221; sia disabilitato. In caso contrario, fai clic sul pulsante a destra e disattivalo. Fai lo stesso per &#8220;Mostra colore in risalto sulle barre del titolo e sui bordi delle finestre&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"558\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d11-1.webp\" title=\"\" width=\"992\"\/><\/figure>\n<h2 id=\"reset-the-mouse-pointer\">Reimposta il puntatore del mouse<\/h2>\n<p>Il puntatore del mouse potrebbe sembrare troppo grande, di un colore diverso o addirittura di entrambi. Per risolvere questo problema, dovrai accedere alle impostazioni di accessibilit\u00e0.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sull&#8217;opzione Accessibilit\u00e0 a sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"511\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d12-1.webp\" title=\"\" width=\"909\"\/><\/figure>\n<ul>\n<li>Nella pagina Accessibilit\u00e0, fai clic sull&#8217;opzione &#8220;Puntatore del mouse e tocco&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"511\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d12-2-1.webp\" title=\"\" width=\"909\"\/><\/figure>\n<ul>\n<li>Fare clic sull&#8217;icona bianca del puntatore del mouse e trascinare il cursore verso sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"502\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d13-2-1.webp\" title=\"\" width=\"892\"\/><\/figure>\n<h2 id=\"turn-off-color-filters\">Disattiva i filtri colore<\/h2>\n<p>Windows offre diversi filtri colorati che possono influenzare il modo in cui i vari elementi dell&#8217;interfaccia utente vengono visualizzati sullo schermo. Puoi disabilitarli se preferisci l&#8217;aspetto predefinito del sistema operativo.<\/p>\n<ul>\n<li>Nella pagina Accessibilit\u00e0 dell&#8217;app Impostazioni, fai clic sull&#8217;opzione &#8220;Filtri colore&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"474\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d14-1.webp\" title=\"\" width=\"842\"\/><\/figure>\n<ul>\n<li>Fare clic sul pulsante a destra dell&#8217;opzione &#8220;Filtri colore&#8221; per disattivarla.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"425\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d15-1.webp\" title=\"\" width=\"756\"\/><\/figure>\n<h2 id=\"turn-off-contrast-themes\">Disattiva i temi a contrasto<\/h2>\n<p>Windows viene fornito con alcuni temi di contrasto progettati per garantire che le icone e il testo siano pi\u00f9 facilmente leggibili e comprensibili. Tuttavia, puoi impostare il tema predefinito se lo preferisci.<\/p>\n<ul>\n<li>Fai clic sull&#8217;opzione &#8220;Temi a contrasto&#8221; nella pagina Accessibilit\u00e0 nell&#8217;app Impostazioni.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"465\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d16-1.webp\" title=\"\" width=\"827\"\/><\/figure>\n<ul>\n<li>Quando si apre la pagina &#8220;Temi di contrasto&#8221;, fai clic sul menu a discesa e seleziona &#8220;Nessuno&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"430\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d17-1.webp\" title=\"\" width=\"765\"\/><\/figure>\n<h2 id=\"reset-windows-themes\">Ripristina temi di Windows<\/h2>\n<p>I temi includono diversi componenti che influiscono sull&#8217;aspetto di Windows, come lo sfondo del desktop, gli effetti di colore, ecc. A seconda del tema applicato, pu\u00f2 creare un po&#8217; di distrazione, quindi puoi reimpostarlo sul tema predefinito.<\/p>\n<ul>\n<li>Apri l&#8217;app Impostazioni e fai clic sulla sezione &#8220;Personalizzazione&#8221;.<\/li>\n<li>Fare clic sull&#8217;opzione &#8220;Temi&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"453\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d18-1.webp\" title=\"\" width=\"805\"\/><\/figure>\n<ul>\n<li>Vedrai tutti i temi che hai installato e quelli preinstallati con Windows. Fare clic sul tema &#8220;Windows Light&#8221; per selezionarlo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"460\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d20-1.webp\" title=\"\" width=\"817\"\/><\/figure>\n<h2 id=\"reset-visual-effects\">Ripristina effetti visivi<\/h2>\n<p>Gli effetti di animazione in Windows possono rendere l&#8217;esperienza dell&#8217;utente pi\u00f9 piacevole in quanto possono rendere le interazioni pi\u00f9 fluide. Se hai apportato modifiche agli effetti visivi, puoi ripristinarli alle impostazioni predefinite.<\/p>\n<ul>\n<li>Nella pagina Accessibilit\u00e0 dell&#8217;app Impostazioni, fai clic sull&#8217;opzione &#8220;Effetti visivi&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"487\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d21-1.webp\" title=\"\" width=\"866\"\/><\/figure>\n<ul>\n<li>Fai clic sul pulsante accanto all&#8217;opzione &#8220;Effetti di animazione&#8221; e attivala.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"581\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d22-2-1.webp\" title=\"\" width=\"1033\"\/><\/figure>\n<h2 id=\"restore-default-color-display-settings\">Ripristina le impostazioni predefinite del display a colori<\/h2>\n<p>Le impostazioni di gestione del colore di Windows 11 ti consentono di creare diversi profili colore per diversi casi d&#8217;uso, ma la creazione di profili complessi pu\u00f2 influire negativamente sulla tua esperienza utente. Per evitare ci\u00f2, puoi ripristinare le impostazioni predefinite del colore dello schermo seguendo questi passaggi.<\/p>\n<ul>\n<li>Apri il Pannello di controllo e fai clic sull&#8217;opzione &#8220;Gestione colore&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"487\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d23-1.webp\" title=\"\" width=\"865\"\/><\/figure>\n<ul>\n<li>Nella finestra Gestione colore, nella scheda &#8220;Dispositivi&#8221;, seleziona il tuo display dal menu a discesa in alto e seleziona l&#8217;opzione &#8220;Utilizza le mie impostazioni per questo dispositivo&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"527\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d24-1.webp\" title=\"\" width=\"936\"\/><\/figure>\n<ul>\n<li>Ora, fai clic sulla scheda &#8220;Avanzate&#8221; in alto e poi sul pulsante &#8220;Cambia impostazioni predefinite del sistema&#8221; in basso.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"614\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d25-1.webp\" title=\"\" width=\"1092\"\/><\/figure>\n<ul>\n<li>Fai nuovamente clic sulla scheda &#8220;Avanzate&#8221; nella casella visualizzata e seleziona l&#8217;opzione &#8220;Utilizza calibrazione colore Windows&#8221;, prima di fare clic sul pulsante &#8220;Chiudi&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"554\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d26-1.webp\" title=\"\" width=\"985\"\/><\/figure>\n<h2 id=\"reset-the-text-color\">Reimposta il colore del testo<\/h2>\n<p>Se hai cambiato il colore del testo sul tuo computer Windows 11 ma non sei soddisfatto dei risultati, puoi modificarlo nuovamente utilizzando l&#8217;editor del Registro di sistema.<\/p>\n<ul>\n<li>Apri il menu Start, digita <code>regedit<\/code>e fai clic sull&#8217;opzione &#8220;Esegui come amministratore&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"578\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d27-1.webp\" title=\"\" width=\"1028\"\/><\/figure>\n<ul>\n<li>Quando si apre l&#8217;editor del Registro di sistema, vai al seguente indirizzo:<code>Computer\\HKEY_CURRENT_USER\\Control Panel\\Colors.<\/code><\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"505\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d28-2-1.webp\" title=\"\" width=\"898\"\/><\/figure>\n<ul>\n<li>Sul lato destro, scorri verso il basso e fai doppio clic sulla voce &#8220;WindowText&#8221;. Digitare <code>000<\/code>e fare clic sul pulsante &#8220;OK&#8221; per salvarlo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"504\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d29-1.webp\" title=\"\" width=\"896\"\/><\/figure>\n<h2 id=\"restore-the-default-text-size\">Ripristina la dimensione del testo predefinita<\/h2>\n<p>Puoi anche ripristinare la dimensione del testo all&#8217;impostazione predefinita dalle impostazioni di accessibilit\u00e0.<\/p>\n<ul>\n<li>Fai clic sull&#8217;opzione &#8220;Dimensione testo&#8221; nella pagina Accessibilit\u00e0 nell&#8217;app Impostazioni.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"465\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d30-1.webp\" title=\"\" width=\"826\"\/><\/figure>\n<ul>\n<li>Sposta il cursore &#8220;Dimensione testo&#8221; verso sinistra per ripristinarlo alla dimensione predefinita.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"532\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d31-1.webp\" title=\"\" width=\"945\"\/><\/figure>\n<h2 id=\"restore-default-icons\">Ripristina le icone predefinite<\/h2>\n<p>Se hai installato icone personalizzate ma desideri ripristinare l&#8217;aspetto predefinito del desktop, ecco i passaggi.<\/p>\n<ul>\n<li>Apri la sezione &#8220;Personalizzazione&#8221; nell&#8217;app Impostazioni.<\/li>\n<li>Fai clic sull&#8217;opzione &#8220;Temi&#8221; e scorri verso il basso fino a &#8220;Impostazioni icone del desktop&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"441\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d32-1.webp\" title=\"\" width=\"784\"\/><\/figure>\n<ul>\n<li>Seleziona le icone che desideri ripristinare e fai clic sul pulsante &#8220;Ripristina impostazioni predefinite&#8221; prima di fare clic sul pulsante &#8220;OK&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"519\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/d33-1.webp\" title=\"\" width=\"922\"\/><\/figure>\n<p>Con i metodi sopra indicati, puoi scegliere di ripristinare i singoli componenti che influiscono sul display di Windows 11 e ripristinarlo alle impostazioni predefinite. Dai colori all&#8217;orientamento e persino la scala, tutto pu\u00f2 essere riportato al suo stato originale. Questi possono essere molto utili se hai modificato determinate impostazioni e non ti piace il modo in cui le cose appaiono sullo schermo.<\/p>\n<p>Tieni presente che la disponibilit\u00e0 di determinate impostazioni dipende dal tuo hardware, come quelle relative all&#8217;HDR. Potrebbe non essere possibile modificarle, ma la maggior parte di queste impostazioni dovrebbe essere disponibile sulla maggior parte dei PC con Windows 11.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A volte potresti voler provare a modificare le impostazioni dello schermo sul tuo computer, per una migliore leggibilit\u00e0, meno sforzo o per altri motivi. Tuttavia, non vi \u00e8 alcuna garanzia che i risultati siano quelli desiderati e, se non sai come ripristinare le impostazioni dello schermo al loro stato predefinito, potresti ritrovarti con una risoluzione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,9],"class_list":["post-1965","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows","tag-windows-11"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=1965"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1965\/revisions"}],"predecessor-version":[{"id":1966,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/1965\/revisions\/1966"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=1965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=1965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=1965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}