{"id":2025,"date":"2024-05-13T14:09:02","date_gmt":"2024-05-13T14:09:02","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2025"},"modified":"2024-05-13T14:09:02","modified_gmt":"2024-05-13T14:09:02","slug":"how-to-change-fan-speed-in-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-change-fan-speed-in-windows-11-it\/","title":{"rendered":"Come modificare la velocit\u00e0 della ventola in Windows 11"},"content":{"rendered":"<p>La ventola di una CPU \u00e8 il componente che aiuta a mantenere fresco il tuo PC, il che \u00e8 particolarmente importante se stai lavorando su qualcosa che richiede molta potenza di elaborazione. Tuttavia, poich\u00e9 sia \u200b\u200bi desktop che i laptop diventano sempre pi\u00f9 compatti e guadagnano sempre pi\u00f9 potenza, la velocit\u00e0 della ventola predefinita sul PC potrebbe non fornire la quantit\u00e0 di raffreddamento richiesta.<\/p>\n<p>Per evitare che il computer si surriscaldi e si danneggi, potrebbe essere necessario regolare la velocit\u00e0 della ventola in modo che fornisca un raffreddamento adeguato. In alternativa, potresti voler modificare la velocit\u00e0 della ventola perch\u00e9 la ventola \u00e8 troppo rumorosa, con conseguenti distrazioni. In entrambi i casi, abbiamo messo insieme questa guida per aiutarti.<\/p>\n<h2 id=\"from-the-power-plan-settings\">Dalle impostazioni del piano di risparmio energia<\/h2>\n<p>Le combinazioni per il risparmio di energia di Windows 11 ti consentono di personalizzare il funzionamento del tuo computer consentendoti di regolare aspetti come il timeout dello schermo, le impostazioni di sospensione e altro ancora. Puoi utilizzare un piano preimpostato o crearne uno tuo per controllare la velocit\u00e0 della ventola.<\/p>\n<ul>\n<li>Apri il Pannello di controllo dal menu Start.<\/li>\n<li>Quando si apre il Pannello di controllo, fare clic su &#8220;Opzioni risparmio energia&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"482\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f0-1.webp\" title=\"\" width=\"857\"\/><\/figure>\n<ul>\n<li>Qui vedrai i piani di risparmio energia disponibili, come un piano di risparmio batteria, un piano bilanciato e un piano ad alte prestazioni. Il piano Risparmio batteria riduce la velocit\u00e0 della ventola e riduce le prestazioni del sistema per risparmiare la batteria, mentre il piano bilanciato mantiene la velocit\u00e0 della ventola al livello normale. Il piano ad alte prestazioni massimizza la velocit\u00e0 della ventola per un raffreddamento pi\u00f9 efficiente. Per modificare la velocit\u00e0 della ventola \u00e8 sufficiente fare clic sul piano che desideri utilizzare.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"495\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f2-1.webp\" title=\"\" width=\"880\"\/><\/figure>\n<ul>\n<li>Se non vedi pi\u00f9 piani qui, fai clic sull&#8217;opzione &#8220;Crea un piano di alimentazione&#8221; a sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"495\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f2-2-1.webp\" title=\"\" width=\"880\"\/><\/figure>\n<ul>\n<li>Ora puoi scegliere tra i tre piani e persino dare al piano selezionato un nome personalizzato. Fai clic sul piano che desideri utilizzare, quindi fai clic sul pulsante &#8220;Avanti&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"419\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f3-1.webp\" title=\"\" width=\"745\"\/><\/figure>\n<ul>\n<li>Nella pagina successiva puoi scegliere quando spegnere lo schermo e mettere il computer in modalit\u00e0 di sospensione. Dopo averlo fatto, fai clic sul pulsante &#8220;Crea&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"449\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f4-1.webp\" title=\"\" width=\"799\"\/><\/figure>\n<ul>\n<li>Una volta creato un piano di risparmio energia, verr\u00e0 visualizzato nella prima pagina delle opzioni di risparmio energia. Fai clic sull&#8217;opzione &#8220;Modifica impostazioni piano&#8221; qui.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"484\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f1-1.webp\" title=\"\" width=\"861\"\/><\/figure>\n<ul>\n<li>Ora, fai clic sull&#8217;opzione &#8220;Modifica impostazioni di alimentazione avanzate&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"486\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f5-1.webp\" title=\"\" width=\"864\"\/><\/figure>\n<ul>\n<li>Nel popup visualizzato, scorri verso il basso e fai clic sul pulsante &#8220;+&#8221; accanto all&#8217;opzione &#8220;Gestione alimentazione processore&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"578\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f6-1.webp\" title=\"\" width=\"1028\"\/><\/figure>\n<ul>\n<li>Ora puoi regolare lo stato minimo e massimo del processore, che controlla la generazione di calore e, di conseguenza, la velocit\u00e0 della ventola. Idealmente, lo stato minimo del processo dovrebbe essere il 5% e il massimo dovrebbe essere il 100%, anche se puoi utilizzare impostazioni personalizzate, se lo desideri.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"495\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f7-1.webp\" title=\"\" width=\"880\"\/><\/figure>\n<h2 id=\"using-the-task-manager\">Utilizzando il Task Manager<\/h2>\n<p>Anche se Windows non consente di controllare direttamente la velocit\u00e0 della ventola, \u00e8 possibile verificare quali processi portano ad un aumento della generazione di calore utilizzando il Task Manager, aumentando cos\u00ec la velocit\u00e0 della ventola. Poi, se vuoi, puoi fermarli e ridurre la velocit\u00e0 della ventola.<\/p>\n<ul>\n<li>Fare clic con il tasto destro sulla barra delle applicazioni e fare clic sull&#8217;opzione &#8220;Task Manager&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f8-1.webp\" title=\"\" width=\"889\"\/><\/figure>\n<ul>\n<li>Il Task Manager mostra tutti i processi in esecuzione sulla destra. Il processo che porta al massimo utilizzo della CPU sar\u00e0 responsabile di una maggiore velocit\u00e0 della ventola. Per chiuderlo, fai clic con il pulsante destro del mouse su di esso e fai clic sull&#8217;opzione &#8220;Termina operazione&#8221;. Non chiudere i processi in background del sistema, poich\u00e9 ci\u00f2 potrebbe causare l&#8217;arresto anomalo del PC.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"582\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f9-1.webp\" title=\"\" width=\"1035\"\/><\/figure>\n<h2 id=\"using-first-party-software\">Utilizzo di software di prima parte<\/h2>\n<p>A meno che non si utilizzi un PC assemblato utilizzando componenti di marche diverse, molto probabilmente \u00e8 dotato di determinati software proprietari. Tale software include utilit\u00e0 che consentono di personalizzare il computer in modo che soddisfi le proprie esigenze in modo pi\u00f9 efficace e pu\u00f2 anche includere strumenti per controllare la velocit\u00e0 della ventola.<\/p>\n<p>L&#8217;aspetto migliore dell&#8217;utilizzo del software di prima parte \u00e8 che \u00e8 progettato specificamente per il tuo hardware, quindi non incorrerai in alcun problema di compatibilit\u00e0.<\/p>\n<ul>\n<li>Controlla il produttore e il modello del tuo PC osservando il numero di serie nella parte inferiore o sul retro del computer. Se utilizzi un sistema personalizzato, chiedi al fornitore la marca e il modello della scheda madre.<\/li>\n<li>Una volta trovate le informazioni richieste, visita il sito web del produttore e cerca il modello del tuo PC. La pagina dovrebbe contenere tutte le utilit\u00e0 che puoi scaricare per il tuo sistema.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"583\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f10-1.webp\" title=\"\" width=\"1036\"\/><\/figure>\n<ul>\n<li>Potresti non trovare un&#8217;utilit\u00e0 dedicata per il controllo della velocit\u00e0 della ventola poich\u00e9 i produttori di solito la associano ad altri software di gestione dell&#8217;alimentazione. Nel caso di Dell, ad esempio, la gestione termica \u00e8 inclusa nel servizio Dell Power Manager. Quindi, cerca tale software e scaricalo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"553\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f10-2-1.webp\" title=\"\" width=\"984\"\/><\/figure>\n<ul>\n<li>Dopo aver scaricato il software, installalo sul tuo PC e aprilo. Fai clic sulle impostazioni di controllo della velocit\u00e0 della ventola, che potrebbero essere presenti in &#8220;Ventola&#8221;, &#8220;Gestione termica&#8221; o opzioni simili.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1296\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/uzvsdtlv11h11-1.webp\" title=\"\" width=\"2305\"\/><\/figure>\n<ul>\n<li>Qui puoi scegliere tra diverse impostazioni che controllano la velocit\u00e0 della ventola. A seconda del sistema, potresti visualizzare opzioni come Predefinito, Risparmio energetico, Prestazioni elevate, ecc. Fai clic sull&#8217;opzione che desideri utilizzare.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1098\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/uzvsdtlv11h11-2-1.webp\" title=\"\" width=\"1951\"\/><\/figure>\n<h2 id=\"from-the-bios\">Dal BIOS<\/h2>\n<p>Il BIOS o Basic Input Output System \u00e8 il sistema operativo presente sulla scheda madre del tuo PC e ti consente di controllare funzioni che altrimenti non potresti. Questo spesso include la velocit\u00e0 della ventola.<\/p>\n<ul>\n<li>Per accedere al BIOS, riavvia il PC e prima che si avvii in Windows, premi il tasto che ti consente di accedere al BIOS. A seconda del produttore del PC, pu\u00f2 essere il tasto <code>F2<\/code>, <code>F10<\/code>o <code>Delete<\/code>.<\/li>\n<li>Nel BIOS, cerca un&#8217;opzione che controlla le impostazioni della ventola e raggiungila. Potrebbe essere presente in Overclocking, Advanced, PC Health o un&#8217;opzione simile.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"547\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/220901-bios-monitor-fanspeed-1.webp\" title=\"\" width=\"973\"\/><\/figure>\n<ul>\n<li>Una volta trovato, modifica la velocit\u00e0 della ventola in base alle tue preferenze. Quindi salva le modifiche ed esci prima di riavviare il PC.<\/li>\n<\/ul>\n<h2 id=\"using-third-party-software\">Utilizzo di software di terze parti<\/h2>\n<p>Un altro modo per controllare la velocit\u00e0 della ventola su Windows 11 \u00e8 tramite software di terze parti, molti dei quali sono disponibili. Alcuni dei pi\u00f9 popolari includono Fan Control, Argus Monitor e SpeedFan. Ricorda che questi non sono progettati specificamente per una marca e un modello particolare, quindi potresti riscontrare problemi.<\/p>\n<ul>\n<li>Visitare il sito Web del software di controllo della ventola di terze parti e scaricarlo da l\u00ec. Ad esempio, puoi visitare questo collegamento e fare clic sul pulsante &#8220;Scarica Zip&#8221; per scaricare Fan Control.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"551\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f11-1.webp\" title=\"\" width=\"980\"\/><\/figure>\n<ul>\n<li>Una volta scaricato il software, installalo sul tuo sistema e avvialo. Nel caso del file zip, dovrai prima estrarlo.<\/li>\n<li>Quando apri l&#8217;utilit\u00e0 per la prima volta, dovrebbe informarti sulle funzioni che ti consentir\u00e0 di controllare. Fare clic sul pulsante &#8220;S\u00ec&#8221; o &#8220;OK&#8221; per procedere.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"496\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f12-1.webp\" title=\"\" width=\"881\"\/><\/figure>\n<ul>\n<li>Il software potrebbe impiegare alcuni secondi per determinare quali impostazioni della ventola della CPU possono essere controllate, prima di mostrarti le impostazioni disponibili. Una volta fatto, puoi regolare la velocit\u00e0 della ventola da zero a 100.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"501\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/f13-1-1.webp\" title=\"\" width=\"891\"\/><\/figure>\n<p>Se la ventola della CPU fa troppo rumore o non funziona correttamente causando problemi di riscaldamento, i metodi sopra indicati possono aiutarti a controllare facilmente la velocit\u00e0 della ventola. Detto questo, le impostazioni predefinite della ventola su Windows fanno un ottimo lavoro nel mantenere un raffreddamento efficace, quindi non dovresti manomettere le impostazioni della velocit\u00e0 della ventola a meno che non ci sia un grosso problema.<\/p>\n<p>Inoltre, \u00e8 una buona idea eseguire il backup del sistema prima di utilizzare strumenti di controllo della velocit\u00e0 della ventola di terze parti. In questo modo, nel caso qualcosa vada storto, puoi ripristinare rapidamente il tuo sistema allo stato precedente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ventola di una CPU \u00e8 il componente che aiuta a mantenere fresco il tuo PC, il che \u00e8 particolarmente importante se stai lavorando su qualcosa che richiede molta potenza di elaborazione. Tuttavia, poich\u00e9 sia \u200b\u200bi desktop che i laptop diventano sempre pi\u00f9 compatti e guadagnano sempre pi\u00f9 potenza, la velocit\u00e0 della ventola predefinita sul [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,9],"class_list":["post-2025","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows","tag-windows-11"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":2026,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2025\/revisions\/2026"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}