{"id":2095,"date":"2024-05-17T07:57:37","date_gmt":"2024-05-17T07:57:37","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2095"},"modified":"2024-05-17T07:57:37","modified_gmt":"2024-05-17T07:57:37","slug":"android-is-getting-an-ai-infusion-with-gemini-nano-heres-everything-you-need-to-know-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/android-is-getting-an-ai-infusion-with-gemini-nano-heres-everything-you-need-to-know-it\/","title":{"rendered":"Android sta ricevendo un&#8217;infusione di intelligenza artificiale con Gemini Nano: ecco tutto ci\u00f2 che devi sapere"},"content":{"rendered":"<p>Che si tratti di Siri, Cortana o Google Assistant, gli assistenti AI sono presenti ormai da tempo sugli smartphone. E con il rapido progresso delle tecnologie di intelligenza artificiale in ogni ambito, questi assistenti sono destinati a migliorare con il tempo.<\/p>\n<p>Il primo esempio che abbiamo \u00e8 Gemini di Google, che ha sostituito Google Assistant sugli smartphone Android come assistente AI predefinito. Mentre in precedenza Gemini era piuttosto limitato in ci\u00f2 che poteva fare rispetto a Google Assistant, Google ha recentemente annunciato importanti aggiornamenti che renderanno il chatbot incredibilmente potente e pi\u00f9 utile.<\/p>\n<p>Ci\u00f2 \u00e8 particolarmente vero per Gemini Nano, annunciato sui telefoni Pixel 8 e Samsung Galaxy S24 a gennaio. Ecco come Google intende aggiornare questo modello per renderlo ancora migliore.<\/p>\n<h2 id=\"geminis-contextual-awareness-is-getting-a-major-improvement\">La consapevolezza contestuale dei Gemelli sta ottenendo un notevole miglioramento<\/h2>\n<p>Come altri chatbot, Gemini di solito \u00e8 in grado di comprendere il contesto in cui interagisci con esso, anche se non \u00e8 sempre cos\u00ec. Ecco perch\u00e9 uno dei cambiamenti pi\u00f9 importanti in arrivo \u00e8 un miglioramento significativo nelle sue capacit\u00e0 di consapevolezza contestuale.<\/p>\n<p>Gemini ora pu\u00f2 capire facilmente cosa sta succedendo sul tuo schermo e persino l&#8217;applicazione che potresti utilizzare in un dato momento. Secondo Google, gli utenti potranno visualizzare l&#8217;overlay Gemini e utilizzare l&#8217;intelligenza artificiale mentre utilizzano contemporaneamente un&#8217;altra app. Ad esempio, puoi generare immagini con Gemini e trascinarle direttamente in Google Messaggi, Gmail o un&#8217;altra app.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"704\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/2a.20Drag20drop-1-1.webp\" title=\"\" width=\"1252\"\/><figcaption><span>Trascinare e rilasciare le immagini generate con Gemini Nano in un&#8217;altra app.<\/span> Fonte: Google<\/figcaption><\/figure>\n<p>Un altro esempio \u00e8 quando guardi un video di YouTube, puoi utilizzare la funzione &#8220;Chiedi a questo video&#8221; di Gemini per ottenere informazioni da quel video. Questo \u00e8 simile alla funzione &#8220;Chiedi a questo PDF&#8221; di Gemini Advanced che pu\u00f2 aiutarti a ottenere rapidamente informazioni da un PDF senza doverlo leggere completamente.<\/p>\n<p>Infine, ci sono suggerimenti dinamici che Gemini offrir\u00e0 controllando il tuo schermo. Ci\u00f2 pu\u00f2 accadere anche senza che tu debba digitare nulla poich\u00e9 Gemelli capir\u00e0 automaticamente il contesto di qualunque cosa tu stia lavorando.<\/p>\n<p>Ad esempio, se stai conversando in Google Messaggi su come andare a prendere un caff\u00e8, Gemini pu\u00f2 consigliarti automaticamente i migliori bar vicino a te su Google Maps.<\/p>\n<p>Gli utenti potranno presto accedere a Gemini dal suo pannello in sovrapposizione che sar\u00e0 presente anche durante la fornitura dei risultati, in modo da non doverlo aprire ogni volta in modalit\u00e0 a schermo intero.<\/p>\n<h2 id=\"gemini-nano-to-get-full-multimodal-capabilities\">Gemini Nano per ottenere funzionalit\u00e0 multimodali complete<\/h2>\n<p>Fino ad ora, Gemini si \u00e8 affidata a input testuali o vocali per comprendere la query di un utente e fornire risposte pertinenti. Ora Google sta aggiornando le sue capacit\u00e0 e lo chiama Gemini Nano con multimodalit\u00e0. Questo perch\u00e9 il modello aggiornato pu\u00f2 anche utilizzare immagini, lingue parlate e suoni per capire cosa vuole un utente.<\/p>\n<p>Si tratta di un aggiornamento enorme ma molto gradito e cambier\u00e0 drasticamente ci\u00f2 che possono fare gli smartphone con assistenti AI. Potrai utilizzare il tuo smartphone Pixel per ottenere informazioni dall&#8217;ambiente circostante attraverso la fotocamera e il microfono invece di affidarti solo al testo.<\/p>\n<h2 id=\"circle-to-search-has-been-updated-to-help-out-students\">Circle to Search \u00e8 stato aggiornato per aiutare gli studenti<\/h2>\n<p>Gi\u00e0 a gennaio, Google aveva annunciato una nuova funzionalit\u00e0 per alcuni smartphone Android: Circle To Search, che ti consente di utilizzare un semplice gesto per cercare informazioni senza uscire dall&#8217;app che stai utilizzando. Funziona con la ricerca multipla, consentendoti di utilizzare sia immagini che testo per porre a Google una domanda su qualsiasi cosa sullo schermo.<\/p>\n<p>Sin dal suo lancio, Circle To Launch \u00e8 stato aggiornato con funzionalit\u00e0 come la traduzione a schermo intero, ma alla conferenza degli sviluppatori I\/O, Google ha annunciato un altro aggiornamento. Ora pu\u00f2 aiutare gli studenti a fare i compiti aiutandoli a risolvere facilmente problemi di matematica e fisica.<\/p>\n<p>Gli studenti devono solo cerchiare il problema per cui desiderano aiuto e Gemini fornir\u00e0 loro i passaggi che devono seguire per ottenere la risposta.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"484\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/2024-05-17_13-11-21-1-.gif\" title=\"\" width=\"796\"\/><figcaption><span>Cerchia per cercare in azione.<\/span> Fonte: Google<\/figcaption><\/figure>\n<p>Google ha inoltre annunciato che Circle To Search sar\u00e0 presto in grado di aiutare a risolvere problemi complessi che coinvolgono grafici, diagrammi, formule e altro ancora. Google sta inoltre espandendo la funzionalit\u00e0 a pi\u00f9 smartphone Pixel e Samsung.<\/p>\n<h2 id=\"talkback-will-offer-better-descriptions\">Talkback offrir\u00e0 descrizioni migliori<\/h2>\n<p>Talkback \u00e8 una funzionalit\u00e0 Android progettata per aiutare le persone con disabilit\u00e0 visive spiegando cosa viene visualizzato sugli schermi dei loro smartphone. Con l&#8217;acquisizione di capacit\u00e0 multimodali da parte di Gemini Nano, Talkback sta anche diventando molto migliore nel descrivere oggetti ed elementi.<\/p>\n<p>La cosa pi\u00f9 impressionante \u00e8 che funziona anche quando il tuo dispositivo \u00e8 offline. Il modello Gemini Nano aggiornato pu\u00f2 offrire descrizioni che saranno molto simili a quelle fornite da un essere umano, rendendolo molto pi\u00f9 utile rispetto a come funziona Talkback in questo momento.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"848\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/talkback-gemini-nano-1.webp\" title=\"\" width=\"1508\"\/><figcaption><span>TalkBack ora gestito da Gemini Nano.<\/span> Fonte: Google<\/figcaption><\/figure>\n<h2 id=\"gemini-can-now-alert-you-about-scam-calls\">I Gemelli ora possono avvisarti delle chiamate truffe<\/h2>\n<p>Poich\u00e9 le protezioni antifrode sono diventate pi\u00f9 robuste nel corso degli anni, anche le chiamate fraudolente sono diventate pi\u00f9 sofisticate. Pertanto, nonostante queste protezioni, molte persone ancora non riescono a distinguere le chiamate truffa da quelle autentiche. Ecco perch\u00e9 Google sta testando una nuova funzionalit\u00e0 che consentir\u00e0 a Gemini Nano di fornire avvisi in tempo reale per la protezione dalle truffe.<\/p>\n<p>Sar\u00e0 in grado di rilevare schemi nelle conversazioni solitamente presenti nelle chiamate truffa e avvisarti immediatamente. Ad esempio, se ricevi una chiamata da qualcuno che dichiara di essere un rappresentante di banca che ti chiede di trasferire fondi o qualcosa del genere, riceverai un avviso. E poich\u00e9 si tratta di protezione integrata nel dispositivo, la tua privacy non sar\u00e0 compromessa.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"421\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/4._Scam_detection_QEJJP1Q.width-1000.format-webp-2-1.webp\" title=\"\" width=\"749\"\/><figcaption><span>Avvisi di truffe forniti da Gemini Nano.<\/span> Fonte: Google<\/figcaption><\/figure>\n<p>Gemini Nano \u00e8 stato introdotto con la serie di telefoni Pixel 8 e Samsung Galaxy S24 all&#8217;inizio di quest&#8217;anno. Si prevede che il modello aggiornato arriver\u00e0 sui telefoni Pixel entro la fine dell&#8217;anno, mentre funzionalit\u00e0 come gli avvisi di chiamate fraudolente arriveranno su tutti i dispositivi Android.<\/p>\n<p>Con questi aggiornamenti, Google rende Gemini pi\u00f9 potente e migliore nel suo ruolo di assistente virtuale che pu\u00f2 aiutarti ogni volta che ne hai bisogno. Tuttavia, la maggior parte di queste funzionalit\u00e0 sar\u00e0 limitata ai telefoni di punta, almeno per ora, quindi potremmo dover aspettare un po&#8217; di tempo per vederle su altri dispositivi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che si tratti di Siri, Cortana o Google Assistant, gli assistenti AI sono presenti ormai da tempo sugli smartphone. E con il rapido progresso delle tecnologie di intelligenza artificiale in ogni ambito, questi assistenti sono destinati a migliorare con il tempo. Il primo esempio che abbiamo \u00e8 Gemini di Google, che ha sostituito Google Assistant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,182,200],"class_list":["post-2095","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-artificial-intelligence","tag-gemini"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2095"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2095\/revisions"}],"predecessor-version":[{"id":2096,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2095\/revisions\/2096"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}