{"id":2206,"date":"2024-05-24T16:01:16","date_gmt":"2024-05-24T16:01:16","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2206"},"modified":"2024-05-24T16:01:16","modified_gmt":"2024-05-24T16:01:16","slug":"3-best-free-t9-dialer-apps-for-iphone-no-ads-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/3-best-free-t9-dialer-apps-for-iphone-no-ads-it\/","title":{"rendered":"3 migliori app dialer T9 gratuite per iPhone (senza pubblicit\u00e0)"},"content":{"rendered":"<p>La composizione T9, nota anche come Testo su 9 tasti, ti consente di trovare i contatti toccando i numeri che corrispondono alla lettera dei nomi. Standard nei vecchi telefoni con tastiera, gli iPhone non ce l&#8217;hanno. Naturalmente, puoi aprire l&#8217;app Contatti e la ricerca Spotlight funziona, ma ci\u00f2 comporta il passaggio da un&#8217;app all&#8217;altra e da un&#8217;interfaccia all&#8217;altra. Manca gravemente il dialer T9 dei telefoni pi\u00f9 vecchi, volevo ricreare un&#8217;esperienza simile su iPhone. Quindi ho testato oltre una dozzina di app dialer T9 per iPhone e ho stilato un elenco delle migliori in circolazione.<\/p>\n<h2><span id=\"Heres-How-T9-Dialing-Works\">Ecco come funziona la composizione T9<\/span><\/h2>\n<p>Prima di passare all&#8217;elenco, dai un&#8217;occhiata a come funziona la composizione T9, nel caso in cui l&#8217;hai dimenticato o non lo sai del tutto. Quando apri il tuo combinatore, troverai nove tasti (da 1 a 9). Ogni tasto numerico ha 3-4 lettere. Ad esempio, il tasto numero 2 ha le lettere A, B e C.<\/p>\n<p>Per inserire un nome, \u00e8 necessario premere il tasto numerico corrispondente alla lettera desiderata. Ad esempio, per cercare MIKE, premere 6 (per M), 4 (per I), 5 (per K) e 3 (per E). Oppure, per cercare DAD, premi 3 (per D), 2 (per A) e poi di nuovo 3 (per la seconda D).<\/p>\n<figure class=\"wp-block-image\"><img alt=\"iPhone 13 con Connessione telefonica aperta\" class=\"wp-image\" decoding=\"async\" height=\"576\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/T9-Dialer-iPhone-1024x576-1.webp\" title=\"iPhone 13 con Connessione telefonica aperta\" width=\"1024\"\/><\/figure>\n<p>Il tuo telefono fa un riferimento incrociato al numero che stai digitando (le volte in cui premi un pulsante) con la lettera corrispondente. Quindi tenta di abbinarlo a un nome nell&#8217;elenco dei contatti. Se \u00e8 un&#8217;ortografia comune, troverai rapidamente il nome del contatto. In alcuni casi, il telefono potrebbe mostrare pi\u00f9 nomi se esistono contatti con nomi uguali o simili.<\/p>\n<p><strong>Ecco perch\u00e9 devi utilizzare la composizione T9 sul tuo iPhone:<\/strong><\/p>\n<ul>\n<li>\u00c8 pi\u00f9 veloce che inserire numeri di telefono con cifre singole.<\/li>\n<li>\u00c8 pi\u00f9 comodo che aprire Contatti e cercare un contatto o scorrere un lungo elenco.<\/li>\n<li>Inoltre, la ricerca Siri e Spotlight potrebbe non trovare sempre il contatto giusto (se sono presenti pi\u00f9 contatti con lo stesso nome) e dovrai specificare il nome completo del contatto.<\/li>\n<\/ul>\n<p>Pronto a provare la composizione T9? Ecco alcune app dialer T9 tra cui puoi scegliere per il tuo iPhone. La composizione \u00e8 una procedura in due passaggi a causa delle restrizioni di iOS. Toccherai il pulsante di composizione nell&#8217;app, quindi confermerai la chiamata nel popup dell&#8217;iPhone.<\/p>\n<h2><span id=\"1-Drupe-Caller-ID-Dialer\">1. Drupe: ID chiamante e combinatore<\/span><\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Combinatore Drupe su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Drupe-0-475x1024-1.webp\" title=\"Combinatore Drupe su iPhone\" width=\"475\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Combinatore Drupe su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Drupe-1-475x1024-1.webp\" title=\"Combinatore Drupe su iPhone\" width=\"475\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Combinatore Drupe su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Drupe-2-475x1024-1.webp\" title=\"Combinatore Drupe su iPhone\" width=\"475\"\/><\/figure>\n<p>Drupe \u00e8 un&#8217;app dialer all-in-one disponibile per iPhone e Android. Offre una composizione T9 fluida insieme all&#8217;identificazione del chiamante e al supporto della chiamata rapida.<\/p>\n<p>Ottieni scorciatoie per SMS, FaceTime, WhatsApp ed e-mail, tutto dalla pagina dei contatti. Puoi anche condividere direttamente la tua posizione e aggiungere promemoria o eventi del calendario per un contatto dall&#8217;interno dell&#8217;app.<\/p>\n<p>Drupe ti aiuta anche a gestire i tuoi contatti unendo i duplicati e ti consente di personalizzare la tua esperienza con oltre 20 temi integrati. Inoltre, \u00e8 gratuito e senza pubblicit\u00e0. L&#8217;unico avvertimento: dovrai accedere con l&#8217;ID Apple o l&#8217;account Google per iniziare a utilizzare l&#8217;app.<\/p>\n<p><strong>Scarica: <a href=\"https:\/\/apps.apple.com\/us\/app\/drupe-caller-id-dialer\/id1244510953\" rel=\"noreferrer noopener\" target=\"_blank\">Drupe Dialer per iPhone<\/a><\/strong><\/p>\n<h2><span id=\"2-One-Dialer\">2. Un combinatore<\/span><\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Un Dialer con ricerca T9 su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/OneDialer-2-475x1024-1.webp\" title=\"Un Dialer con ricerca T9 su iPhone\" width=\"475\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Un Dialer con ricerca T9 su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/OneDialer-4-475x1024-1.webp\" title=\"Un Dialer con ricerca T9 su iPhone\" width=\"475\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Un Dialer con ricerca T9 su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/OneDialer-3-475x1024-1.webp\" title=\"Un Dialer con ricerca T9 su iPhone\" width=\"475\"\/><\/figure>\n<p>One Dialer \u00e8 un semplice dialer T9. Apri l&#8217;app e il dialer \u00e8 pronto per la ricerca (T9 funziona perfettamente). \u00c8 possibile scegliere tra tre diversi temi dialer: uno assomiglia al dialer dell&#8217;iPhone, l&#8217;altro assomiglia a quello di Samsung e il terzo \u00e8 un dialer con tastiera qwerty a tutti gli effetti.<\/p>\n<p>Puoi cambiare il tema dell&#8217;app in 16 colori diversi. Ti d\u00e0 anche un piacevole feedback tattile quando componi i numeri. \u00c8 gratuito senza pubblicit\u00e0.<\/p>\n<p><strong>Scarica: <a href=\"https:\/\/apps.apple.com\/us\/app\/onedialer\/id1639782094\" rel=\"noreferrer noopener\" target=\"_blank\">OneDialer per iPhone<\/a><\/strong><\/p>\n<h2><span id=\"3-T9-Speed-Dialer\">3. Chiamata rapida T9<\/span><\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Applicazione T9 Chiamata rapida su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/T9-Speed-Dial-1-475x1024-1.webp\" title=\"Applicazione T9 Chiamata rapida su iPhone\" width=\"475\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Applicazione T9 Chiamata rapida su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/T9-Speed-Dial-2-475x1024-1.webp\" title=\"Applicazione T9 Chiamata rapida su iPhone\" width=\"475\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"Applicazione T9 Chiamata rapida su iPhone\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/T9-speed-Dial0-3-475x1024-1.webp\" title=\"Applicazione T9 Chiamata rapida su iPhone\" width=\"475\"\/><\/figure>\n<p>T9 Speed \u200b\u200bDialer consiste nella composizione rapida di un contatto. Quando apri l&#8217;app, vedrai l&#8217;elenco dei contatti nella schermata principale, con il tastierino in basso. Puoi scorrere l&#8217;elenco o toccare i numeri sul dialer per eseguire una ricerca T9. C&#8217;\u00e8 anche una comoda scorciatoia per aggiungere un nuovo contatto in questa schermata.<\/p>\n<p>Speed \u200b\u200bDialer pu\u00f2 mostrare gli avatar dei contatti e puoi abilitare\/disabilitare i suoni della tastiera. \u00c8 un&#8217;app senza pubblicit\u00e0 e non richiede abbonamento o pacchetto premium. C&#8217;\u00e8 un&#8217;accurata nota sulla privacy nelle impostazioni che promette che l&#8217;app non condivide i dati dei tuoi contatti con nessuno.<\/p>\n<p><strong>Scarica: <a href=\"https:\/\/apps.apple.com\/us\/app\/t9-speed-dialer\/id1088249271\" rel=\"noreferrer noopener\" target=\"_blank\">Dialer T9 veloce per iPhone<\/a><\/strong><\/p>\n<h2><span id=\"Dial-in-a-Flash\">Componi in un lampo<\/span><\/h2>\n<p>Le app di composizione di cui sopra dovrebbero semplificarti la ricerca e la composizione rapida dei contatti. Oltre a quelle sopra, ho trovato anche altre due app dialer T9 per iPhone degne di nota:<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/apps.apple.com\/us\/app\/t9-dialer\/id1104916319\">T9 Dialer<\/a> :<\/strong> vanta un&#8217;interfaccia intuitiva, ma la versione gratuita visualizza annunci pubblicitari.<\/li>\n<li><strong><a href=\"https:\/\/apps.apple.com\/us\/app\/t9-dial\/id1401820281\" rel=\"noreferrer noopener\" target=\"_blank\">Quadrante T9<\/a> :<\/strong> hai un tastierino numerico con una sola mano e opzioni di scorrimento personalizzabili, ma \u00e8 pieno di pubblicit\u00e0.<\/li>\n<\/ul>\n<p>E per coloro che si chiedono perch\u00e9 il dialer del tuo iPhone ha delle lettere sui tasti numerici anche se non puoi cercare i contatti utilizzandoli, la ragione \u00e8 semplice: molte aziende utilizzano numeri di telefono che compongono parole o frasi. Ad esempio, un&#8217;azienda idraulica potrebbe avere il numero 1-800-PLUMBER (1-800-758-6237). Le lettere sul tastierino facilitano la memorizzazione del numero associandolo alle lettere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La composizione T9, nota anche come Testo su 9 tasti, ti consente di trovare i contatti toccando i numeri che corrispondono alla lettera dei nomi. Standard nei vecchi telefoni con tastiera, gli iPhone non ce l&#8217;hanno. Naturalmente, puoi aprire l&#8217;app Contatti e la ricerca Spotlight funziona, ma ci\u00f2 comporta il passaggio da un&#8217;app all&#8217;altra e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[65,17,71,18],"class_list":["post-2206","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-apps","tag-ios","tag-ios-17","tag-iphone"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2206\/revisions"}],"predecessor-version":[{"id":2207,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2206\/revisions\/2207"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}