{"id":2214,"date":"2024-05-25T06:48:36","date_gmt":"2024-05-25T06:48:36","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2214"},"modified":"2024-05-25T06:48:36","modified_gmt":"2024-05-25T06:48:36","slug":"cant-type-in-windows-11-search-bar-try-these-7-fixes-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/cant-type-in-windows-11-search-bar-try-these-7-fixes-it\/","title":{"rendered":"Non riesci a digitare nella barra di ricerca di Windows 11? Prova queste 7 soluzioni"},"content":{"rendered":"<p>Frustrato da una barra di ricerca di Windows che non risponde? Non sei solo. Questa guida offre soluzioni per correggere la barra di ricerca e farla funzionare di nuovo.<\/p>\n<h2><span id=\"Flowchart\">Diagramma di flusso<\/span><\/h2>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"222\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/flowchart-1-1024x222-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<h2><span id=\"Possible-Reasons\">Possibili ragioni<\/span><\/h2>\n<ul>\n<li><strong>Dati di ricerca danneggiati:<\/strong> bug o file di sistema corrotti possono portare a dati di ricerca danneggiati che possono quindi influire sulla funzionalit\u00e0 della barra di ricerca.<\/li>\n<li><strong>Servizio di ricerca di Windows non in esecuzione:<\/strong> il servizio in background responsabile della funzionalit\u00e0 di ricerca potrebbe essere disabilitato o interrotto in modo imprevisto. \u00c8 facile riavviarlo.<\/li>\n<li><strong>File di sistema danneggiati:<\/strong> i file di sistema di Windows associati alla barra di ricerca potrebbero essere danneggiati o persi.<\/li>\n<li><strong>Processo CTFMON non in esecuzione:<\/strong> \u00e8 responsabile dell&#8217;immissione di testo in Windows. Se non \u00e8 in esecuzione, non sarai in grado di digitare nella barra di ricerca. Ancora una volta, \u00e8 facile riavviare se interrotto.<\/li>\n<li><strong>Versione o driver di Windows obsoleti:<\/strong> mantieni sempre aggiornati il \u200b\u200bsistema operativo Windows e i driver. Non solo proteggono i PC, ma risolvono anche bug e aggiungono nuove funzionalit\u00e0.<\/li>\n<\/ul>\n<h2><span id=\"1-Check-for-Obvious-Problems\">1. Verificare la presenza di problemi evidenti<\/span><\/h2>\n<ul>\n<li>Assicurati che la tastiera funzioni su un altro PC. Se non hai un PC a portata di mano, prova <a href=\"https:\/\/keyboardchecker.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">il sito Keyboard Checker<\/a> .<\/li>\n<li>Fare clic sulla barra di ricerca per verificare se il cursore lampeggia. In caso contrario, fare di nuovo clic per riorientarlo.<\/li>\n<li>Controlla se ci sono aggiornamenti del sistema operativo Windows in sospeso e, in caso affermativo, esegui l&#8217;installazione.<\/li>\n<\/ul>\n<h2><span id=\"2-Restart-Windows-Explorer-and-Windows-Search\">2. Riavviare Esplora risorse e Ricerca di Windows<\/span><\/h2>\n<p>Il riavvio di Esplora risorse aggiorner\u00e0 la barra di ricerca.<\/p>\n<ol>\n<li>Premi <strong>il tasto Windows+Maiusc+Esc<\/strong> per aprire Task Manager.<\/li>\n<li>Utilizza Cerca in alto per trovare <strong>Explorer<\/strong> . Fare clic con il tasto destro su <strong>Esplora risorse<\/strong> e selezionare <strong>Riavvia<\/strong> .<\/li>\n<\/ol>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"601\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Cant-Type-in-Windows-11-Search-Bar-1-1024x601-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<p>Se il problema persiste, <a href=\"https:\/\/learn.microsoft.com\/en-us\/troubleshoot\/windows-client\/shell-experience\/fix-problems-in-windows-search\" rel=\"noreferrer noopener\" target=\"_blank\">Microsoft consiglia<\/a> di riavviare Windows Search.<\/p>\n<ol>\n<li>Per fare ci\u00f2, ripeti <strong>i passaggi 1 e 2<\/strong> sopra ma invece di riavviare Esplora risorse, questa volta cerca <strong>Cerca<\/strong> . Potresti trovarlo nell&#8217;indicizzatore di ricerca di Microsoft Windows.<\/li>\n<li>Fare clic con il tasto destro su di esso e selezionare <strong>Termina attivit\u00e0<\/strong> . Conferma se richiesto.<\/li>\n<li>Il servizio dovrebbe riavviarsi automaticamente. In caso contrario, riavvia il computer.<\/li>\n<\/ol>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"646\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Cant-Type-in-Windows-11-Search-Bar-6-1024x646-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<h2><span id=\"3-Run-Search-and-Index-Troubleshooter\">3. Eseguire lo strumento di risoluzione dei problemi di ricerca e indice<\/span><\/h2>\n<p>Il sistema operativo Windows dispone di alcuni strumenti di risoluzione dei problemi integrati per i problemi comuni che gli utenti potrebbero riscontrare. Questo \u00e8 uno di loro.<\/p>\n<ol>\n<li>Premi il <strong>tasto Windows + I<\/strong> per aprire <strong>Impostazioni<\/strong> e vai a <strong>Privacy e sicurezza &gt; Ricerca in Windows<\/strong> .<\/li>\n<li>Fai clic su <strong>Risoluzione dei problemi dell&#8217;indicizzatore<\/strong> in basso.<\/li>\n<li>Seleziona <strong>Impossibile avviare una ricerca o visualizzare i risultati<\/strong> e fare clic su <strong>Avanti<\/strong> .<\/li>\n<\/ol>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"585\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Cant-Type-in-Windows-11-Search-Bar-4-1024x585-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<h2><span id=\"4-Restart-Windows-Search-and-Windows-Font-Cache-Service\">4. Riavviare Windows Search e il servizio cache dei caratteri di Windows<\/span><\/h2>\n<p><a href=\"https:\/\/learn.microsoft.com\/en-us\/dotnet\/framework\/windows-services\/introduction-to-windows-service-applications\" rel=\"noreferrer noopener\" target=\"_blank\">Servizi Windows<\/a> ti consente di visualizzare e gestire i servizi in background sul tuo PC Windows. Avvia, interrompi o modifica la modalit\u00e0 di esecuzione per risolvere problemi, ottimizzare le prestazioni o gestire la sicurezza. Troppo tecnico? Basta seguire i semplici passaggi riportati di seguito.<\/p>\n<ol>\n<li>Premi <strong>il tasto Windows<\/strong> , cerca <strong>Servizi<\/strong> e aprilo.<\/li>\n<li>Trova <strong>Windows Search<\/strong> , fai clic con il pulsante destro del mouse su di esso e seleziona l&#8217;opzione <strong>Riavvia<\/strong> .<\/li>\n<li>Trova <strong>la cache dei caratteri di Windows<\/strong> successivamente e di nuovo, fai clic con il pulsante destro del mouse e seleziona l&#8217;opzione <strong>Riavvia<\/strong> .<\/li>\n<\/ol>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"621\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Cant-Type-in-Windows-11-Search-Bar-2-1024x621-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<h2><span id=\"5-Rebuild-Search-Index\">5. Ricostruisci l&#8217;indice di ricerca<\/span><\/h2>\n<p>Un indice di ricerca obsoleto e danneggiato pu\u00f2 generare risultati di ricerca errati o lenti. Poich\u00e9 questa funzionalit\u00e0 \u00e8 correlata alla barra di ricerca, \u00e8 necessario ricostruire l&#8217;indice manualmente.<\/p>\n<ol>\n<li>Premere il <strong>tasto Windows + R<\/strong> per aprire la <strong>finestra di dialogo Esegui<\/strong> . Digitare <strong>control \/name Microsoft.IndexingOptions<\/strong> e premere <strong>Invio<\/strong> .<\/li>\n<li>Nella finestra <strong>Opzioni di indicizzazione<\/strong> , fai clic sul pulsante <strong>Avanzate<\/strong> .<\/li>\n<li>Nella sezione Risoluzione dei problemi, fai clic sul pulsante <strong>Ricostruisci<\/strong> accanto all&#8217;opzione Elimina e ricostruisci indice.<\/li>\n<\/ol>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"805\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Cant-Type-in-Windows-11-Search-Bar-5.webp\" title=\"\" width=\"747\"\/><\/figure>\n<h2><span id=\"6-Run-the-CTFMON-Process\">6. Eseguire il processo CTFMON<\/span><\/h2>\n<p>Il processo CTFMON agisce come un vigile urbano dietro le quinte per la digitazione in Windows. Gestisce sia l&#8217;input vocale che quello di testo. Se questo processo non \u00e8 in esecuzione, la barra di ricerca non accetter\u00e0 alcun carattere digitato. Ecco come riavviarlo manualmente.<\/p>\n<p>Premi il <strong>tasto Windows + R<\/strong> per avviare la <strong>finestra di dialogo Esegui.<\/strong> Digita <strong>ctfmon.exe<\/strong> e premi <strong>Invio<\/strong> .<\/p>\n<h2><span id=\"7-Run-SFC-and-DISM-Scan\">7. Eseguire la scansione SFC e DISM<\/span><\/h2>\n<p>Windows dispone di strumenti integrati, SFC (System File Checker) e DISM (Deployment Image Servicing and Management), per scansionare e correggere i file di sistema corrotti. Ecco come usarli (ricorda che avrai bisogno di una connessione Internet):<\/p>\n<ol>\n<li>Apri il prompt dei comandi con i privilegi di amministratore sul tuo PC.<\/li>\n<li>Digita il seguente comando e premi Invio:<\/li>\n<\/ol>\n<p> <code> <code>DISM.exe \/Online \/Cleanup-image \/Restorehealth<\/code><\/code> <code> <code>sfc \/scannow<\/code><\/code><\/p>\n<p>Esistono altri modi per trovare ci\u00f2 che stai cercando su Windows. Preferisco usare i <a href=\"https:\/\/github.com\/microsoft\/PowerToys\" rel=\"noreferrer noopener\" target=\"_blank\">PowerToys<\/a> . \u00c8 un&#8217;app open source e gratuita che potenzier\u00e0 il tuo sistema operativo e funzionalit\u00e0 uniche e divertenti. Uno di questi \u00e8 la ricerca universale che appare istantaneamente, ovunque, quando premi la scorciatoia da tastiera Windows+Barra spaziatrice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frustrato da una barra di ricerca di Windows che non risponde? Non sei solo. Questa guida offre soluzioni per correggere la barra di ricerca e farla funzionare di nuovo. Diagramma di flusso Possibili ragioni Dati di ricerca danneggiati: bug o file di sistema corrotti possono portare a dati di ricerca danneggiati che possono quindi influire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[232,6,7,9],"class_list":["post-2214","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-search-bar","tag-troubleshooting","tag-windows","tag-windows-11"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2214"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2214\/revisions"}],"predecessor-version":[{"id":2215,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2214\/revisions\/2215"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}