{"id":2332,"date":"2024-05-31T07:20:04","date_gmt":"2024-05-31T07:20:04","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2332"},"modified":"2024-05-31T07:20:04","modified_gmt":"2024-05-31T07:20:04","slug":"how-to-change-font-size-only-in-text-messages-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-change-font-size-only-in-text-messages-it\/","title":{"rendered":"Come modificare la dimensione del carattere solo nei messaggi di testo"},"content":{"rendered":"<p>Sia Android che iOS offrono modi semplici per modificare la dimensione complessiva del carattere dell&#8217;interfaccia utente. Ma potresti voler modificare la dimensione del carattere solo per i messaggi di testo. Per fortuna, puoi ingrandire o ridurre il testo nell&#8217;app Messaggi lasciando il resto dell&#8217;interfaccia utente cos\u00ec com&#8217;\u00e8. Ecco come.<\/p>\n<h2>Modificare la dimensione del carattere dei messaggi di testo su Android<\/h2>\n<p><strong>Apri qualsiasi chat<\/strong> nell&#8217;app Messaggi del tuo telefono. Quindi, <strong>utilizza il gesto di pizzicare<\/strong> per modificare la dimensione del carattere. Cio\u00e8, pizzica usando due dita per diminuire la dimensione del carattere e pizzica sullo schermo per aumentare la dimensione del carattere.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"706\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Android-messages-make-text-font-size-smaller.webp\" title=\"\" width=\"320\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"706\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/Android-messages-change-text-font-size.webp\" title=\"\" width=\"320\"\/><\/figure>\n<p>Alcune cose da notare:<\/p>\n<ul>\n<li>La dimensione del carattere selezionata verr\u00e0 applicata a tutte le chat nell&#8217;app Messaggi e rimarr\u00e0 tale finch\u00e9 non cambierai nuovamente la dimensione del carattere.<\/li>\n<li>Questo metodo funziona sia con le app Google che con quelle Samsung Messaggi.<\/li>\n<li>Se <strong>non puoi utilizzare il gesto<\/strong> nell&#8217;app Google Messaggi, tocca l&#8217; <strong>immagine del profilo &gt; Impostazioni Messaggi<\/strong> . Abilita l&#8217;interruttore accanto a <strong>Pizzica per ingrandire il testo della conversazione<\/strong> .<\/li>\n<li>Se la dimensione del carattere non cambia secondo le tue esigenze, dovresti provare prima a cambiare il carattere del dispositivo.<\/li>\n<\/ul>\n<h2>Modifica la dimensione del carattere dei messaggi di testo su iPhone<\/h2>\n<p>Su iPhone, puoi modificare la dimensione del carattere di qualsiasi app supportata dal Centro di controllo utilizzando il riquadro di testo come mostrato di seguito.<\/p>\n<p><strong>1.<\/strong> Apri l&#8217; <strong>app Messaggi<\/strong> sul tuo iPhone.<\/p>\n<p><strong>2.<\/strong> Ora apri <strong>Centro di controllo<\/strong> e tocca l&#8217; <strong>icona aA.<\/strong> Se non \u00e8 presente, vai su <strong>Impostazioni iPhone &gt; Centro di controllo<\/strong> e tocca l&#8217; <strong>icona verde pi\u00f9<\/strong> accanto a Dimensioni testo per aggiungerlo al Centro di controllo. Una volta aggiunto, toccalo dal Centro di controllo.<\/p>\n<p><strong>3.<\/strong> Tocca <strong>Solo Messaggi<\/strong> e <strong>scorri verso l&#8217;alto o verso il basso il cursore<\/strong> per aumentare o diminuire la dimensione del carattere nell&#8217;app Messaggi. Quindi, tocca un punto qualsiasi dello spazio vuoto e torna all&#8217;app Messaggi. Vedrai che la dimensione del testo \u00e8 cambiata solo nell&#8217;app Messaggi di iPhone.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"567\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/iPhone-control-center-text-size.webp\" title=\"\" width=\"320\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"567\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/iPhone-control-center-text-size-change-for-messages.webp\" title=\"\" width=\"320\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"567\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/05\/iPhone-change-text-messages-font-size.webp\" title=\"\" width=\"320\"\/><\/figure>\n<p>Alcune cose da notare:<\/p>\n<ul>\n<li>Per ripristinare la dimensione del carattere originale, ripetere i passaggi precedenti e selezionare la dimensione del carattere originale.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sia Android che iOS offrono modi semplici per modificare la dimensione complessiva del carattere dell&#8217;interfaccia utente. Ma potresti voler modificare la dimensione del carattere solo per i messaggi di testo. Per fortuna, puoi ingrandire o ridurre il testo nell&#8217;app Messaggi lasciando il resto dell&#8217;interfaccia utente cos\u00ec com&#8217;\u00e8. Ecco come. Modificare la dimensione del carattere dei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,241,17,98],"class_list":["post-2332","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-fonts","tag-ios","tag-messages"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2332"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2332\/revisions"}],"predecessor-version":[{"id":2333,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2332\/revisions\/2333"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}