{"id":2622,"date":"2024-06-17T15:24:42","date_gmt":"2024-06-17T15:24:42","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2622"},"modified":"2024-06-17T15:24:42","modified_gmt":"2024-06-17T15:24:42","slug":"how-to-reset-windows-security-app-in-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-reset-windows-security-app-in-windows-11-it\/","title":{"rendered":"Come reimpostare l&#8217;app di sicurezza di Windows in Windows 11"},"content":{"rendered":"<p>L&#8217;ultima versione di Windows Security ha alcune funzionalit\u00e0 di sicurezza avanzate come Ransomware Protection e Exploit protection. Sebbene Windows Defender o l&#8217;applicazione Windows Security siano privi di bug, gli utenti possono talvolta riscontrare problemi.<\/p>\n<p>Alcuni utenti di Windows 11 hanno recentemente segnalato problemi con Microsoft Security. Gli utenti hanno affermato che l&#8217;applicazione Windows Security mostra un errore e a volte non riesce a eseguire la scansione. Quindi, se anche tu hai problemi relativi a Windows Security sul tuo Windows 11, dovresti reimpostarlo.<\/p>\n<h2><span id=\"1_Reset_Windows_Defender_via_PowerShell\"><strong>1. Ripristina Windows Defender tramite PowerShell<\/strong><\/span><\/h2>\n<p>Questo metodo utilizzer\u00e0 l&#8217;utilit\u00e0 PowerShell per reinstallare l&#8217;applicazione Windows Defender. Ecco alcuni dei semplici passaggi che devi seguire.<\/p>\n<p>1. Innanzitutto, fai clic sulla ricerca di Windows 11 e digita <strong>PowerShell<\/strong> . Successivamente, fai clic con il pulsante destro del mouse su PowerShell e seleziona <strong>Esegui come amministratore<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"PowerShell\" class=\"wp-image\" decoding=\"async\" height=\"511\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Defender-via-PowerShell-1.webp\" title=\"PowerShell\" width=\"600\"\/><\/figure>\n<p>2. Ora, nella finestra di PowerShell, digita il seguente comando e premi <strong>Invio<\/strong> .<\/p>\n<p><strong>Get-AppxPackage Microsoft.SecHealthUI -AllUsers | Reset-AppxPackage<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"digitare il seguente comando\" class=\"wp-image\" decoding=\"async\" height=\"303\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Defender-via-PowerShell-2.webp\" title=\"digitare il seguente comando\" width=\"640\"\/><\/figure>\n<p>3. Ora attendi qualche secondo fino al completamento della scansione.<\/p>\n<p>Una volta completata la parte di reinstallazione, riavvia il computer Windows 11. Dopo il riavvio, puoi eseguire Sicurezza di Windows senza problemi.<\/p>\n<h2><span id=\"2_Reset_Windows_Security_via_Settings\"><strong>2. Ripristina la sicurezza di Windows tramite Impostazioni<\/strong><\/span><\/h2>\n<p>In questo metodo, utilizzeremo l&#8217;app Impostazioni di Windows 11 per ripristinare l&#8217;applicazione Sicurezza di Windows. Ecco alcuni dei semplici passaggi che devi seguire.<\/p>\n<p>1. Innanzitutto, fai clic sul pulsante Start di Windows 11 e seleziona <strong>Impostazioni<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni\" class=\"wp-image\" decoding=\"async\" height=\"600\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Security-via-Settings-1.webp\" title=\"Impostazioni\" width=\"576\"\/><\/figure>\n<p>2. Fare clic su <strong>App<\/strong> nel riquadro sinistro dell&#8217;app <strong>Impostazioni<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Applicazioni\" class=\"wp-image\" decoding=\"async\" height=\"400\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Security-via-Settings-2.webp\" title=\"Applicazioni\" width=\"285\"\/><\/figure>\n<p>3. Sulla destra, fare clic sull&#8217;opzione <strong>App installate<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"App installate\" class=\"wp-image\" decoding=\"async\" height=\"404\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Security-via-Settings-3.webp\" title=\"App installate\" width=\"500\"\/><\/figure>\n<p>4. Nelle app installate, scorri verso il basso e trova Sicurezza di Windows. Successivamente, fai clic sui <strong>tre punti<\/strong> accanto a Sicurezza di Windows.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"tre punti\" class=\"wp-image\" decoding=\"async\" height=\"259\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Security-via-Settings-4.webp\" title=\"tre punti\" width=\"700\"\/><\/figure>\n<p>5. Dall&#8217;elenco delle opzioni visualizzato, toccare <strong>Opzioni avanzate<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Opzioni avanzate\" class=\"wp-image\" decoding=\"async\" height=\"247\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Security-via-Settings-5.webp\" title=\"Opzioni avanzate\" width=\"700\"\/><\/figure>\n<p>6. Nelle opzioni Avanzate, fare clic sul pulsante <strong>Reimposta<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Ripristina\" class=\"wp-image\" decoding=\"async\" height=\"377\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Reset-Windows-Security-via-Settings-6.webp\" title=\"Ripristina\" width=\"600\"\/><\/figure>\n<p>Ecco come reimpostare l&#8217;applicazione Sicurezza di Windows dalle Impostazioni di Windows 11.<\/p>\n<h2><span id=\"3_Reset_the_Windows_Security_App_using_CMD\"><strong>3. Reimposta l&#8217;app di sicurezza di Windows utilizzando CMD<\/strong><\/span><\/h2>\n<p>Come Powershell, puoi usare l&#8217;utilit\u00e0 Prompt dei comandi per reimpostare l&#8217;app Windows Security. Per farlo, segui i passaggi che abbiamo descritto.<\/p>\n<p>1. Digitare CMD nella ricerca di Windows 11. Quindi, fare clic con il pulsante destro del mouse su <strong>CMD<\/strong> e selezionare Esegui come amministratore.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Comando\" class=\"wp-image\" decoding=\"async\" height=\"498\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/Windows-Search-1-2.webp\" title=\"Comando\" width=\"600\"\/><\/figure>\n<p>2. Quando si apre il prompt dei comandi, incolla il comando e premi Invio.<\/p>\n<p> <code>PowerShell -ExecutionPolicy Unrestricted -Command \"&amp; {$manifest = (Get-AppxPackage *Microsoft.Windows.SecHealthUI*).InstallLocation + '\\AppxManifest.xml' ; Add-AppxPackage -DisableDevelopmentMode -Register $manifest}\"<\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"incolla il comando\" class=\"wp-image\" decoding=\"async\" height=\"415\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/06\/CMD-2.webp\" title=\"incolla il comando\" width=\"900\"\/><\/figure>\n<p>Dopo aver eseguito il comando, riavvia il PC e avvia l&#8217;app Windows Security. Ci\u00f2 reimposter\u00e0 l&#8217;app Windows Security.<\/p>\n<p>Questi sono i due modi migliori per reimpostare la sicurezza di Windows in Windows 11. Dovresti reimpostare lo strumento di sicurezza se riscontri problemi con esso. Se hai bisogno di ulteriore aiuto, faccelo sapere nei commenti qui sotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ultima versione di Windows Security ha alcune funzionalit\u00e0 di sicurezza avanzate come Ransomware Protection e Exploit protection. Sebbene Windows Defender o l&#8217;applicazione Windows Security siano privi di bug, gli utenti possono talvolta riscontrare problemi. Alcuni utenti di Windows 11 hanno recentemente segnalato problemi con Microsoft Security. Gli utenti hanno affermato che l&#8217;applicazione Windows Security mostra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-2622","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2622"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2622\/revisions"}],"predecessor-version":[{"id":2623,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2622\/revisions\/2623"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}