{"id":268,"date":"2023-12-06T19:21:17","date_gmt":"2023-12-06T19:21:17","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=268"},"modified":"2023-12-06T19:21:17","modified_gmt":"2023-12-06T19:21:17","slug":"7-fixes-for-unable-to-copy-and-paste-in-microsoft-outlook-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/7-fixes-for-unable-to-copy-and-paste-in-microsoft-outlook-it\/","title":{"rendered":"7 correzioni per l&#8217;impossibilit\u00e0 di copiare e incollare in Microsoft Outlook"},"content":{"rendered":"<p>Con le funzionalit\u00e0 copia e incolla di <u>Microsoft Outlook<\/u>, puoi duplicare facilmente testo, immagini e altri contenuti in Outlook e altrove varie applicazioni. Ci\u00f2 non solo fa risparmiare tempo ma riduce anche la probabilit\u00e0 di errori. Tuttavia, se non riesci a fare tutto questo perch\u00e9 Outlook non copia e incolla nulla sul tuo computer Windows, questa guida contiene alcuni suggerimenti che ti aiuteranno.<\/p>\n<h2><span id=\"1-Use-Keyboard-Shortcuts\">1. Utilizza le scorciatoie da tastiera<\/span><\/h2>\n<p>Problemi temporanei con l&#8217;app Outlook a volte possono impedire il funzionamento delle opzioni di copia e incolla nel menu di scelta rapida. Puoi provare a utilizzare le scorciatoie da tastiera Ctrl + C (copia) e Ctrl + V (incolla) per verificare se funzionano correttamente. In tal caso, <u>chiudere l&#8217;app Outlook sul PC<\/u> e riaprirla dovrebbe risolvere il problema.<\/p>\n<h2><span id=\"2-Clear-the-Clipboard\">2. Cancella gli Appunti<\/span><\/h2>\n<p>Se non riesci a copiare e incollare nulla in Outlook, anche con le scorciatoie da tastiera, potrebbe esserci un problema con gli <u>appunti di Windows<\/u> . In tal caso, cancellare gli appunti dovrebbe ripristinare la normalit\u00e0.<\/p>\n<p><strong>1.<\/strong> Premi il <strong>tasto Windows + I <\/strong>per aprire l&#8217;app Impostazioni. <\/p>\n<p><strong>2.<\/strong> Nella scheda <strong>Sistema<\/strong>, fai clic su <strong> Appunti<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni degli Appunti su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"579\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Clipboard-Settings-on-Windows-11.webp\" title=\"Impostazioni degli Appunti su Windows 11\" width=\"1023\"\/><\/figure>\n<p><strong>3.<\/strong> Fai clic sul pulsante <strong>Cancella<\/strong> accanto a <strong>Cancella dati degli appunti<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cancella i dati degli Appunti su Windows 11\" class=\"wp-image\" decoding=\"async\" height=\"587\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Clear-Clipboard-Data-on-Windows-11-1024x587-1.webp\" title=\"Cancella i dati degli Appunti su Windows 11\" width=\"1024\"\/><\/figure>\n<h2><span id=\"3-Open-Outlook-in-Safe-Mode\">3. Apri Outlook in modalit\u00e0 provvisoria<\/span><\/h2>\n<p>Uno dei componenti aggiuntivi di Outlook potrebbe interrompere i processi dell&#8217;app e impedirti di copiare e incollare contenuti in Outlook. Per verificare questa possibilit\u00e0, prova ad aprire Outlook in modalit\u00e0 provvisoria. Chiudi l&#8217;app Outlook, quindi tieni premuto il tasto <strong>Ctrl<\/strong> e fai doppio clic sul collegamento di Outlook.<\/p>\n<p>Una volta aperto Outlook in modalit\u00e0 provvisoria, testa le funzionalit\u00e0 di copia e incolla. Se non riscontri problemi, puoi considerare di disabilitare tutti i componenti aggiuntivi e riattivarli uno alla volta. Ci\u00f2 dovrebbe aiutarti a determinare quale componente aggiuntivo causa il problema.<\/p>\n<p><strong>1.<\/strong> Nell&#8217;app Outlook, fai clic sul menu <strong>File<\/strong> in alto.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Menu File di Outlook su Windows\" class=\"wp-image\" decoding=\"async\" height=\"584\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Outlook-File-Menu-on-Windows.webp\" title=\"Menu File di Outlook su Windows\" width=\"944\"\/><\/figure>\n<p><strong>2.<\/strong> Seleziona <strong>Opzioni<\/strong> dal riquadro sinistro.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Opzioni di Outlook su Windows\" class=\"wp-image\" decoding=\"async\" height=\"662\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Outlook-Options-on-Windows.webp\" title=\"Opzioni di Outlook su Windows\" width=\"1011\"\/><\/figure>\n<p><strong>3.<\/strong> Passa alla scheda <strong>Componenti aggiuntivi<\/strong> e fai clic su <strong>Vai<\/strong> accanto a <strong>Componenti aggiuntivi COM<\/strong>. <\/p>\n<figure class=\"wp-block-image\"><img alt=\"Componenti aggiuntivi di Outlook su Windows\" class=\"wp-image\" decoding=\"async\" height=\"620\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Outlook-Add-ins-on-Windows.webp\" title=\"Componenti aggiuntivi di Outlook su Windows\" width=\"956\"\/><\/figure>\n<p><strong>4.<\/strong> Deseleziona le caselle per disabilitare i componenti aggiuntivi e fai clic su <strong>OK<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Disattiva i componenti aggiuntivi di Outlook su Windows\" class=\"wp-image\" decoding=\"async\" height=\"503\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Disable-Outlook-Add-Ins-on-Windows.webp\" title=\"Disattiva i componenti aggiuntivi di Outlook su Windows\" width=\"874\"\/><\/figure>\n<p>Successivamente riavvia l&#8217;app Outlook e abilita i componenti aggiuntivi uno alla volta finch\u00e9 il problema non si ripresenta. Una volta trovato il componente aggiuntivo problematico, valuta la possibilit\u00e0 di rimuoverlo.<\/p>\n<h2><span id=\"4-Run-the-Office-Repair-Tool\">4. Eseguire lo strumento di ripristino di Office<\/span><\/h2>\n<p>Microsoft include un pratico strumento di riparazione su Windows 10 e 11 per <u>risolvere problemi con le app di Office<\/u> come Outlook. Puoi provare a eseguire questo strumento per vedere se ripristina la tua capacit\u00e0 di copiare e incollare in Outlook.<\/p>\n<p><strong>1.<\/strong> Premi il <strong>tasto Windows + R<\/strong> per aprire la finestra di dialogo Esegui. Digita <strong>appwiz.cpl<\/strong> nella casella e premi <strong>Invio<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Apri la finestra Programmi e funzionalit\u00e0 su Windows\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Open-Programs-and-Features-Window-on-Windows-1-1024x500-1.webp\" title=\"Apri la finestra Programmi e funzionalit\u00e0 su Windows\" width=\"1024\"\/><\/figure>\n<p><strong>2.<\/strong> Nella finestra Programmi e funzionalit\u00e0, seleziona la suite Microsoft Office nell&#8217;elenco e fai clic su <strong>Cambia<\/strong> pulsante in alto.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Office Suite nella finestra Programmi e funzionalit\u00e0 su Windows\" class=\"wp-image\" decoding=\"async\" height=\"600\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Office-Suite-in-Programs-and-Features-Window-on-Windows.webp\" title=\"Office Suite nella finestra Programmi e funzionalit\u00e0 su Windows\" width=\"954\"\/><\/figure>\n<p><strong>3.<\/strong> Seleziona l&#8217;opzione <strong>Riparazione online<\/strong> e fai clic su <strong> Ripara<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui lo strumento di riparazione di Office su Windows\" class=\"wp-image\" decoding=\"async\" height=\"761\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Run-Office-Repair-Tool-on-Windows-1-1024x761-1.webp\" title=\"Esegui lo strumento di riparazione di Office su Windows\" width=\"1024\"\/><\/figure>\n<h2><span id=\"5-Enable-Clipboard-Access-for-Outlook-for-Web\">5. Abilita l&#8217;accesso agli appunti per Outlook (per Web)<\/span><\/h2>\n<p>Non riesci a copiare e incollare testo, immagini e allegati in Outlook per il Web? In tal caso, devi assicurarti che Outlook disponga delle autorizzazioni necessarie per accedere agli appunti. Ecco come verificare.<\/p>\n<p><strong>1.<\/strong> Apri Outlook nel tuo browser web. Fai clic sull&#8217;<strong>icona del lucchetto<\/strong> a sinistra dell&#8217;URL del sito web e seleziona <strong>Autorizzazioni per questo sito<\/strong> (Edge) o <strong>Impostazioni sito<\/strong> (Chrome).<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni del sito Outlook sui browser\" class=\"wp-image\" decoding=\"async\" height=\"596\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Outlook-Site-Settings-on-Browsers.webp\" title=\"Impostazioni del sito Outlook sui browser\" width=\"942\"\/><\/figure>\n<p><strong>2.<\/strong> Nella nuova scheda che si apre, fai clic sul menu a discesa accanto a <strong>Appunti<\/strong> per selezionare <strong>Consenti<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Abilita l'accesso agli Appunti per Outlook sul Web\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Enable-Clipboard-Access-for-Outlook-on-Web.webp\" title=\"Abilita l'accesso agli Appunti per Outlook sul Web\" width=\"928\"\/><\/figure>\n<p>Torna alla scheda Outlook e aggiornala. Successivamente, controlla se il problema persiste.<\/p>\n<h2><span id=\"6-Turn-Off-Keyboard-Shortcuts-for-Web\">6. Disattiva le scorciatoie da tastiera (per il Web)<\/span><\/h2>\n<p>Diversi utenti in un <a href=\"https:\/\/answers.microsoft.com\/en-us\/outlook_com\/forum\/all\/right-click-paste-not-working-in-outlook-365\/43a195a8-e3bc-49c0-b57a-cc62e5899ee2\" rel=\"noreferrer noopener\" target=\"_blank\">post della community Microsoft<\/a> hanno segnalato di aver risolto questo particolare problema disattivando temporaneamente le scorciatoie da tastiera in Outlook per il Web. Puoi anche provarlo.<\/p>\n<p><strong>1.<\/strong> Apri Outlook nel browser e fai clic sull&#8217;<strong>icona a forma di ingranaggio<\/strong> nell&#8217;angolo in alto a destra. <\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni di Outlook per il Web\" class=\"wp-image\" decoding=\"async\" height=\"619\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Outlook-For-the-Web-Settings.webp\" title=\"Impostazioni di Outlook per il Web\" width=\"820\"\/><\/figure>\n<p><strong>2.<\/strong> Vai a <strong>Generale &gt; Accessibilit\u00e0<\/strong> e seleziona l&#8217;opzione <strong>Disattiva scorciatoie da tastiera<\/strong>. Quindi, fai clic su <strong>Salva<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Disattiva le scelte rapide da tastiera in Outlook per il Web\" class=\"wp-image\" decoding=\"async\" height=\"634\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Turn-Off-Keybaord-Shortcuts-on-Outlook-for-the-Web-1024x634-1.webp\" title=\"Disattiva le scelte rapide da tastiera in Outlook per il Web\" width=\"1024\"\/><\/figure>\n<h2><span id=\"7-Clear-Browsing-Data-for-Web\">7. Cancella dati di navigazione (per il Web)<\/span><\/h2>\n<p>Se ancora non riesci a copiare e incollare in Outlook per il Web, la cache del browser esistente potrebbe essere danneggiata. Puoi provare a sbarazzarti di questi dati per vedere se questo aiuta.<\/p>\n<p>Se utilizzi Chrome o Edge, premi <strong>Ctrl + Maiusc + Canc<\/strong> sulla tastiera per aprire il pannello Cancella dati di navigazione. Seleziona <strong>Tutto il tempo<\/strong> nell&#8217;opzione <strong>Intervallo di tempo<\/strong>. Seleziona la casella che dice <strong>Immagini e file memorizzati nella cache<\/strong> e premi <strong>Cancella ora<\/strong> pulsante.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cancella i dati della cache su Microsoft Edge\" class=\"wp-image\" decoding=\"async\" height=\"623\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Clear-Cache-Data-on-Microsoft-Edge.webp\" title=\"Cancella i dati della cache su Microsoft Edge\" width=\"995\"\/><\/figure>\n<h2><span id=\"No-More-Copy-Paste-Holdups\">Niente pi\u00f9 rallentamenti copia-incolla<\/span><\/h2>\n<p>Le funzionalit\u00e0 di copia e incolla di Outlook aiutano a migliorare la produttivit\u00e0 e a semplificare le attivit\u00e0 di creazione e modifica delle e-mail. Pertanto, pu\u00f2 essere scomodo non riuscire a copiare e incollare nulla in Outlook. Ci auguriamo che l&#8217;applicazione dei suggerimenti sopra riportati ti abbia aiutato a risolvere il problema di fondo e che tu possa riprendere a lavorare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con le funzionalit\u00e0 copia e incolla di Microsoft Outlook, puoi duplicare facilmente testo, immagini e altri contenuti in Outlook e altrove varie applicazioni. Ci\u00f2 non solo fa risparmiare tempo ma riduce anche la probabilit\u00e0 di errori. Tuttavia, se non riesci a fare tutto questo perch\u00e9 Outlook non copia e incolla nulla sul tuo computer Windows, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[57,58,59,6,7],"class_list":["post-268","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-copy","tag-outlook","tag-paste","tag-troubleshooting","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=268"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/268\/revisions"}],"predecessor-version":[{"id":269,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/268\/revisions\/269"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}