{"id":2976,"date":"2024-07-28T08:36:54","date_gmt":"2024-07-28T08:36:54","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=2976"},"modified":"2024-07-28T08:36:54","modified_gmt":"2024-07-28T08:36:54","slug":"samsung-galaxy-z-fold-6-vs-galaxy-z-fold-5-feels-same-but-is-different-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/samsung-galaxy-z-fold-6-vs-galaxy-z-fold-5-feels-same-but-is-different-it\/","title":{"rendered":"Samsung Galaxy Z Fold 6 vs. Galaxy Z Fold 5: sembra uguale, ma \u00e8 diverso"},"content":{"rendered":"<figure class=\"wp-block-image\"><img alt=\"Confronto delle specifiche tra Samsung Galaxy Z Fold 6 e Fold 5\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-vs-Fold-5-Specs-Comparison-1024x577-1.webp\" title=\"Confronto delle specifiche tra Samsung Galaxy Z Fold 6 e Fold 5\" width=\"1024\"\/><figcaption>Sinistra \u2013 Piega 6 e Destra \u2013 Piega 5<\/figcaption><\/figure>\n<p>L&#8217;attesissimo Z Fold 6 di Samsung ha debuttato all&#8217;evento Galaxy Unpacked il 10 luglio 2024. Vanta diverse nuove funzionalit\u00e0 e aggiornamenti hardware, come un nuovo processore, un nuovo design della cerniera, un peso pi\u00f9 leggero e un sacco di nuove funzionalit\u00e0 Galaxy AI. Ma la grande domanda \u00e8: queste differenze sono abbastanza significative da farti passare dal Galaxy Z Fold 5? O aspettare il Google Pixel 9 Pro Fold, che dovrebbe arrivare il 13 agosto 2024? Analizziamolo.<\/p>\n<h2>Confronto delle specifiche di Galaxy Z Fold 6 vs Fold 5<\/h2>\n<table>\n<thead>\n<tr>\n<th data-align=\"left\">Galaxy Z Fold 6<\/th>\n<th data-align=\"left\">Galaxy Z Fold 5<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td data-align=\"left\"><strong>Display interno<\/strong><\/td>\n<td data-align=\"left\">7,6 pollici (1856 x 2160 pixel), AMOLED dinamico 2X, 120 Hz, 2600 nit (picco)<\/td>\n<td data-align=\"left\">7,6 pollici (1812 x 2176 pixel), AMOLED dinamico 2X, 120 Hz, 1750 nit (picco)<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Display esterno<\/strong><\/td>\n<td data-align=\"left\">6,3 pollici (968 x 2376 pixel), AMOLED dinamico 2X, 120 Hz, 2600 nit (picco)<\/td>\n<td data-align=\"left\">6,2 pollici (904 x 2316 pixel), AMOLED dinamico 2X, 120 Hz, 1750 nit (picco)<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Processore<\/strong><\/td>\n<td data-align=\"left\">Qualcomm Snapdragon 8 Gen 3 (4nm)<\/td>\n<td data-align=\"left\">Qualcomm Snapdragon 8 Gen 2 (4nm)<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>RAM e archiviazione<\/strong><\/td>\n<td data-align=\"left\">12 GB<\/td>\n<td data-align=\"left\">12 GB<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Magazzinaggio<\/strong><\/td>\n<td data-align=\"left\">256 GB \/ 512 GB \/ 1 TB (UFS 4.0)<\/td>\n<td data-align=\"left\">256 GB \/ 512 GB \/ 1 TB (UFS 4.0)<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Fotocamera principale<\/strong><\/td>\n<td data-align=\"left\">50 MP grandangolare, f\/1.8, 12 MP ultragrandangolare f2.2, 10 MP teleobiettivo f\/2.4 (zoom ottico 3X), PDAF, OIS<\/td>\n<td data-align=\"left\">50 MP grandangolare, f\/1.8, 12 MP ultragrandangolare f2.2, 10 MP teleobiettivo f\/2.4 (zoom ottico 3X), PDAF, OIS<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Fotocamera per selfie<\/strong><\/td>\n<td data-align=\"left\">10MP f\/2.2 (esterno), 4MP f\/1.8 (interno)<\/td>\n<td data-align=\"left\">10MP f\/2.2 (esterno), 4MP f\/1.8 (interno)<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Batteria<\/strong><\/td>\n<td data-align=\"left\">4400 mAh, velocit\u00e0 di ricarica 25 W<\/td>\n<td data-align=\"left\">4400 mAh, velocit\u00e0 di ricarica 25 W<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Peso<\/strong><\/td>\n<td data-align=\"left\">239g<\/td>\n<td data-align=\"left\">253g<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Grado di protezione IP<\/strong><\/td>\n<td data-align=\"left\">IP48<\/td>\n<td data-align=\"left\">IPX8<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Colori<\/strong><\/td>\n<td data-align=\"left\">Blu navy, Silver Shadow, Rosa, Nero, Bianco<\/td>\n<td data-align=\"left\">Blu ghiaccio, Nero fantasma, Crema, Grigio, Blu<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Prezzo<\/strong><\/td>\n<td data-align=\"left\">A partire da $ 1.899<\/td>\n<td data-align=\"left\">A partire da $ 1.799<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Prezzo e disponibilit\u00e0<\/h2>\n<p>Samsung Galaxy Z Fold 6 ti coster\u00e0:<\/p>\n<ul>\n<li><a href=\"https:\/\/amzn.to\/3SrKXQD\" rel=\"noreferrer noopener\" target=\"_blank\">$ 1.900 per il modello da 256 GB<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/3WCwGDl\">$ 2.020 per il modello da 512 GB<\/a><\/li>\n<\/ul>\n<p>In confronto, il Galaxy Z Fold 5 costa:<\/p>\n<ul>\n<li><a href=\"https:\/\/amzn.to\/3Yp5Yzh\">$ 1.800 per il modello da 256 GB<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/3WB48dj\">$ 1.920 per il modello da 512 GB<\/a><\/li>\n<\/ul>\n<p>Anche se il Galaxy Z Fold 5 sembra pi\u00f9 economico, \u00e8 comunque piuttosto costoso e per molte persone potrebbe risultare difficile procurarselo.<\/p>\n<h2>Linguaggio di progettazione leggermente nuovo<\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Confronto tra il design del Galaxy Z Fold 6 e quello del Fold 5\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Galaxy-Z-Fold-6-vs-Fold-5-Design-Comparison-1024x577-1.webp\" title=\"Confronto tra il design del Galaxy Z Fold 6 e quello del Fold 5\" width=\"1024\"\/><figcaption>Sinistra \u2013 Piega 6 e Destra \u2013 Piega 5<\/figcaption><\/figure>\n<p>Samsung non ha cambiato molto il design del Fold nel corso degli anni, ma lo Z Fold 6 \u00e8 diverso. Presenta un design simile a una lastra con una nuova cerniera Dual Rail che migliora la resistenza agli urti e riduce la piega dello schermo.<\/p>\n<p>Parlando della piega, \u00e8 meno evidente sul Fold 6 rispetto al Fold 5. \u00c8 ancora l\u00ec in certi angoli, ma \u00e8 meno percettibile al tatto. Amiamo la finitura opaca sui lati del Fold 6, che lo rende pi\u00f9 attraente e meno soggetto alle impronte digitali rispetto al Fold 5 lucido.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Differenza di piega tra Samsung Fold 6 e Fold 5\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Fold-6-vs-Fold-5-Crease-Difference-1024x577-1.webp\" title=\"Differenza di piega tra Samsung Fold 6 e Fold 5\" width=\"1024\"\/><figcaption>Sinistra \u2013 Piega 6 e Destra \u2013 Piega 5<\/figcaption><\/figure>\n<p>Il fattore di forma del telefono rimane alto e stretto, cosa che molti utenti hanno criticato. Samsung potrebbe prendere spunto dal Google Pixel Fold e dal libro di OnePlus Open, che hanno schermi di copertura pi\u00f9 ampi. Nonostante piccole modifiche nelle dimensioni, Fold 6 \u00e8 pi\u00f9 leggero di Fold 5 di 14 grammi, il che lo rende quasi leggero quanto iPhone 14 Pro Max (240 g).<\/p>\n<p>Fold 6 vanta anche la classificazione IP48, il che significa che \u00e8 resistente all&#8217;acqua e alla polvere, un passo avanti rispetto a Fold 5, che era solo resistente all&#8217;acqua.<\/p>\n<p>Nel frattempo, Fold 5 \u00e8 disponibile nei colori Crema, Nero Fantasma e Blu Ghiaccio, mentre Blu e Grigio sono disponibili in esclusiva sul sito web di Samsung.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Samsung Galaxy Z Fold 6 colori\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-Colors-2-1024x577-1.webp\" title=\"Samsung Galaxy Z Fold 6 colori\" width=\"1024\"\/><figcaption>Galaxy Z Fold 6 colori<\/figcaption><\/figure>\n<h2>Come si confronta il display<\/h2>\n<p>Il Fold 6 ha dimensioni leggermente pi\u00f9 grandi, con uno schermo di copertura da 6,3 pollici rispetto allo schermo da 6,2 pollici del Fold 5. Anche la risoluzione \u00e8 aumentata a 968 x 2376 pixel rispetto ai 904 x 2316 pixel del Fold 5.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Confronto display Galaxy Z Fold 6 vs Fold 5\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Galaxy-Z-Fold-6-vs-Fold-5-Display-Comparison-1024x577-1.webp\" title=\"Confronto display Galaxy Z Fold 6 vs Fold 5\" width=\"1024\"\/><figcaption>Sinistra \u2013 Piega 6 e Destra \u2013 Piega 5<\/figcaption><\/figure>\n<p>Il display principale rimane uno schermo da 7,6 pollici ma con un leggero cambiamento di risoluzione. Il Fold 6 ha 1856 x 2160 pixel, mentre il Fold 5 ha 1812 x 2176 pixel.<\/p>\n<p>Il Fold 6 brilla con una luminosit\u00e0 massima di 2600 nit, rispetto ai 1750 nit del Fold 5. Quindi, guardare i tuoi programmi e film preferiti sullo schermo del Fold 6 \u00e8 ancora pi\u00f9 vivido e piacevole, anche in ambienti esterni luminosi. Entrambi i modelli sono dotati di LTPO AMOLED 2X, 120 Hz e Corning Gorilla Glass Victus 2 (Cover Display). Inoltre, la tua S Pen del Fold 5 \u00e8 compatibile con il Fold 6.<\/p>\n<h2>Com&#8217;\u00e8 la prestazione?<\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Confronto benchmark tra Samsung Fold 6 e Fold 5\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Benchmark-comparison-between-Samsung-Fold-6-and-Fold-5-1024x577-1.webp\" title=\"Confronto benchmark tra Samsung Fold 6 e Fold 5\" width=\"1024\"\/><figcaption>Sinistra \u2013 Piega 6 e Destra \u2013 Piega 5<\/figcaption><\/figure>\n<p>Sotto il cofano, Fold 6 racchiude l&#8217;ultimo chipset Snapdragon 8 Gen 3, ottimizzato per i dispositivi Galaxy, apparso per la prima volta nella gamma Galaxy S24. Ecco come si colloca nei benchmark:<\/p>\n<table>\n<thead>\n<tr>\n<th data-align=\"left\">Galaxy Z Fold 6<\/th>\n<th data-align=\"left\">Galaxy Z Fold 5<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td data-align=\"left\"><strong>Antutu 10.2.9<\/strong><\/td>\n<td data-align=\"left\">1.641.860<\/td>\n<td data-align=\"left\">1.512.396<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Geekbench 6.3 (singolo core)<\/strong><\/td>\n<td data-align=\"left\">2152<\/td>\n<td data-align=\"left\">2054<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Geekbench 6.3 (multi-core)<\/strong><\/td>\n<td data-align=\"left\">6794<\/td>\n<td data-align=\"left\">5409<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>GPU Geekbench 6.3<\/strong><\/td>\n<td data-align=\"left\">14074<\/td>\n<td data-align=\"left\">9517<\/td>\n<\/tr>\n<tr>\n<td data-align=\"left\"><strong>Marchio 3D (Wild Life Extreme)<\/strong><\/td>\n<td data-align=\"left\">Punteggio: 4683FPS medio: 28.05<\/td>\n<td data-align=\"left\">Punteggio: 3868FPS medio: 23.17<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Come potete vedere, il nuovo processore Snapdragon 8 Gen 3 supera le prestazioni dello Snapdragon 8 Gen 2 in tutti i test di benchmark che abbiamo eseguito.<\/p>\n<p>Quest&#8217;anno, il nuovo Fold 6 ha una camera di vapore 1,6 volte pi\u00f9 grande di quella del Fold 5, che dovrebbe aiutare con la gestione del calore. Per testarlo, abbiamo giocato a giochi ad alta richiesta come PUBG Mobile per circa 30 minuti, con impostazioni grafiche su HDR, frame rate estremo, anti-aliasing a 4x e luminosit\u00e0 al 50%. Sorprendentemente, le temperature medie di entrambi i telefoni pieghevoli erano comprese tra 33,7 \u00b0C e 34,8 \u00b0C. Ci aspettavamo un miglioramento significativo nel controllo del calore, ma la differenza era appena percettibile.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Misurazione della temperatura del Galaxy Z Fold 6 e Fold 5 dopo il gioco\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Measuring-Galaxy-Z-Fold-6-and-Fold-5-temperature-after-gaming-1024x577-1.webp\" title=\"Misurazione della temperatura del Galaxy Z Fold 6 e Fold 5 dopo il gioco\" width=\"1024\"\/><\/figure>\n<p>Per riassumere, il chipset Gen 3 \u00e8 sicuramente un processore leggermente pi\u00f9 potente del Gen 2, ma state tranquilli, non noterete alcun intoppo nelle prestazioni dello Z Fold 5 nell&#8217;uso quotidiano. Ma se volete l&#8217;ultimo e il migliore, scegliete il Fold 6.<\/p>\n<h2>Le fotocamere sono migliori di Z Fold 5?<\/h2>\n<figure class=\"wp-block-image\"><img alt=\"Confronto tra le fotocamere del Galaxy Z Fold 6 e del Fold 5\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Galaxy-Z-Fold-6-vs-Fold-5-Camera-Comparison-1024x577-1.webp\" title=\"Confronto tra le fotocamere del Galaxy Z Fold 6 e del Fold 5\" width=\"1024\"\/><figcaption>Sinistra \u2013 Piega 5 e Destra \u2013 Piega 6<\/figcaption><\/figure>\n<p>Il Fold 6 sfoggia un nuovo design della fotocamera con un anello nero, ma le specifiche della fotocamera rimangono sostanzialmente le stesse, fatta eccezione per la fotocamera ultrawide, che ora supporta la registrazione video 4K HDR a 60 fps e una migliore fotografia in condizioni di scarsa illuminazione. Ecco un rapido confronto tra la fotocamera del Samsung Galaxy Z Fold 6 e quella del Fold 5.<\/p>\n<p><strong>Fotocamera principale<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Fotocamera principale da 50 MP\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-vs-Fold-5-50-MP-Main-Camera-1024x640-1.webp\" title=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Fotocamera principale da 50 MP\" width=\"1024\"\/><\/figure>\n<p>A prima vista non c&#8217;\u00e8 molta differenza, ma se guardi attentamente, vedrai che lo Z Fold 6 cattura meglio le nuvole, mentre il Fold 5 le rende appena visibili. Inoltre, le ombre sul Fold 5 sono un po&#8217; aggressive, con conseguente perdita di dettagli.<\/p>\n<p><strong>Ritratto Scattato<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Fotocamera principale per ritratti\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-vs-Fold-5-Portrait-Main-Camera-1024x640-1.webp\" title=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Fotocamera principale per ritratti\" width=\"1024\"\/><\/figure>\n<p>L&#8217;effetto bokeh (sfocatura dello sfondo) \u00e8 venuto bene su entrambi i dispositivi. Tuttavia, i dettagli sui jeans del mio collega sono pi\u00f9 morbidi sul Fold 5, mentre il Fold 6 mantiene la consistenza e il contrasto.<\/p>\n<p><strong>Ritratto Selfie<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Ritratto Selfie\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-vs-Fold-5-Portrait-Selfie-1024x640-1.webp\" title=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Ritratto Selfie\" width=\"1024\"\/><\/figure>\n<p>Quando ho scattato un selfie in modalit\u00e0 ritratto, era difficile distinguere tra le due immagini. Il rilevamento dei bordi, la precisione del colore, il tono della pelle e la texture erano perfetti. Qui \u00e8 un pareggio.<\/p>\n<p><strong>Riprese con zoom<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Foto Zoom\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-vs-Fold-5-Zoom-Photos-878x1024-1.webp\" title=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Foto Zoom\" width=\"878\"\/><\/figure>\n<p>Poi abbiamo testato il teleobiettivo 3x dedicato in pieno giorno. Le immagini sono venute decenti su entrambi i telefoni, ma nessuno dei due \u00e8 stato eccezionale. Con uno zoom out a 30x, entrambi i telefoni sono riusciti a elaborare l&#8217;immagine e a fornire un testo chiaro.<\/p>\n<p><strong>Ripresa notturna<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Modalit\u00e0 notturna\" class=\"wp-image\" decoding=\"async\" height=\"640\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Samsung-Galaxy-Z-Fold-6-vs-Fold-5-Night-Mode-1024x640-1.webp\" title=\"Samsung Galaxy Z Fold 6 vs Fold 5 - Modalit\u00e0 notturna\" width=\"1024\"\/><\/figure>\n<p>C&#8217;erano lavori in corso nella nostra zona, quindi ho scattato qualche foto a caso. Entrambi i telefoni hanno fatto un lavoro fenomenale, mostrando persino il riflesso di un albero su un vetro di un ufficio. Tuttavia, in altre aree, Fold 5 manca chiaramente di alcuni dettagli chiave. Ad esempio, l&#8217;immagine \u00e8 un po&#8217; morbida e leggermente sovraesposta. Puoi vedere i dettagli mancanti nella seconda immagine, dove persino il testo sul cancello di latta blu \u00e8 sfocato.<\/p>\n<p><strong>Considerazioni generali sulla fotocamera<\/strong><\/p>\n<p>Le fotocamere del Galaxy Z Fold 6 e del Fold 5 sono piuttosto simili. Il Fold 6 ha alcuni bei miglioramenti, come scatti in condizioni di scarsa illuminazione e scatti HDR migliori. Tuttavia, questi miglioramenti non sono abbastanza significativi da giustificare un aggiornamento solo per la fotocamera.<\/p>\n<h2>Come sono le prestazioni della batteria?<\/h2>\n<p>La capacit\u00e0 della batteria del Galaxy Z Fold 6 rimane la stessa da 4.400 mAh del suo predecessore. Ma c&#8217;\u00e8 qualche miglioramento nella durata della batteria dato che Samsung sta utilizzando il nuovo Snapdragon 8 Gen 3, che si dice sia pi\u00f9 efficiente dal punto di vista energetico rispetto al Gen 2? Scopriamolo.<\/p>\n<ul>\n<li>Guardando video 4K per 30 minuti: entrambi hanno perso il 5% di batteria.<\/li>\n<li>Giocando a PUBG Mobile per 1 ora: Fold 6 ha perso il 14% di batteria, mentre Fold 5 ne ha persa il 19%.<\/li>\n<li>Registrazione di video 8K e foto diurne per 15 minuti: entrambi hanno perso il 6% della batteria.<\/li>\n<\/ul>\n<p>E la velocit\u00e0 di ricarica? Samsung continua a usare la ricarica cablata da 25 W. Abbiamo testato entrambi i dispositivi e ci sono voluti 32:45 minuti per passare dal 30% all&#8217;80%. Speravamo nel supporto alla ricarica da 45 W quest&#8217;anno, ma sembra che dovremo aspettare ancora un po&#8217;.<\/p>\n<h2>Quali software e caratteristiche speciali offre?<\/h2>\n<p>Con la serie Galaxy S24, abbiamo avuto modo di conoscere la Galaxy AI di Samsung, ricca di funzionalit\u00e0 come Circle to Search, Live Translate, Generative Edit e Chat Assist. Queste sono state poi implementate nel Galaxy Z Fold 5. Fortunatamente, Samsung non ha semplicemente riciclato le stesse funzionalit\u00e0 AI per lo Z Fold 6. Invece, ha aggiunto un sacco di nuovi strumenti AI:<\/p>\n<ul>\n<li><strong>Sketch to Image:<\/strong> come suggerisce il nome, disegni un&#8217;immagine e l&#8217;intelligenza artificiale generativa di Samsung la porta in vita. I risultati possono essere un successo o un fallimento, ma \u00e8 uno strumento divertente con cui giocare, soprattutto per i bambini.<\/li>\n<li><strong>Portrait Studio:<\/strong> questa funzione converte il tuo selfie in diversi stili artistici come fumetti, cartoni animati 3D, acquerelli e schizzi. Una volta scelto uno stile e premuto Genera, scansiona il tuo viso e ti fornisce alcuni ritratti diversi nello stile da te scelto.<\/li>\n<li><strong>Modalit\u00e0 interprete avanzata:<\/strong> mentre stai conversando con qualcuno, puoi usare lo schermo di copertina per mostrare il testo tradotto alla persona di fronte a te.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"Nuove funzionalit\u00e0 di Galaxy AI su Z Fold 6\" class=\"wp-image\" decoding=\"async\" height=\"747\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/New-Galaxy-AI-features-on-Z-Fold-6-1024x747-1.webp\" title=\"Nuove funzionalit\u00e0 di Galaxy AI su Z Fold 6\" width=\"1024\"\/><\/figure>\n<p>Oltre a queste fantastiche funzionalit\u00e0 AI, Samsung promette 7 anni di importanti aggiornamenti Android e patch di sicurezza per lo Z Fold 6. Si tratta di un significativo passo avanti rispetto allo Z Fold 5, che offre solo 4 anni di aggiornamenti (e ora sono rimaste solo 3 versioni Android al momento in cui scrivo). Quindi, se stai pianificando un utilizzo a lungo termine, il Galaxy Z Fold 6 \u00e8 una scommessa solida per la longevit\u00e0.<\/p>\n<h2>Quale telefono dovresti acquistare?<\/h2>\n<p>C&#8217;\u00e8 molto da amare nel Samsung Galaxy Z Fold 6. Il nuovo design squadrato \u00e8 fantastico da tenere in mano, la piega interna dello schermo \u00e8 meno evidente e la promessa di 7 anni di aggiornamenti software \u00e8 lodevole. Considerato il prezzo elevato dei telefoni pieghevoli, \u00e8 rassicurante sapere che il tuo telefono sar\u00e0 supportato per molto tempo.<\/p>\n<p>Tuttavia, se possiedi gi\u00e0 il Galaxy Z Fold 5, non c&#8217;\u00e8 un grande incentivo ad aggiornarlo. Le differenze, sebbene piacevoli, non cambiano le carte in tavola. Ma per coloro che si avventurano per la prima volta nel mercato dei dispositivi pieghevoli, lo Z Fold 6 \u00e8 una scelta di prim&#8217;ordine. In alternativa, potresti aspettare una buona offerta sul Fold 5. Se lo trovi a $ 400 o pi\u00f9 di sconto, \u00e8 un affare da considerare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sinistra \u2013 Piega 6 e Destra \u2013 Piega 5 L&#8217;attesissimo Z Fold 6 di Samsung ha debuttato all&#8217;evento Galaxy Unpacked il 10 luglio 2024. Vanta diverse nuove funzionalit\u00e0 e aggiornamenti hardware, come un nuovo processore, un nuovo design della cerniera, un peso pi\u00f9 leggero e un sacco di nuove funzionalit\u00e0 Galaxy AI. Ma la grande [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,111,278,279,280,38],"class_list":["post-2976","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-comparison","tag-galaxy-ai","tag-galaxy-z-fold-5","tag-galaxy-z-fold-6","tag-samsung"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=2976"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2976\/revisions"}],"predecessor-version":[{"id":2977,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/2976\/revisions\/2977"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=2976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=2976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=2976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}