{"id":3008,"date":"2024-07-30T05:10:57","date_gmt":"2024-07-30T05:10:57","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=3008"},"modified":"2024-07-30T05:10:57","modified_gmt":"2024-07-30T05:10:57","slug":"how-to-access-your-android-phone-in-file-explorer-in-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-access-your-android-phone-in-file-explorer-in-windows-11-it\/","title":{"rendered":"Come accedere al tuo telefono Android in Esplora file in Windows 11"},"content":{"rendered":"<h2 id=\"prerequisites\">Prerequisiti<\/h2>\n<ul>\n<li>Il tuo dispositivo Android dovrebbe avere Android 11 o versione successiva.<\/li>\n<li>Dovresti avere installata sul tuo telefono la versione Beta (1.24071 o successiva) dell&#8217;app Collegamento a Windows.<\/li>\n<li>Dovresti utilizzare Windows 11 ed essere un Windows Insider con accesso a uno qualsiasi dei quattro Canali Insider.<\/li>\n<\/ul>\n<h2 id=\"enable-the-new-feature\">Abilita la nuova funzionalit\u00e0<\/h2>\n<ul>\n<li>Apri l&#8217;app Impostazioni e clicca su &#8220;Bluetooth e dispositivi&#8221; sulla sinistra.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"465\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Screenshot-2024-07-29-130517-2-1.webp\" title=\"\" width=\"827\"\/><\/figure>\n<ul>\n<li>Nella pagina Bluetooth e dispositivi, tocca &#8220;Dispositivi mobili&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"464\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Screenshot-2024-07-29-130642-2-1.webp\" title=\"\" width=\"824\"\/><\/figure>\n<ul>\n<li>Assicurati che il pulsante &#8216;Consenti a questo PC di accedere ai tuoi dispositivi mobili&#8217; sia attivato. In caso contrario, cliccaci sopra per abilitarlo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"596\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/Screenshot-2024-07-29-144554-1.webp\" title=\"\" width=\"1060\"\/><\/figure>\n<ul>\n<li>Dovresti anche vedere un&#8217;opzione &#8216;Access in File Explorer&#8217; che mostra le foto, i file e i contenuti multimediali del tuo cellulare in File Explorer. Cliccaci sopra per attivarla. Se questa opzione non \u00e8 presente, la funzionalit\u00e0 non \u00e8 ancora disponibile sul tuo computer.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"736\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/PFFE_blogpost_CDEH-1.webp\" title=\"\" width=\"1309\"\/><figcaption>Fonte: Microsoft<\/figcaption><\/figure>\n<h2 id=\"access-your-android-files\">Accedi ai tuoi file Android<\/h2>\n<ul>\n<li>Apri Esplora file di Windows: in alto a sinistra dovrebbe essere visibile un punto di accesso per il tuo dispositivo Android.<\/li>\n<li>Quando il tuo telefono Android \u00e8 connesso al PC, ora puoi accedervi direttamente facendo doppio clic sulla sua icona in Esplora file. Puoi spostare, copiare, eliminare e gestire i file sul tuo dispositivo Android direttamente da qui, senza doverlo connettere al PC tramite un cavo.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"892\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/07\/PFFE_blogpost_FE@2x-1-1.webp\" title=\"\" width=\"1586\"\/><figcaption><span>Il nuovo punto di ingresso per accedere ai file sul tuo Android.<\/span> Fonte: Microsoft<\/figcaption><\/figure>\n<h2 id=\"known-issues\">Problemi conosciuti<\/h2>\n<p>Poich\u00e9 la nuova funzionalit\u00e0 \u00e8 ancora in versione Beta, ci sono alcuni problemi di cui devi essere a conoscenza quando la utilizzi.<\/p>\n<ul>\n<li>Quando elimini file sul tuo telefono Android usando questa funzionalit\u00e0, vengono spostati nel Cestino dove rimangono per cinque giorni, invece dei 30 giorni indicati. Microsoft ha dichiarato che una correzione \u00e8 in arrivo.<\/li>\n<li>A volte i file nel Cestino del telefono potrebbero non apparire in Esplora file di Windows. Anche in questo caso, un aggiornamento risolver\u00e0 il problema.<\/li>\n<li>Occasionalmente, le modifiche apportate ai file sul telefono tramite il PC potrebbero non avere effetto. Per risolvere il problema, esci dal tuo account Windows e accedi di nuovo.<\/li>\n<\/ul>\n<h3 id=\"things-to-know\">Cose da sapere<\/h3>\n<ul>\n<li>Con la nuova funzionalit\u00e0, potrai accedere a tutti i tuoi file Android sul tuo PC Windows 11 in modalit\u00e0 wireless. Attualmente, puoi farlo solo collegando entrambi i dispositivi con un cavo.<\/li>\n<li>Poich\u00e9 la funzionalit\u00e0 viene distribuita gradualmente ai partecipanti al programma Windows Insider, potrebbe volerci del tempo prima che raggiunga il tuo dispositivo.<\/li>\n<li>Poich\u00e9 si tratta di una versione beta, alcune funzionalit\u00e0 potrebbero essere aggiunte, modificate o rimosse quando verr\u00e0 rilasciata la versione finale.<\/li>\n<li>Al momento non si sa ancora quando verr\u00e0 rilasciato e reso pubblico l&#8217;ultimo aggiornamento stabile, n\u00e9 se sar\u00e0 disponibile per Windows 10.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Prerequisiti Il tuo dispositivo Android dovrebbe avere Android 11 o versione successiva. Dovresti avere installata sul tuo telefono la versione Beta (1.24071 o successiva) dell&#8217;app Collegamento a Windows. Dovresti utilizzare Windows 11 ed essere un Windows Insider con accesso a uno qualsiasi dei quattro Canali Insider. Abilita la nuova funzionalit\u00e0 Apri l&#8217;app Impostazioni e clicca [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,9],"class_list":["post-3008","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows","tag-windows-11"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=3008"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3008\/revisions"}],"predecessor-version":[{"id":3009,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3008\/revisions\/3009"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=3008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=3008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=3008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}