{"id":3142,"date":"2024-08-08T13:21:11","date_gmt":"2024-08-08T13:21:11","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=3142"},"modified":"2024-08-08T13:21:11","modified_gmt":"2024-08-08T13:21:11","slug":"how-to-install-apple-maps-on-windows-and-android-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-install-apple-maps-on-windows-and-android-it\/","title":{"rendered":"Come installare Apple Maps su Windows e Android"},"content":{"rendered":"<h2 id=\"install-apple-maps-on-windows\">Installare Apple Maps su Windows<\/h2>\n<ul>\n<li>Apri Microsoft Edge sul tuo computer e visita la pagina beta.maps.com. Si aprir\u00e0 la pagina Apple Maps.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"560\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/08\/2024-08-07-15-51-49-1.webp\" title=\"\" width=\"996\"\/><\/figure>\n<ul>\n<li>Fai clic sui tre pulsanti in alto a destra, quindi sposta il cursore sulla sezione &#8220;App&#8221; prima di fare clic su &#8220;Installa questo sito come app&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"506\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/08\/2024-08-07-15-58-23-1.webp\" title=\"\" width=\"900\"\/><\/figure>\n<ul>\n<li>Assegna un nome all&#8217;app e clicca sul pulsante &#8220;Installa&#8221;.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"507\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/08\/2024-08-07-16-01-20-1.webp\" title=\"\" width=\"902\"\/><\/figure>\n<ul>\n<li>Una volta installata l&#8217;app, questa si avvier\u00e0 automaticamente in una finestra a s\u00e9 stante. Puoi aggiungerla alla barra delle applicazioni, al menu Start e persino creare un collegamento sul desktop. Fai clic sul pulsante &#8220;Consenti&#8221; dopo aver selezionato le opzioni desiderate.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"543\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/08\/2024-08-07-16-10-58-1.webp\" title=\"\" width=\"966\"\/><\/figure>\n<ul>\n<li>A seconda di dove hai appuntato l&#8217;app, puoi avviare la nuova app Apple Maps dal desktop, dal menu Start o dalla barra delle applicazioni. Puoi rimuovere l&#8217;app in qualsiasi momento dalle Impostazioni, proprio come le altre app.<\/li>\n<\/ul>\n<h2 id=\"install-apple-maps-on-android\">Installa Apple Maps su Android<\/h2>\n<p>Sebbene non sia possibile installare Apple Maps su Android come su Windows, \u00e8 comunque possibile utilizzarlo con il browser DuckDuckGo. Questo browser utilizza Apple Maps di default quando si cerca una posizione.<\/p>\n<ul>\n<li>Installa il browser DuckDuckGo sul tuo dispositivo Android.<\/li>\n<li>Cerca un luogo e poi clicca sul filtro &#8216;Mappe&#8217;. Puoi anche toccare &#8216;Indicazioni&#8217; per ottenere indicazioni stradali per la posizione che stai cercando.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><\/figure>\n<h3 id=\"things-to-know\">Cose da sapere<\/h3>\n<ul>\n<li>Rispetto a Bing Maps o Google Maps, Apple Maps offre un&#8217;esperienza pi\u00f9 incentrata sulla privacy, anche se non \u00e8 cos\u00ec ricca di funzionalit\u00e0.<\/li>\n<li>Alcune limitazioni di Apple Maps sui dispositivi non Apple includono la mancanza di assistenza alla navigazione, nessuna pianificazione del percorso o guide cittadine curate e nessuna informazione sul traffico o sui trasporti pubblici.<\/li>\n<li>Se utilizzi la navigazione in Apple Maps su Android o Windows, l&#8217;azione verr\u00e0 completata tramite Google Maps.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Installare Apple Maps su Windows Apri Microsoft Edge sul tuo computer e visita la pagina beta.maps.com. Si aprir\u00e0 la pagina Apple Maps. Fai clic sui tre pulsanti in alto a destra, quindi sposta il cursore sulla sezione &#8220;App&#8221; prima di fare clic su &#8220;Installa questo sito come app&#8221;. Assegna un nome all&#8217;app e clicca sul [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,7],"class_list":["post-3142","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=3142"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3142\/revisions"}],"predecessor-version":[{"id":3143,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3142\/revisions\/3143"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=3142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=3142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=3142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}