{"id":3728,"date":"2024-09-09T22:58:22","date_gmt":"2024-09-09T22:58:22","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=3728"},"modified":"2024-09-09T22:58:22","modified_gmt":"2024-09-09T22:58:22","slug":"apple-watch-series-10-vs-series-9-key-differences-and-features-explained-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/apple-watch-series-10-vs-series-9-key-differences-and-features-explained-it\/","title":{"rendered":"Apple Watch Series 10 vs Series 9 \u2013 Differenze principali e caratteristiche spiegate"},"content":{"rendered":"<p>L&#8217;evento Glowtime di Apple si \u00e8 concluso e sono stati fatti molti annunci interessanti e importanti, tra cui iPhone 16. Sono stati rilasciati anche due nuovi Apple Watch e uno di questi \u00e8 Watch Series 10. Invece di chiamarlo Watch X come con iPhone X, Apple ha deciso di usare solo Watch 10. Ecco uno sguardo a come Watch 10 si confronta con Watch 9 dell&#8217;anno scorso e se dovresti fare l&#8217;upgrade.<\/p>\n<h2><span id=\"Design-and-Display-Thinner-Bigger-Larger\">Design e display: pi\u00f9 sottile, pi\u00f9 grande, pi\u00f9 ampio<\/span><\/h2>\n<p>Il display dell&#8217;Apple Watch 10 \u00e8 leggermente pi\u00f9 grande dell&#8217;Ultra ma pi\u00f9 sottile del Watch 9 del 10%, il che \u00e8 piuttosto impressionante. Le persone con mani pi\u00f9 piccole e polsi pi\u00f9 sottili potrebbero non essere troppo entusiaste di sentirlo, ma nel complesso, vedo una tendenza verso display pi\u00f9 grandi negli smartwatch, purtroppo. Ci\u00f2 significa anche un display pi\u00f9 grande e pi\u00f9 informazioni sullo schermo. \u00c8 possibile che il Watch SE, in arrivo l&#8217;anno prossimo, avr\u00e0 la cassa da 41 mm, consentendo ad Apple di includere pi\u00f9 funzionalit\u00e0 (probabilmente sensori) nella serie conveniente.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"498\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/09\/apple-watch-10-wide-angle-display-1024x498-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<p>Ecco una tabella che confronta l&#8217;Apple Watch Series 9 e il vociferato Apple Watch Series 10:<\/p>\n<table>\n<thead>\n<tr>\n<th>Caratteristica<\/th>\n<th>Apple Watch Serie 9<\/th>\n<th>Apple Watch Serie 10<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><strong>Opzioni di dimensione dell&#8217;involucro<\/strong><\/td>\n<td>41mm, 45mm<\/td>\n<td>42mm, 46mm<\/td>\n<\/tr>\n<tr>\n<td><strong>Opzioni di dimensione dello schermo<\/strong><\/td>\n<td>1,69 pollici, 1,9 pollici<\/td>\n<td>1,89 pollici, 2 pollici (+11,8%, +7,4%)<\/td>\n<\/tr>\n<tr>\n<td><strong>Display OLED grandangolare<\/strong><\/td>\n<td>10,7 mm<\/td>\n<td>9,7 mm<\/td>\n<\/tr>\n<tr>\n<td><strong>Materiali<\/strong><\/td>\n<td>Rivestimento standard<\/td>\n<td>Vetro Ion-X<\/td>\n<\/tr>\n<tr>\n<td><strong>Tecnologia di visualizzazione<\/strong><\/td>\n<td>SEI<\/td>\n<td>Display OLED grandangolare<\/td>\n<\/tr>\n<tr>\n<td><strong>Luminosit\u00e0<\/strong><\/td>\n<td>2000 nit al massimo<\/td>\n<td>2800 nit (40% pi\u00f9 luminoso)<\/td>\n<\/tr>\n<tr>\n<td><strong>Impermeabile<\/strong><\/td>\n<td>Fino a 50 metri<\/td>\n<td>Fino a 50 metri<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Il design rimane pi\u00f9 o meno lo stesso, fatta eccezione per le dimensioni. Perch\u00e9 rompere qualcosa che funziona gi\u00e0 cos\u00ec bene? Inoltre, gli utenti non sempre rispondono positivamente ai drastici cambiamenti di design. Apple segue la collaudata filosofia di design.<\/p>\n<p>C&#8217;\u00e8 un nuovo speaker che aiuta a riprodurre canzoni e podcast. Tuttavia, ritengo che siano pi\u00f9 adatti per ascoltare podcast, notizie o chiamate rapide piuttosto che per ascoltare canzoni. Lascia la musica alle cuffie e ai TWS, per favore.<\/p>\n<h2><span id=\"Performance-and-Battery-With-Some-AI-Magic\">Prestazioni e batteria: con un po&#8217; di magia dell&#8217;intelligenza artificiale<\/span><\/h2>\n<p>Come previsto, Watch 10 \u00e8 dotato del chip S10, un upgrade rispetto al chip S9 di Watch 9. Aspettatevi prestazioni migliori grazie al motore neurale a 4 core. Tuttavia, non \u00e8 questo che conta. Ci\u00f2 che \u00e8 pi\u00f9 importante per l&#8217;utente finale \u00e8 che il chip S10 \u00e8 stato progettato pensando all&#8217;intelligenza artificiale o Apple Intelligence. Se possedete un iPhone compatibile con l&#8217;intelligenza artificiale, parte di quella magia dell&#8217;intelligenza artificiale si riverser\u00e0 nel vostro Watch 10. Maggiori informazioni di seguito.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"777\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/09\/apple-watch-fall-detection-1024x777-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<p>Apple afferma che Watch 10 \u00e8 l&#8217;Apple Watch con la ricarica pi\u00f9 rapida, caricandosi fino all&#8217;80% in 30 minuti rispetto a Watch 9 che carica dallo 0 all&#8217;80% in 45 minuti. Avr\u00e0 una durata della batteria di circa 18 ore. Lo testeremo senza dubbio, quindi seguiteci. Tuttavia, il keynote non ha rivelato dettagli sulla capacit\u00e0 della batteria.<\/p>\n<h2><span id=\"Health-and-Sensors-Old-Dog-New-Tricks\">Salute e sensori: vecchio cane, nuovi trucchi<\/span><\/h2>\n<p>Apple Watch pu\u00f2 gi\u00e0 rilevare automaticamente il rilevamento di cadute e urti. Per una migliore udibilit\u00e0 e chiarezza durante le chiamate, Apple ha aggiunto una nuova rete neurale per ridurre il rumore di fondo come quello delle strade o delle giornate ventose.<\/p>\n<p>Gli smartwatch e i dispositivi indossabili in generale sono ideali per due cose: monitorare le metriche sulla salute e visualizzare le notifiche dal tuo iPhone. Apple Watch 10 \u00e8 dotato di alcuni nuovi sensori, il che significa nuove metriche sulla salute a portata di mano. Uno ti aiuter\u00e0 a dormire meglio.<\/p>\n<p>Ecco uno sguardo ai sensori inclusi nell&#8217;Apple Watch Series 10 e a cosa servono:<\/p>\n<table>\n<thead>\n<tr>\n<th>Tipo di sensore<\/th>\n<th>Funzione\/Uso<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><strong>Sensore di frequenza cardiaca<\/strong><\/td>\n<td>Misura la frequenza cardiaca in modo continuo durante gli allenamenti e l&#8217;uso quotidiano<\/td>\n<\/tr>\n<tr>\n<td><strong>Sensore di ossigeno nel sangue<\/strong><\/td>\n<td>Monitora i livelli di saturazione dell&#8217;ossigeno nel sangue (SpO2)<\/td>\n<\/tr>\n<tr>\n<td><strong>Sensore ECG<\/strong><\/td>\n<td>Genera un elettrocardiogramma per l&#8217;analisi della salute del cuore (non disponibile ovunque)<\/td>\n<\/tr>\n<tr>\n<td><strong>Accelerometro<\/strong><\/td>\n<td>Traccia i movimenti, rileva le cadute, rileva l&#8217;apnea notturna<\/td>\n<\/tr>\n<tr>\n<td><strong>Giroscopio<\/strong><\/td>\n<td>Monitora il movimento e l&#8217;orientamento<\/td>\n<\/tr>\n<tr>\n<td><strong>Altimetro<\/strong><\/td>\n<td>Misura i cambiamenti di altitudine e traccia l&#8217;elevazione<\/td>\n<\/tr>\n<tr>\n<td><strong>Bussola<\/strong><\/td>\n<td>Aiuta con la navigazione e l&#8217;orientamento<\/td>\n<\/tr>\n<tr>\n<td><strong>Sensore di temperatura<\/strong><\/td>\n<td>Tiene traccia dei cambiamenti della temperatura corporea, utile per il monitoraggio del sonno e della salute<\/td>\n<\/tr>\n<tr>\n<td><strong>Sensore di luce ambientale<\/strong><\/td>\n<td>Regola la luminosit\u00e0 del display in base all&#8217;illuminazione esterna<\/td>\n<\/tr>\n<tr>\n<td><strong>UWB (banda ultra larga)<\/strong><\/td>\n<td>Tracciamento preciso della posizione per i dispositivi<\/td>\n<\/tr>\n<tr>\n<td><strong>Misuratore di profondit\u00e0<\/strong><\/td>\n<td>Misura la profondit\u00e0 dell&#8217;acqua fino a 6 metri o 20 piedi<\/td>\n<\/tr>\n<tr>\n<td><strong>Temperatura dell&#8217;acqua<\/strong><\/td>\n<td>Misurare la temperatura dell&#8217;acqua prima di immergersi<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Apple Watch 10 \u00e8 dotato di una nuova ma importante metrica per la salute: l&#8217;apnea notturna (in attesa di approvazione da parte della FDA). Nota che l&#8217;apnea notturna arriver\u00e0 anche su Series 9 e Ultra 2 in seguito.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/09\/apple-watch-10-sleep-apnea-502x1024-1.webp\" title=\"\" width=\"502\"\/><\/figure>\n<p>Watch 10 pu\u00f2 rilevare l&#8217;apnea notturna utilizzando una nuova metrica chiamata disturbo respiratorio. Utilizzer\u00e0 il sensore dell&#8217;accelerometro per misurare i disturbi respiratori. Questi dati saranno raccolti ogni notte ma saranno analizzati ogni 30 giorni per cercare anomalie e, se trovate, verrete avvisati.<\/p>\n<p>Verr\u00e0 creato un report dettagliato e salvato nell&#8217;app Salute che potrai condividere automaticamente con il tuo medico se lo desideri. Vedremo tutto questo nel nostro test approfondito.<\/p>\n<h2><span id=\"Three-New-Apps\">Tre nuove app<\/span><\/h2>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"846\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/09\/apple-watch-10-tides-app-1024x846-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<p>Apple ha aggiunto tre nuove app all&#8217;Apple Watch Series 10. Sono le app Tides, Depth e Paddle Logger. Ecco cosa fanno:<\/p>\n<ul>\n<li><strong>App Tides<\/strong> : mostra 7 giorni di dati su maree alte\/basse, alba\/tramonto, con dati per le coste di tutto il mondo. Ora puoi pianificare gite in barca, kayak o giornate di surf di conseguenza.<\/li>\n<li><strong>App Depth<\/strong> : rilever\u00e0 la profondit\u00e0 in cui nuoti, fai immersioni o snorkeling. Non solo. Rilever\u00e0 anche la temperatura dell&#8217;acqua, cos\u00ec saprai quando \u00e8 troppo calda o fredda.<\/li>\n<li><strong>App Paddle Logger<\/strong> : crea un piano di galleggiamento per consentirti di mantenere la rotta mentre ti trovi in \u200b\u200bmezzo all&#8217;oceano.<\/li>\n<\/ul>\n<h2><span id=\"Software-and-AI\">Software e intelligenza artificiale<\/span><\/h2>\n<p>Apple Watch 10 arriver\u00e0 con watchOS 10 preinstallato. E poich\u00e9 nessun annuncio software \u00e8 completo senza AI, s\u00ec, Apple Watch 10 arriver\u00e0 con alcuni trucchi AI intelligenti.<\/p>\n<p>Apple Watch ora pu\u00f2 riassumere le notifiche che ricevi tramite il tuo iPhone. Pu\u00f2 anche riassumere qualsiasi testo sullo schermo che pu\u00f2 essere utilizzato durante la lettura di messaggi lunghi, ad esempio. Apple ha mostrato una demo di riconoscimento vocale e funzionalit\u00e0 di traduzione nell&#8217;evento.<\/p>\n<h2><span id=\"Price-Availability-and-Colors-No-Change\">Prezzo, disponibilit\u00e0 e colori: nessun cambiamento<\/span><\/h2>\n<p>Apple Watch Series 9 parte da $ 399 e arriva fino a $ 499. Watch 10 segue l&#8217;esempio e il prezzo rimane invariato. Niente da vedere qui, gente. Andiamo avanti ora.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"879\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/09\/apple-watch-10-color-1024x879-1.webp\" title=\"\" width=\"1024\"\/><\/figure>\n<p>Sono disponibili in nero jet, oro rosa e alluminio argento. Una nuova linea di finitura in titanio grado 5 \u00e8 disponibile anche in oro, naturale e grigio. Apple Watch 10 sar\u00e0 disponibile dal 20 settembre.<\/p>\n<h2><span id=\"Who-Should-Get-Watch-10\">Chi dovrebbe acquistare Watch 10<\/span><\/h2>\n<p>Bella domanda e ho una risposta. Watch 10 offre buoni progressi in termini di durata della batteria e funzionalit\u00e0 rispetto a Watch 9 e 8. Dovresti fare l&#8217;upgrade. I principianti dovrebbero provarlo senza guardare i modelli precedenti.<\/p>\n<blockquote class=\"wp-embedded-content\">\n<p>Il lancio dell&#8217;iPhone 16: cosa dicono i meme<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;evento Glowtime di Apple si \u00e8 concluso e sono stati fatti molti annunci interessanti e importanti, tra cui iPhone 16. Sono stati rilasciati anche due nuovi Apple Watch e uno di questi \u00e8 Watch Series 10. Invece di chiamarlo Watch X come con iPhone X, Apple ha deciso di usare solo Watch 10. Ecco uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[45,111,17,559],"class_list":["post-3728","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-apple-watch","tag-comparison","tag-ios","tag-watch-10"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=3728"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3728\/revisions"}],"predecessor-version":[{"id":3729,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/3728\/revisions\/3729"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=3728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=3728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=3728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}