{"id":410,"date":"2023-12-22T07:20:15","date_gmt":"2023-12-22T07:20:15","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=410"},"modified":"2023-12-22T07:20:15","modified_gmt":"2023-12-22T07:20:15","slug":"how-to-enable-virtualization-in-windows-11-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-enable-virtualization-in-windows-11-it\/","title":{"rendered":"Come abilitare la virtualizzazione in Windows 11?"},"content":{"rendered":"<p><span data-preserver-spaces=\"true\">Abilitare la virtualizzazione in Windows non \u00e8 affatto scienza missilistica. Hai solo bisogno di conoscere i metodi esatti e corretti per farlo. Beh, indovina un po&#8217;? Oggi siamo qui per chiarire alcuni dettagli che ti aiuteranno a comprendere il concetto di Hyper-V e ad abilitarlo sul tuo PC Windows 11.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Come sappiamo, il nuovo <u data-wpel-link=\"internal\">Windows 11<\/u> offre un design nuovo e fresco con un&#8217;interfaccia visivamente completamente modificata. Ecco perch\u00e9 alcuni utenti potrebbero sentirsi confusi quando si tratta di abilitare questo tipo di funzionalit\u00e0. <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Quindi, siamo qui per ridurre il tuo lavoro. Pertanto, ora non perder\u00f2 il tuo tempo parlando qui e ti porter\u00f2 direttamente ai passaggi che ti aiuteranno ad abilitare la virtualizzazione (hyper-v) in Windows 11.<\/span><\/p>\n<h2><span id=\"What_is_Microsoft_Hyper-V\"><strong><span data-preserver-spaces=\"true\">Cos&#8217;\u00e8 Microsoft Hyper-V?<\/span><\/strong><\/span><\/h2>\n<p><span data-preserver-spaces=\"true\">Per coloro che non conoscono <a data-wpel-link=\"external\" href=\"https:\/\/learn.microsoft.com\/en-us\/windows-server\/virtualization\/hyper-v\/hyper-v-technology-overview\" rel=\"nofollow external noopener noreferrer\" target=\"_blank\">Hyper-V<\/a>, \u00e8 una piattaforma di virtualizzazione di Microsoft Windows e viene fornita nativamente con Windows 11. Tuttavia, \u00e8 necessario abilitare manualmente questa funzionalit\u00e0 perch\u00e9, per impostazione predefinita, \u00e8 disabilitata sul tuo PC. <\/span><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cos'\u00e8 Microsoft Hyper-V\" class=\"wp-image\" decoding=\"async\" height=\"266\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/What-is-Microsoft-Hyper-V.webp\" title=\"Cos'\u00e8 Microsoft Hyper-V\" width=\"600\"\/><\/figure>\n<p><span data-preserver-spaces=\"true\">Tuttavia, sfortunatamente, se sul tuo PC \u00e8 installata la versione Home di Windows 11, potresti non essere in grado di utilizzarla poich\u00e9 \u00e8 disponibile su Windows 11 Pro e Windows 11 Education.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Nel frattempo, se non sai come verificare la <\/span><u data-wpel-link=\"internal\" rel=\"noopener\">versione di Windows 11<\/u><span data-preserver-spaces=\"true\">, segui il collegamento indicato. Lo scopo principale di Hyper-V \u00e8 consentirti di eseguire macchine virtuali sul tuo PC Windows. <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Parliamo di macchina virtuale, un&#8217;applicazione che permette di eseguire numerosi sistemi operativi utilizzando lo stesso hardware fisico in un luogo solitario e protetto.<\/span><\/p>\n<h2><span id=\"Steps_To_Check_Whether_Your_PC_Supports_Hyper-V_or_Not\"><strong><span data-preserver-spaces=\"true\">Passaggi per verificare se il tuo PC supporta Hyper-V o meno<\/span><\/strong><\/span><\/h2>\n<p><span data-preserver-spaces=\"true\">Esistono due metodi che puoi utilizzare per sapere se il tuo PC ha il supporto per la virtualizzazione. Quindi, diamo un\u2019occhiata a loro:<\/span><\/p>\n<h3><span id=\"1_Using_Task_Manager\"><strong><span data-preserver-spaces=\"true\">1. Utilizzo del Task Manager<\/span><\/strong><\/span><\/h3>\n<ol>\n<li><span data-preserver-spaces=\"true\">Per prima cosa, tieni premuti <\/span><strong><span data-preserver-spaces=\"true\">Ctrl+Maiusc+Esc <\/span><\/strong><span data-preserver-spaces=\"true\">contemporaneamente. Questo avvier\u00e0 il Task Manager. Successivamente, vai alla <\/span><strong><span data-preserver-spaces=\"true\">scheda Prestazioni<\/span><\/strong><span data-preserver-spaces=\"true\">.<\/span><\/li>\n<li><span data-preserver-spaces=\"true\">Ora vedrai se il tuo PC ha o meno la funzionalit\u00e0 di virtualizzazione sul lato destro.<\/span><img alt=\"virtualizzazione della scheda Prestazioni del task manager\" class=\"wp-image\" decoding=\"async\" height=\"470\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/task-manager-Performance-Tab-virtualization.webp\" title=\"virtualizzazione della scheda Prestazioni del task manager\" width=\"600\"\/><\/li>\n<\/ol>\n<h3><span id=\"2_Use_Command_Prompt\"><strong><span data-preserver-spaces=\"true\">2. Utilizzare il prompt dei comandi<\/span><\/strong><\/span><\/h3>\n<ol>\n<li><span data-preserver-spaces=\"true\">Per prima cosa, apri la barra di ricerca di Windows e cerca <strong>CMD<\/strong>, quindi eseguilo utilizzando i privilegi di amministratore.<\/span><img alt=\"CMD Esegui come amministratore\" class=\"wp-image\" decoding=\"async\" height=\"474\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/CMD-Run-as-administrator.webp\" title=\"CMD Esegui come amministratore\" width=\"336\"\/><\/li>\n<li><span data-preserver-spaces=\"true\">Successivamente, esegui il comando: <\/span><strong><span data-preserver-spaces=\"true\">systeminfo<\/span><\/strong><\/li>\n<li><span data-preserver-spaces=\"true\">Ora apparir\u00e0 nella parte inferiore dello schermo CMD, ma solo se hai una <strong>funzione di virtualizzazione<\/strong> sul tuo PC.&lt; \/span&gt;<\/span><img alt=\"virtualizzazione systeminfo abilitata\" class=\"wp-image\" decoding=\"async\" height=\"416\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/systeminfo-virtualization-enabled.webp\" title=\"virtualizzazione systeminfo abilitata\" width=\"562\"\/><\/li>\n<\/ol>\n<h2><span id=\"Steps_To_Enable_Virtualization_in_Windows_11\"><strong><span data-preserver-spaces=\"true\">Passaggi per abilitare la virtualizzazione in Windows 11<\/span><\/strong><\/span><\/h2>\n<p><span data-preserver-spaces=\"true\">Quindi, ora sai come verificare se il tuo PC supporta la virtualizzazione o meno. Pertanto, ora \u00e8 il momento di abilitarlo.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Ma prima di iniziare, devi verificare se \u00e8 abilitato o meno nel menu delle impostazioni BIOS\/UEFI. Per fare ci\u00f2, ecco i passaggi che puoi seguire nel percorso:<\/span><\/p>\n<figure class=\"wp-block-image\"><img alt=\"NOTA:\u00a0ogni marca di laptop o computer ha chiavi diverse per aprire le impostazioni del BIOS, quindi premi il tasto di avvio in base alla marca del tuo laptop o computer e accedi alle impostazioni BIOS\/UEFI.\" class=\"wp-image\" decoding=\"async\" height=\"572\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/All-Laptop-Desktop-Boot-Menu-Bios-Keys.webp\" title=\"NOTA:\u00a0ogni marca di laptop o computer ha chiavi diverse per aprire le impostazioni del BIOS, quindi premi il tasto di avvio in base alla marca del tuo laptop o computer e accedi alle impostazioni BIOS\/UEFI.\" width=\"600\"\/><\/figure>\n<p><strong>Riavvia il PC &gt; Premi il tasto funzione F2 o F10 &gt; Configurazione del sistema<\/strong><span data-preserver-spaces=\"true\"> o <\/span><strong><span data-preserver-spaces=\"true\">Tecnologia virtuale<\/span><\/strong><span data-preserver-spaces=\"true\"> o qualcosa di simile e attivalo.<\/span><\/p>\n<figure class=\"wp-block-image\"><img alt=\"abilitare la virtualizzazione dalle impostazioni del bios\" class=\"wp-image\" decoding=\"async\" height=\"364\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/enable-virtualization-from-bios-settings.webp\" title=\"abilitare la virtualizzazione dalle impostazioni del bios\" width=\"640\"\/><\/figure>\n<p><span data-preserver-spaces=\"true\">Quindi, ora hai abilitato questa opzione nel menu <strong>impostazioni BIOS\/UEFI<\/strong>; pertanto, diamo un&#8217;occhiata ai passaggi per abilitare la virtualizzazione in Windows 11. <\/span><\/p>\n<ol>\n<li><span data-preserver-spaces=\"true\">Prima di tutto, apri la casella <\/span><strong><span data-preserver-spaces=\"true\">Esegui prompt <\/span><\/strong><span data-preserver-spaces=\"true\">premendo <\/span><strong><span data-preserver-spaces=\"true\">Win+R <\/span><\/strong><span data-preserver-spaces=\"true\">tasto contemporaneamente. <\/span><\/li>\n<li><span data-preserver-spaces=\"true\">Successivamente, digita <\/span><strong><span data-preserver-spaces=\"true\">optionalupdates.exe <\/span><\/strong>e premi invio.<img alt=\"aggiornamentiopzionali.exe\" class=\"wp-image\" decoding=\"async\" height=\"230\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/optionalupdates.exe_.webp\" title=\"aggiornamentiopzionali.exe\" width=\"400\"\/><\/li>\n<li><span data-preserver-spaces=\"true\">Ora verr\u00e0 visualizzata la schermata <\/span><strong><span data-preserver-spaces=\"true\">Funzioni Windows <\/span><\/strong><span data-preserver-spaces=\"true\">; da qui puoi abilitare e disabilitare diverse impostazioni di Windows 11, come <\/span><strong><span data-preserver-spaces=\"true\">Hyper-V<\/span><\/strong><span data-preserver-spaces=\"true\">. Quindi, puoi semplicemente individuare e verificare se <strong>tutte le impostazioni relative a Hyper-V sono abilitate<\/strong> e quindi premere <\/span><strong><span data-preserver-spaces=\"true\"> OK<\/span><\/strong><span data-preserver-spaces=\"true\"> pulsante.<\/span><img alt=\"Opzioni Hyper-V abilitate\" class=\"wp-image\" decoding=\"async\" height=\"443\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Hyper-V-options-enabled.webp\" title=\"Opzioni Hyper-V abilitate\" width=\"500\"\/><\/li>\n<li><span data-preserver-spaces=\"true\">Quindi vedrai che apparir\u00e0 una nuova finestra di avanzamento; pertanto, \u00e8 necessario attendere il completamento del processo. Una volta terminato, premi il pulsante <\/span><strong><span data-preserver-spaces=\"true\">Riavvia ora<\/span><\/strong><span data-preserver-spaces=\"true\">. <\/span><\/li>\n<\/ol>\n<h3><span id=\"How_To_Open_The_Hyper-V_Manager_on_Your_Windows_11_PC\"><strong><span data-preserver-spaces=\"true\">Come aprire Hyper-V Manager sul tuo PC Windows 11<\/span><\/strong><\/span><\/h3>\n<p><span data-preserver-spaces=\"true\">Ora, dopo aver seguito i passaggi precedenti; pertanto, una volta riavviato il PC, sarai in grado di creare e gestire le tue macchine Hyper-V. Quindi, ora diamo un&#8217;occhiata a come \u00e8 possibile utilizzare questa funzione:<\/span><\/p>\n<ol>\n<li><span data-preserver-spaces=\"true\">Inizialmente, vai all&#8217;opzione di ricerca di Windows e cerca <\/span><strong><span data-preserver-spaces=\"true\">Hyper-V Manager<\/span><\/strong><span data-preserver-spaces=\"true\">, quindi aprilo utilizzando <\/span><strong><span data-preserver-spaces=\"true\">Esegui come amministratore.<\/span><img loading=\"lazy\" decoding=\"async\" alt=\"Gestione Hyper-V Esegui come amministratore\" height=\"408\" src=\"https:\/\/techdator.net\/wp-content\/uploads\/2021\/12\/Hyper-V-Manager-Run-as-admin.jpg\" title=\"Gestione Hyper-V Esegui come amministratore\" width=\"640\"\/><\/strong><\/li>\n<li><span data-preserver-spaces=\"true\">Ora puoi creare e gestire la tua macchina virtuale utilizzando hyper-v. Quindi, crea una nuova macchina virtuale in esecuzione su Windows, Linux o qualche altro sistema operativo utilizzando l&#8217;opzione <\/span><strong><span data-preserver-spaces=\"true\">Procedura guidata nuova macchina virtuale <\/span><\/strong><span data-preserver-spaces=\"true\">. <\/span><img alt=\"Crea nuova macchina virtuale\" class=\"wp-image\" decoding=\"async\" height=\"303\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/Create-New-Virtual-Machine.webp\" title=\"Crea nuova macchina virtuale\" width=\"600\"\/><\/li>\n<li>Poich\u00e9 la macchina virtuale utilizza le risorse del sistema per funzionare correttamente; pertanto, ti consigliamo di non assegnargli una <strong><span data-preserver-spaces=\"true\">RAM<\/span><\/strong><span data-preserver-spaces=\"true\"> o <\/span><strong><span data-preserver-spaces=\"true\">spazio di archiviazione<\/span><\/strong><span data-preserver-spaces=\"true\">.<\/span><img alt=\"Assegna RAM alla macchina virtuale\" class=\"wp-image\" decoding=\"async\" height=\"304\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2023\/12\/assign-memory-for-virtualization.webp\" title=\"Assegna RAM alla macchina virtuale\" width=\"640\"\/><\/li>\n<\/ol>\n<h4><span id=\"From_Authors_Desk\"><strong><span data-preserver-spaces=\"true\">Dalla scrivania dell&#8217;autore<\/span><\/strong><\/span><\/h4>\n<p><span data-preserver-spaces=\"true\">Quindi, questo \u00e8 tutto ci\u00f2 che abbiamo per te su come abilitare la virtualizzazione (hyper-v) in Windows 11. Ci auguriamo che questa guida ti abbia aiutato. Tuttavia, nel caso in cui tu abbia dubbi riguardo alla funzionalit\u00e0 Hyper-V o trovi difficile abilitare questa funzionalit\u00e0, faccelo sapere nella sezione commenti.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abilitare la virtualizzazione in Windows non \u00e8 affatto scienza missilistica. Hai solo bisogno di conoscere i metodi esatti e corretti per farlo. Beh, indovina un po&#8217;? Oggi siamo qui per chiarire alcuni dettagli che ti aiuteranno a comprendere il concetto di Hyper-V e ad abilitarlo sul tuo PC Windows 11. Come sappiamo, il nuovo Windows [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[56],"class_list":["post-410","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-tips"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=410"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/410\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/410\/revisions\/411"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}