{"id":4792,"date":"2024-10-16T14:36:17","date_gmt":"2024-10-16T14:36:17","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=4792"},"modified":"2024-10-16T14:36:17","modified_gmt":"2024-10-16T14:36:17","slug":"25-essential-android-15-features-you-must-know-about","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/25-essential-android-15-features-you-must-know-about\/","title":{"rendered":"25+ funzionalit\u00e0 essenziali di Android 15 che devi conoscere"},"content":{"rendered":"<p>Google ha ufficialmente lanciato la versione pubblica di <a href=\"https:\/\/blog.google\/products\/android\/android-15\/\" rel=\"noreferrer noopener\" target=\"_blank\">Android 15<\/a> , offrendo deliziosi miglioramenti che, pur non essendo rivoluzionari, sono sicuramente entusiasmanti. Attualmente, questo aggiornamento \u00e8 disponibile esclusivamente sui dispositivi Google Pixel, a partire da Pixel 6 e oltre, inclusi Pixel Fold e tablet. Gli utenti con un telefono Pixel compatibile possono iniziare a esplorare queste nuove funzionalit\u00e0 subito, con altri dispositivi che seguiranno l&#8217;esempio a breve. Di seguito sono riportate le nuove funzionalit\u00e0 degne di nota di Android 15 di cui dovresti essere a conoscenza.<\/p>\n<p>Purtroppo molti dispositivi non sono idonei per l&#8217;aggiornamento ad Android 15.<\/p>\n<h2><span id=\"1-Theft-Detection\">1. Rilevamento furti migliorato<\/span><\/h2>\n<p>Se sei preoccupato per il furto del telefono, Android 15 migliora la sicurezza con nuove funzionalit\u00e0 progettate per ostacolare l&#8217;accesso non autorizzato. Le funzionalit\u00e0 critiche, come Trova il mio dispositivo, ora richiedono la tua password per l&#8217;attivazione e se qualcuno tenta ripetutamente di sbloccare il tuo telefono, questo si bloccher\u00e0 completamente. Ci\u00f2 rende notevolmente pi\u00f9 difficile per i ladri ottenere l&#8217;accesso. Inoltre, i tentativi di ripristino delle impostazioni di fabbrica vengono bloccati fino a quando non viene confermata la propriet\u00e0, fornendo un ulteriore livello di protezione.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-120941-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-120951-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"2-Private-Space-for-Your-Sensitive-Data-and-Apps\">2. Spazio privato per dati e app sensibili<\/span><\/h2>\n<p>Android 15 offre una funzionalit\u00e0 &#8220;Spazio Privato&#8221;, che funge da cassaforte sicura per le tue app e i tuoi dati. Questa area designata richiede una password distinta, assicurando che le tue applicazioni e informazioni pi\u00f9 sensibili rimangano protette. Quando sono bloccate, le app al suo interno diventano invisibili, preservando la tua privacy finch\u00e9 non scegli di sbloccarle.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-121042-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-121516-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-121521-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"3-App-Archive-Clear-Space-Without-Uninstalling\">3. App Archive: libera spazio senza disinstallare<\/span><\/h2>\n<p>Se lo spazio di archiviazione si sta esaurendo, la funzionalit\u00e0 App Archive di Android 15 viene in soccorso. Gli utenti possono archiviare le app utilizzate di rado tramite le impostazioni, liberando spazio prezioso senza perdere dati. Ripristinare l&#8217;app \u00e8 facile in seguito, rendendo questa funzionalit\u00e0 particolarmente utile per le app che non si desidera disinstallare completamente.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-121703-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-121715-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"4-Health-Connect\">4. Miglioramenti di Health Connect<\/span><\/h2>\n<p>I miglioramenti nell&#8217;applicazione Health Connect sono notevoli in Android 15, che ora supporta tipi di dati aggiuntivi per un monitoraggio completo della salute, tra cui metriche di fitness e nutrizione. Con l&#8217;ultima Beta 2, gli utenti possono anche acquisire letture della temperatura cutanea e inserire piani di allenamento, offrendo un&#8217;esperienza di monitoraggio della salute pi\u00f9 completa.<\/p>\n<h2><span id=\"5-New-In-App-Camera-Controls\">5. Nuovi controlli della fotocamera nelle app<\/span><\/h2>\n<p>Le funzionalit\u00e0 della fotocamera sono state aggiornate in Android 15, con nuovi controlli di luminosit\u00e0 e flash. Agli sviluppatori \u00e8 concesso l&#8217;accesso a impostazioni aggiuntive della fotocamera, tra cui regolazioni precise per situazioni di scarsa illuminazione. Questi miglioramenti consentono alle app di perfezionare meglio le immagini in tempo reale, migliorando i risultati anche quando si utilizza software per fotocamere di terze parti.<\/p>\n<h2><span id=\"6-Screen-Record-One-App-Instead-of-Entire-Screen\">6. Registra un&#8217;app invece che a schermo intero<\/span><\/h2>\n<p>La possibilit\u00e0 di registrare una finestra specifica dell&#8217;app anzich\u00e9 l&#8217;intero schermo \u00e8 ora una funzionalit\u00e0 di Android 15. Ci\u00f2 significa che la barra di stato rimarr\u00e0 nascosta, rendendola ideale per tutorial o per dimostrare funzionalit\u00e0 particolari senza esporre notifiche private o altre applicazioni, semplificando l&#8217;attenzione delle registrazioni dello schermo.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-144442-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-144446-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"7-Share-Only-What-You-Need-with-Partial-Screen-Sharing\">7. Condivisione selettiva dello schermo<\/span><\/h2>\n<p>Simile alla registrazione dello schermo, Android 15 consente agli utenti di condividere una singola finestra dell&#8217;app durante le videochiamate o le presentazioni, garantendo la privacy nascondendo il resto del telefono. Questa funzionalit\u00e0 elimina le preoccupazioni relative alla rivelazione inavvertitamente di informazioni sensibili durante la condivisione di contenuti.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122028-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122126-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"8-Satellite-Messaging-for-Zero-Coverage-Zones\">8. Messaggistica satellitare per aree remote<\/span><\/h2>\n<p>Per i momenti in cui il servizio cellulare non \u00e8 disponibile, Android 15 introduce funzionalit\u00e0 di messaggistica satellitare. Se il tuo dispositivo \u00e8 dotato dell&#8217;hardware necessario, puoi inviare messaggi da posizioni isolate prive di connessioni cellulari o Wi-Fi. Ci\u00f2 \u00e8 indubbiamente vantaggioso per i viaggiatori e per coloro che si trovano in aree con copertura di rete incoerente.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"406\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/TW-image9.webp\" title=\"\" width=\"404\"\/><figcaption>Fonte: Android<\/figcaption><\/figure>\n<h2><span id=\"9-App-Pairs-Instant-Multitasking-Done-Right\">9. Coppie di app: multitasking senza sforzo<\/span><\/h2>\n<p>Con l&#8217;introduzione di App Pairs, il multitasking diventa pi\u00f9 semplice in Android 15. Puoi salvare le tue combinazioni di schermo diviso preferite e accedervi con un singolo tocco. Questa funzionalit\u00e0 \u00e8 particolarmente utile per utilizzare due app contemporaneamente, eliminando la seccatura di dover configurare manualmente le viste divise ogni volta. Ad esempio, puoi visualizzare senza sforzo l&#8217;app YouTube insieme a Note per annotare le ricette.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122244-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122258-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"10-Always-on-Taskbar-for-Tablets-and-Foldables\">10. Barra delle applicazioni persistente per tablet e dispositivi pieghevoli<\/span><\/h2>\n<p>Se possiedi un tablet o un dispositivo pieghevole, apprezzerai la funzionalit\u00e0 &#8220;Mostra sempre la barra delle applicazioni&#8221; in Android 15. Ci\u00f2 mantiene la barra delle applicazioni sempre visibile, facilitando il cambio rapido delle app senza inutili scorrimenti. \u00c8 un fantastico risparmio di tempo per chi \u00e8 spesso multitasking e passa spesso da un&#8217;applicazione all&#8217;altra sui propri tablet.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1124\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/TW-1000000602.webp\" title=\"\" width=\"1084\"\/><\/figure>\n<h2><span id=\"11-Lock-Screen-Widgets-Are-Back\">11. Ritorno dei widget della schermata di blocco<\/span><\/h2>\n<p>Il ritorno dei widget della schermata di blocco in Android 15 consente agli utenti di accedere rapidamente alle informazioni. Che si tratti di aggiornamenti sul meteo, controlli musicali o la programmazione del calendario, l&#8217;interazione con questi widget \u00e8 possibile senza sbloccare il dispositivo, rendendo molto pi\u00f9 semplice rimanere informati.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"641\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/TW-Screenshot_20240912-145231-1024x641-1.webp\" title=\"\" width=\"1024\"\/><figcaption>Fonte: <a href=\"https:\/\/9to5google.com\/2024\/09\/12\/android-15-lock-screen-widgets-tablets-beta\/\">9to5Google<\/a><\/figcaption><\/figure>\n<h2><span id=\"12-Adaptive-Vibration\">12. Tecnologia di vibrazione adattiva<\/span><\/h2>\n<p>Con l&#8217;introduzione di Adaptive Vibration in Android 15, l&#8217;intensit\u00e0 delle vibrazioni si adatta in base alla superficie su cui si trova il telefono. Ad esempio, le vibrazioni saranno pi\u00f9 intense se posizionate su una superficie morbida e meno su una dura, assicurandoti di non perdere avvisi importanti indipendentemente dall&#8217;ambiente circostante.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122342-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"13-High-Quality-Webcam-Mode\">13. Funzionalit\u00e0 webcam di alta qualit\u00e0<\/span><\/h2>\n<p>Hai mai desiderato usare il tuo telefono come webcam? Android 15 ha introdotto una modalit\u00e0 Webcam di alta qualit\u00e0, migliorando significativamente la nitidezza del tuo video. Questo miglioramento ti far\u00e0 apparire molto meglio durante le riunioni o le videochiamate senza la necessit\u00e0 di applicazioni separate, consentendo al tuo telefono di fungere da valida alternativa alle webcam autonome.<\/p>\n<h2><span id=\"14-Switch-Keyboards-Faster-Than-Ever\">14. Cambio tastiera pi\u00f9 veloce<\/span><\/h2>\n<p>Passare da una tastiera all&#8217;altra non \u00e8 mai stato cos\u00ec facile con il rinnovato switcher di tastiera di Android 15. Ora puoi passare da un metodo di input all&#8217;altro con una sola pressione di un pulsante, semplificando l&#8217;uso di pi\u00f9 lingue o layout di tastiera. Questo design semplificato migliora l&#8217;esperienza utente consentendo regolazioni con meno tocchi.<\/p>\n<h2><span id=\"15-Updated-Volume-Panel\">15. Controllo del volume riprogettato<\/span><\/h2>\n<p>L&#8217;interfaccia di controllo del volume ha ricevuto un restyling. La nuova interfaccia utente vanta cursori pi\u00f9 spessi e animazioni migliorate, rendendo pi\u00f9 semplice la regolazione del volume per chiamate, musica o impostazioni di sveglia. Il pannello del volume aggiornato presenta anche una scorciatoia persistente per l&#8217;output multimediale per un accesso rapido.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122516-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122524-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122527-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"16-Sensitive-Notifications-That-Stay-Private\">16. Protezione delle notifiche sensibili<\/span><\/h2>\n<p>Android 15 migliora la privacy nascondendo notifiche sensibili come i codici di accesso monouso (OTP) da occhi indiscreti. Hai il controllo su quali app possono visualizzare il loro contenuto nella schermata di blocco, migliorando la gestione della privacy.<\/p>\n<h2><span id=\"17-Bluetooth-Auto-On\">17. Attivazione automatica Bluetooth<\/span><\/h2>\n<p>Una caratteristica preziosa di Android 15 \u00e8 l&#8217;attivazione automatica del Bluetooth il giorno seguente se lo hai disattivato. Ci\u00f2 migliora la reperibilit\u00e0 del tuo dispositivo tramite Trova il mio dispositivo, aumentando la probabilit\u00e0 di recuperarlo in caso di smarrimento. \u00c8 una caratteristica piccola ma di grande impatto per coloro che sono inclini a smarrire i propri dispositivi.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122558-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"18-Universal-Keyboard-Vibration-Control\">18. Impostazioni complete di vibrazione della tastiera<\/span><\/h2>\n<p>Android 15 consente agli utenti di gestire le impostazioni di vibrazione per tutte le tastiere da un&#8217;unica posizione. Non \u00e8 pi\u00f9 necessario regolare le impostazioni per ogni singola applicazione della tastiera: \u00e8 sufficiente un interruttore. Questa \u00e8 la soluzione ideale per gli utenti che desiderano un&#8217;esperienza di digitazione coerente su diverse tastiere.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122634-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"19-Home-Controls-Screensaver\">19. Funzione salvaschermo dei controlli domestici<\/span><\/h2>\n<p>Quando il telefono \u00e8 in carica, Android 15 visualizza scorciatoie per gestire direttamente i dispositivi Google Home, consentendo il controllo della tua smart home senza dover sbloccare il dispositivo. Questa funzionalit\u00e0 rende l&#8217;accesso agli strumenti di automazione domestica rapido e comodo.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"896\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/TW-Android_15_home_controls_screen_saver_on_phone.png-1024x896-1.webp\" title=\"\" width=\"1024\"\/><figcaption>Fonte: <a href=\"https:\/\/www.androidauthority.com\/android-15-home-controls-screensaver-3433352\/\">Android Authority<\/a><\/figcaption><\/figure>\n<h2><span id=\"20-Predictive-Back-Gesture\">20. Gesto predittivo migliorato per la schiena<\/span><\/h2>\n<p>Android 15 migliora il gesto indietro introducendo elementi visivi predittivi che indicano la schermata successiva quando si scorre indietro. Questa funzionalit\u00e0 riduce al minimo le uscite accidentali dalle app e semplifica la navigazione del telefono. Le animazioni raffinate migliorano anche l&#8217;esperienza complessiva, rendendola pi\u00f9 fluida e intuitiva.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122711-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241016-122812-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"21-Loudness-Control\">21. Funzione di gestione del volume<\/span><\/h2>\n<p>Per migliorare la tua esperienza audio, Android 15 lancia una nuova funzionalit\u00e0 di controllo del volume che aderisce allo <a href=\"https:\/\/android-developers.googleblog.com\/2024\/03\/the-second-developer-preview-of-android-15.html#:~:text=and%20HDR%20content.-,Loudness%20Control,-Android%2015%20introduces\" rel=\"noreferrer noopener\" target=\"_blank\">standard CTA-2075<\/a> . Ci\u00f2 garantisce che non ci siano bruschi cambiamenti di volume quando si passa da un&#8217;app o un media all&#8217;altro, offrendo un&#8217;esperienza di ascolto pi\u00f9 fluida e piacevole.<\/p>\n<h2><span id=\"22-Ultra-HDR-Photography\">22. Capacit\u00e0 di imaging Ultra HDR<\/span><\/h2>\n<p>Gli appassionati di fotografia adoreranno il supporto Ultra HDR di Android 15. Il nuovo formato JPEG_R cattura colori pi\u00f9 vivaci e un contrasto migliorato, migliorando il realismo delle tue foto, indipendentemente dal fatto che tu stia utilizzando la fotocamera anteriore o posteriore. Questa funzionalit\u00e0 rende la fotografia HDR pi\u00f9 accessibile e piacevole per tutti gli utenti.<\/p>\n<h2><span id=\"23-Default-Wallet-App\">23. Imposta la tua app Wallet predefinita<\/span><\/h2>\n<p>Android 15 ora consente agli utenti di designare un&#8217;app wallet predefinita, semplificando il processo di pagamento per transazioni pi\u00f9 rapide e senza problemi. Non \u00e8 pi\u00f9 necessario selezionare il wallet ogni volta che si effettua un pagamento.<\/p>\n<h2><span id=\"24-Better-Passkey-Management\">24. Gestione avanzata delle passkey<\/span><\/h2>\n<p>Con l&#8217;aumento dell&#8217;utilizzo delle passkey, Android 15 ne semplifica la gestione. Puoi visualizzare e supervisionare comodamente le tue passkey dalle impostazioni, migliorando il tuo controllo sulle informazioni di accesso. Ci\u00f2 rappresenta un passo avanti verso la creazione di un&#8217;esperienza senza password, rendendo pi\u00f9 semplice il mantenimento della sicurezza online.<\/p>\n<h2><span id=\"25-Rich-Widget-Previews\">25. Anteprime dei widget migliorate<\/span><\/h2>\n<p>Android 15 introduce anteprime avanzate per i widget, consentendo agli utenti di visualizzare in anteprima il contenuto di un widget prima di aggiungerlo alla schermata iniziale. Questa funzionalit\u00e0 consente di valutare se un widget soddisfa le proprie esigenze senza la necessit\u00e0 di tentativi ed errori. Mira a migliorare l&#8217;efficienza e l&#8217;aspetto visivo della configurazione della schermata iniziale.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/TW-1000000603-988x1024-1.webp\" title=\"\" width=\"988\"\/><\/figure>\n<h3>Caratteristiche aggiuntive<\/h3>\n<ul>\n<li><strong>Supporto Virtual MIDI 2.0<\/strong> : questa funzionalit\u00e0 consente l&#8217;uso di dispositivi Virtual MIDI 2.0, migliorando l&#8217;integrazione con gli strumenti di produzione musicale.<\/li>\n<li><strong>Aggiornamenti Health Connect<\/strong> : aggiunge i tipi di dati relativi alla temperatura della pelle e al piano di allenamento alle funzionalit\u00e0 Health Connect.<\/li>\n<li><strong>Controllo HDR Headroom<\/strong> : bilancia la luminosit\u00e0 tra i contenuti HDR e SDR per un&#8217;esperienza visiva migliorata.<\/li>\n<li><strong>Definizione aggiornata di ricarica rapida<\/strong> : in precedenza, la ricarica superiore a 7,5 W era considerata una ricarica rapida. Da Android 15 in poi, la ricarica rapida sar\u00e0 indicata solo per velocit\u00e0 superiori a 20 W.<\/li>\n<li><strong>Menu di gestione SIM<\/strong> : introduce una nuova interfaccia di gestione per semplificare le impostazioni della scheda SIM.<\/li>\n<li><strong>Miglioramenti della privacy Wi-Fi<\/strong> : aggiorna le impostazioni sulla privacy per offrire un controllo migliore sulle connessioni Wi-Fi.<\/li>\n<li><strong>Personalizzazione delle impostazioni dell&#8217;elenco delle app<\/strong> : consente agli utenti di modificare il modo in cui le app vengono visualizzate nel pannello delle app, incluse le opzioni per nomi di app pi\u00f9 lunghi.<\/li>\n<li><strong>Nuove opzioni di contrasto colore<\/strong> : regola il contrasto di testo, pulsanti e icone per una migliore visibilit\u00e0 nelle app.<\/li>\n<li><strong>Attiva\/disattiva suggerimenti app<\/strong> : offre la possibilit\u00e0 di impedire la visualizzazione di suggerimenti per app specifiche nell&#8217;area sopra il pannello delle app.<\/li>\n<\/ul>\n<blockquote class=\"wp-embedded-content\">\n<p>Elenco dei dispositivi Samsung Galaxy idonei per l&#8217;aggiornamento ad Android 15 (One UI 7)<\/p>\n<\/blockquote>\n<p><a class=\"xiaomi\" href=\"https:\/\/techwiser.com\/25-android-15-feature-you-need-to-know\/?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=25-android-15-feature-you-need-to-know\" rel=\"noopener norefferer nofollow\" target=\"_blank\">Fonte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google ha ufficialmente lanciato la versione pubblica di Android 15 , offrendo deliziosi miglioramenti che, pur non essendo rivoluzionari, sono sicuramente entusiasmanti. Attualmente, questo aggiornamento \u00e8 disponibile esclusivamente sui dispositivi Google Pixel, a partire da Pixel 6 e oltre, inclusi Pixel Fold e tablet. Gli utenti con un telefono Pixel compatibile possono iniziare a esplorare [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,305,266,19],"class_list":["post-4792","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-android-15","tag-features","tag-listicle"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/4792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=4792"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/4792\/revisions"}],"predecessor-version":[{"id":4793,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/4792\/revisions\/4793"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=4792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=4792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=4792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}