{"id":4816,"date":"2024-10-17T13:06:40","date_gmt":"2024-10-17T13:06:40","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=4816"},"modified":"2024-10-17T13:06:40","modified_gmt":"2024-10-17T13:06:40","slug":"guide-to-utilizing-private-space-on-pixel-smartphones","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/guide-to-utilizing-private-space-on-pixel-smartphones\/","title":{"rendered":"Guida all&#8217;utilizzo dello spazio privato sugli smartphone Pixel"},"content":{"rendered":"<p>Se vuoi proteggere i tuoi file sensibili o limitare l&#8217;accesso ad applicazioni specifiche, Android 15 introduce una funzionalit\u00e0 chiamata Spazio privato sui dispositivi Pixel. Immaginala come uno scomparto protetto all&#8217;interno del tuo smartphone in cui puoi archiviare in modo sicuro qualsiasi cosa, dai documenti finanziari alle applicazioni di incontri o diari personali.<\/p>\n<p>L&#8217;aspetto pi\u00f9 impressionante di Private Space \u00e8 il suo sistema di blocco indipendente. Anche se qualcuno conosce la password o il PIN del tuo dispositivo principale, non sar\u00e0 in grado di accedere al tuo Private Space.<\/p>\n<h2><span id=\"Whats-Private-Space\">Comprendere lo spazio privato<\/span><\/h2>\n<p>Con l&#8217;implementazione di Android 15, la funzionalit\u00e0 Private Space sui dispositivi Pixel consente agli utenti di stabilire un ambiente sicuro per l&#8217;installazione di app, l&#8217;archiviazione di file e la creazione di account separati: \u00e8 quasi come avere un telefono aggiuntivo direttamente sul dispositivo principale. \u00c8 l&#8217;ideale per mantenere la privacy di informazioni sensibili, applicazioni personali o account utente alternativi.<\/p>\n<p>Dopo averlo configurato, puoi trovare Private Space situato alla fine del tuo cassetto delle app. Basta toccare l&#8217; <strong>icona del lucchetto<\/strong> , inserire la password di Private Space e sarai pronto ad accedere alle tue applicazioni e ai tuoi file riservati. Ecco i passaggi per iniziare a usare Private Space sul tuo dispositivo Pixel.<\/p>\n<h2><span id=\"How-to-Set-Up-and-Use-Private-Space\">Impostazione e utilizzo dello spazio privato<\/span><\/h2>\n<p>Prima di immergerti, assicurati che il tuo Pixel sia aggiornato ad Android 15 o pi\u00f9 recente e che abbia meno di quattro profili attivati. Private Space \u00e8 pensato per l&#8217;utente principale e non \u00e8 supportato su dispositivi gestiti o aziendali. Inoltre, si consiglia di avere almeno 6 GB di RAM sullo smartphone.<\/p>\n<p>Ecco come creare il tuo Spazio Privato su un dispositivo Pixel:<\/p>\n<ol>\n<li>Vai su <strong>Impostazioni &gt; Sicurezza e privacy &gt; Spazio privato<\/strong> . Fai clic su <strong>Configura<\/strong> e segui le istruzioni.<\/li>\n<li>Utilizza il blocco schermo del tuo dispositivo per dare il via alle cose. Si consiglia di utilizzare un account Google diverso per Private Space per impedire la sincronizzazione dei tuoi file privati \u200b\u200bcon il tuo account principale, riducendo al minimo il rischio di esposizione accidentale. Puoi <strong>effettuare l&#8217;accesso con un account distinto<\/strong> o <strong>crearne uno<\/strong> durante questo processo.<\/li>\n<li>Imposta un <strong>nuovo blocco o impronte digitali<\/strong> appositamente per lo Spazio Privato.<\/li>\n<li>Una volta terminata la configurazione, vedrai <strong>Private Space<\/strong> in fondo al tuo cassetto delle app, indicato da <strong>un&#8217;icona a forma di lucchetto<\/strong> . Cliccaci sopra per entrare.<\/li>\n<\/ol>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-163918-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-163944-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164004-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164049-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164109-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164120-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<p>Nella sezione Spazio privato del cassetto delle app, tocca <strong>Impostazioni<\/strong> per modificare le tue preferenze e personalizzare la tua esperienza. Le opzioni sono accessibili anche tramite <strong>Impostazioni di sistema<\/strong> . Di seguito sono riportate le personalizzazioni disponibili:<\/p>\n<ul>\n<li><strong>Tempo di blocco<\/strong> : configura lo Spazio privato in modo che si blocchi automaticamente dopo 5 minuti di inattivit\u00e0 o quando il dispositivo stesso si blocca.<\/li>\n<li><strong>Tipo di blocco<\/strong> : modifica il metodo di blocco, la password o il PIN in base alle tue esigenze.<\/li>\n<li><strong>Nascondi Spazio Privato<\/strong> : di default, Spazio Privato viene visualizzato in fondo al tuo cassetto delle app. Hai la possibilit\u00e0 di nasconderlo completamente. Se \u00e8 nascosto, dovrai cercare Spazio Privato nella funzione di ricerca del cassetto delle app per accedervi.<\/li>\n<li><strong>Elimina spazio privato<\/strong> : questo pu\u00f2 essere fatto sia dalle impostazioni dello spazio privato che dalle pi\u00f9 ampie impostazioni di sistema. Tieni presente che l&#8217;eliminazione \u00e8 irreversibile e comporta la perdita di tutti i dati archiviati.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164206-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164215-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164221-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164237-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"Using-Private-Space-on-Your-Pixel\">Come utilizzare lo spazio privato sul tuo dispositivo Pixel<\/span><\/h2>\n<p><strong>Installazione dell&#8217;app<\/strong> :<\/p>\n<p>Puoi installare facilmente le app all&#8217;interno di Private Space usando la sua versione dedicata del Play Store. In alternativa, puoi trasferire le applicazioni dallo spazio principale premendo a lungo l&#8217;app e selezionando <strong>Installa in privato<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164215-1-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164307-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<p><strong>Gestione file e dati<\/strong> :<\/p>\n<p>I file scaricati o gli screenshot acquisiti all&#8217;interno di Private Space vengono archiviati esclusivamente in quell&#8217;ambiente e non si mescoleranno ai dati del tuo profilo principale. Inoltre, \u00e8 possibile selezionare i file nell&#8217;app Files dello spazio principale e condividerli con il tuo Private Space.<\/p>\n<p><strong>Stato quando bloccato<\/strong> :<\/p>\n<p>Ogni volta che Private Space \u00e8 bloccato, tutte le applicazioni in quello spazio vengono sospese, il che significa che non si verificheranno notifiche o attivit\u00e0 in background e quelle app non appariranno nell&#8217;elenco delle app recenti. Ci\u00f2 garantisce che i tuoi dati rimangano riservati.<\/p>\n<p><strong>Stato quando sbloccato<\/strong> :<\/p>\n<p>Dopo aver sbloccato Private Space, le app riprendono la normale funzione e le voci appariranno nelle app recenti. Puoi condividere app e file solo dallo spazio principale mentre Private Space \u00e8 sbloccato. Saranno visibili anche le notifiche, contrassegnate con un&#8217;icona a forma di lucchetto per indicare che provengono da Private Space.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/10\/Screenshot_20241017-164326-461x1024-1.webp\" title=\"\" width=\"461\"\/><\/figure>\n<h2><span id=\"Limitations-of-Private-Space\">Vincoli dello spazio privato<\/span><\/h2>\n<p><strong>Accesso tramite computer<\/strong> :<\/p>\n<p>Tieni presente che puoi accedere allo Spazio Privato tramite ADB (Android Debug Bridge) o tramite i registri del dispositivo se lo smartphone \u00e8 connesso a un computer.<\/p>\n<p><strong>Limitazioni VPN<\/strong> :<\/p>\n<p>Le applicazioni in esecuzione in Private Space bypassano qualsiasi connessione VPN attiva, il che potrebbe rappresentare una lacuna se desideri la privacy totale. Anche installare un&#8217;app VPN in Private Space non sar\u00e0 utile.<\/p>\n<p><strong>Nessun widget o scorciatoia<\/strong> :<\/p>\n<p>Non \u00e8 possibile aggiungere widget o scorciatoie per le applicazioni all&#8217;interno di Private Space. Non esiste una schermata iniziale unica per questa funzionalit\u00e0.<\/p>\n<p><strong>Limitazioni aggiuntive<\/strong> :<\/p>\n<p>Funzioni come Quick Share, Find My Device e profili di lavoro non sono disponibili in Private Space. Inoltre, non puoi associare o gestire dispositivi smart home. Tuttavia, le app in Private Space possono accedere a Bluetooth e Wi-Fi, quindi la connettivit\u00e0 Internet e l&#8217;utilizzo di accessori Bluetooth come Pixel Buds rimangono inalterati.<\/p>\n<h2><span id=\"Private-Space-on-Android-15\">Panoramica dello spazio privato su Android 15<\/span><\/h2>\n<p>Private Space \u00e8 accessibile solo ai dispositivi con Android 15 o versioni successive. Per gli utenti con versioni Android precedenti, creare un profilo secondario pu\u00f2 aiutare a proteggere le applicazioni e le informazioni private. Tuttavia, questa alternativa non offre un&#8217;integrazione fluida e la possibilit\u00e0 di condividere tra spazi primari e privati. Tuttavia, utilizzare un account secondario \u00e8 generalmente una strategia migliore rispetto all&#8217;impiego di qualsiasi applicazione di terze parti.<\/p>\n<blockquote class=\"wp-embedded-content\">\n<p>25+ funzionalit\u00e0 di Android 15 che devi conoscere<\/p>\n<\/blockquote>\n<p><a class=\"xiaomi\" href=\"https:\/\/techwiser.com\/how-to-use-private-space-on-pixel-phones\/?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=how-to-use-private-space-on-pixel-phones\" rel=\"noopener norefferer nofollow\" target=\"_blank\">Fonte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se vuoi proteggere i tuoi file sensibili o limitare l&#8217;accesso ad applicazioni specifiche, Android 15 introduce una funzionalit\u00e0 chiamata Spazio privato sui dispositivi Pixel. Immaginala come uno scomparto protetto all&#8217;interno del tuo smartphone in cui puoi archiviare in modo sicuro qualsiasi cosa, dai documenti finanziari alle applicazioni di incontri o diari personali. L&#8217;aspetto pi\u00f9 impressionante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,305,138,36],"class_list":["post-4816","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-android","tag-android-15","tag-pixel","tag-privacy"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/4816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=4816"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/4816\/revisions"}],"predecessor-version":[{"id":4817,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/4816\/revisions\/4817"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=4816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=4816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=4816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}