{"id":512,"date":"2024-01-01T10:00:43","date_gmt":"2024-01-01T10:00:43","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=512"},"modified":"2024-01-01T10:00:43","modified_gmt":"2024-01-01T10:00:43","slug":"how-to-get-clippy-ai-on-windows-11-chatgpt-powered-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/how-to-get-clippy-ai-on-windows-11-chatgpt-powered-it\/","title":{"rendered":"Come ottenere Clippy AI su Windows 11 (alimentato da ChatGPT)"},"content":{"rendered":"<p>Potresti conoscere Clippy se sei un utente Windows da molto tempo. Clippy era l&#8217;assistente virtuale presente nella suite Microsoft Office tra la fine degli anni &#8217;90 e l&#8217;inizio degli anni 2000. L&#8217;assistente virtuale ha dato suggerimenti sull&#8217;utilizzo del software Microsoft Office.<\/p>\n<p>Tuttavia, dopo alcuni anni, Clippy fu rimosso perch\u00e9 ricevette molto odio da parte degli utenti. Ci\u00f2 che effettivamente suscit\u00f2 critiche e allontan\u00f2 le persone da Clippy fu la sua invasivit\u00e0.<\/p>\n<p>Parliamo di Clippy perch\u00e9 \u00e8 tornato su Windows 11, anche se non ufficialmente, con una nuova app tramite Microsoft Store. La nuova app Clippy AI proviene da Firecube Studios e ti ricorda i vecchi tempi in cui utilizzavamo Microsoft Office su Windows XP.<\/p>\n<h3><span id=\"Clippy_AI_Download_for_Windows\"><strong>Scarica Clippy AI per Windows<\/strong><\/span><\/h3>\n<p>Prima di procedere e scaricare Cippy AI su Windows 11, \u00e8 importante sapere cosa fa il nuovo assistente Clippy. Fondamentalmente, l&#8217;app Clippy di terze parti \u00e8 molto simile a Windows Copilot.<\/p>\n<p>Clippy AI porta ChatGPT direttamente sullo schermo del tuo desktop. Puoi vedere l&#8217;icona della graffetta della vecchia scuola, che rimane fissata sullo schermo; puoi utilizzare la graffetta per un rapido accesso al chatbot AI o lasciarla cos\u00ec com&#8217;\u00e8 per nostalgia.<\/p>\n<p>Clippy o Paperclip di FireCube \u00e8 basato sul modello OpenAI GPT 3.5 e puoi ottenerlo gratuitamente da Microsoft Store.<\/p>\n<h2><span id=\"How_to_Download_Install_Clippy_AI_on_Windows_11\"><strong>Come scaricare &amp; Installare Clippy AI su Windows 11?<\/strong><\/span><\/h2>\n<p>Ora che sai cos&#8217;\u00e8 Clippy AI, potresti provare questa nuova app. Segui i passaggi che abbiamo condiviso di seguito per scaricare &amp; installa l&#8217;app Clippy AI su Windows 11.<\/p>\n<p>1. Digita Microsoft Store su Windows 11 Cerca. Successivamente, apri l&#8217;<strong>app Microsoft Store<\/strong> nell&#8217;elenco.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Applicazione Microsoft Store\" class=\"wp-image\" decoding=\"async\" height=\"657\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-1.webp\" title=\"Applicazione Microsoft Store\" width=\"700\"\/><\/figure>\n<p>2. Quando si apre Microsoft Store, cerca <strong><a data-wpel-link=\"external\" href=\"https:\/\/apps.microsoft.com\/detail\/9NWK37S35V5T?hl=en-us&amp;gl=US\" rel=\"noopener nofollow external noreferrer\" target=\"_blank\">Paperclip <\/a>di Firecube.<\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Graffetta per fogli\" class=\"wp-image\" decoding=\"async\" height=\"607\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-2.webp\" title=\"Graffetta per fogli\" width=\"800\"\/><\/figure>\n<p>3. Apri l&#8217;app pertinente dai risultati di ricerca di Microsoft Store e fai clic su <strong>Ottieni<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Ottenere\" class=\"wp-image\" decoding=\"async\" height=\"532\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-3.webp\" title=\"Ottenere\" width=\"700\"\/><\/figure>\n<p>4. Ora, <strong>attendi qualche secondo<\/strong> affinch\u00e9 l&#8217;app venga installata sul tuo computer.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"attendere qualche secondo\" class=\"wp-image\" decoding=\"async\" height=\"538\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-4.webp\" title=\"attendere qualche secondo\" width=\"700\"\/><\/figure>\n<p>5. Una volta installata, avvia l&#8217;app. Ora troverai Clippy nell&#8217;angolo in basso a destra dello schermo.<\/p>\n<h3><span id=\"Get_the_OpenAI_API_Key\"><strong>Ottieni la chiave API OpenAI<\/strong><\/span><\/h3>\n<p>Se desideri utilizzare il chatbot AI, devi prendere la chiave API OpenAI. Ecco come puoi ottenere la chiave API da OpenAI.<\/p>\n<p>1. Apri questo collegamento e accedi al tuo account OpenAI.<\/p>\n<p>2. Dopo aver effettuato l&#8217;accesso al tuo account OpenAI, fai clic sul tuo profilo nell&#8217;angolo in alto a destra. Oppure apri direttamente questa <strong><a data-wpel-link=\"external\" href=\"https:\/\/platform.openai.com\/api-keys\" rel=\"noopener nofollow external noreferrer\" target=\"_blank\">pagina<\/a><\/strong>.<\/p>\n<p>3. Nel menu visualizzato, seleziona <strong>Visualizza chiavi API<\/strong>.<\/p>\n<p>4. Nelle chiavi API, fai clic su <strong>Crea nuova chiave segreta<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Crea una nuova chiave segreta\" class=\"wp-image\" decoding=\"async\" height=\"577\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Get-the-OpenAI-API-Key-1.webp\" title=\"Crea una nuova chiave segreta\" width=\"800\"\/><\/figure>\n<p>5. Ora otterrai la chiave API; <strong>copialo<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"copialo\" class=\"wp-image\" decoding=\"async\" height=\"354\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Get-the-OpenAI-API-Key-3.webp\" title=\"copialo\" width=\"640\"\/><\/figure>\n<h3><span id=\"How_to_Chat_with_Clippy_AI\"><strong>Come chattare con Clippy AI?<\/strong><\/span><\/h3>\n<p>Ora che hai la chiave API di OpenAI, \u00e8 il momento di aggiungere le chiavi all&#8217;app Clippy AI. Ecco cosa devi fare.<\/p>\n<p>1. Per utilizzare il chatbot AI, fai clic con il pulsante destro del mouse sull&#8217;<strong>graffetta<\/strong> <strong>icona<\/strong> nella barra delle applicazioni.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Graffetta per fogli\" class=\"wp-image\" decoding=\"async\" height=\"258\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-Chat-1.webp\" title=\"Graffetta per fogli\" width=\"600\"\/><\/figure>\n<p>2. In Impostazioni,<strong> incolla la chiave API OpenAI<\/strong> e fai clic su <strong>Salva<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"incolla la chiave API OpenAI\" class=\"wp-image\" decoding=\"async\" height=\"550\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-Chat-2.webp\" title=\"incolla la chiave API OpenAI\" width=\"900\"\/><\/figure>\n<p>3. Ora fai clic su Clippy\/Paperclip e fai domande. Questo \u00e8 essenzialmente un ChatGPT direttamente sullo schermo del tuo desktop.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Clippy\/Paperclip e fai domande\" class=\"wp-image\" decoding=\"async\" height=\"597\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clippy-AI-Chat-4.webp\" title=\"Clippy\/Paperclip e fai domande\" width=\"600\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ecco come puoi ottenere Clippy AI basato su ChatGPT su un computer Windows 11.<\/p>\n<p>Quindi, questa guida spiega come ottenere la nuova Clippy AI sui computer Windows 11. Facci sapere se hai bisogno di ulteriore aiuto per utilizzare questa nuova app sul tuo computer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Potresti conoscere Clippy se sei un utente Windows da molto tempo. Clippy era l&#8217;assistente virtuale presente nella suite Microsoft Office tra la fine degli anni &#8217;90 e l&#8217;inizio degli anni 2000. L&#8217;assistente virtuale ha dato suggerimenti sull&#8217;utilizzo del software Microsoft Office. Tuttavia, dopo alcuni anni, Clippy fu rimosso perch\u00e9 ricevette molto odio da parte degli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-512","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=512"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/512\/revisions"}],"predecessor-version":[{"id":513,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/512\/revisions\/513"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}