{"id":514,"date":"2024-01-01T10:03:07","date_gmt":"2024-01-01T10:03:07","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=514"},"modified":"2024-01-01T10:03:07","modified_gmt":"2024-01-01T10:03:07","slug":"middle-mouse-button-not-working-on-youtube-9-ways-to-fix-it-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/middle-mouse-button-not-working-on-youtube-9-ways-to-fix-it-it\/","title":{"rendered":"Il pulsante centrale del mouse non funziona su YouTube? 9 modi per risolverlo"},"content":{"rendered":"<p>Il mouse e la tastiera sono i due componenti hardware pi\u00f9 cruciali di un computer, poich\u00e9 senza di essi non \u00e8 possibile utilizzare il computer desktop. Recentemente, molti utenti hanno riscontrato problemi durante l&#8217;utilizzo del mouse su sistemi basati su Windows.<\/p>\n<p>Gli utenti hanno affermato che la funzione di clic centrale del mouse non funziona durante la visione di video di YouTube. Quindi, se YouTube \u00e8 il tuo sito di riferimento per guardare video e sei frustrato a causa dell&#8217;impossibilit\u00e0 di utilizzare la funzione di clic centrale del mouse, continua a leggere la guida.<\/p>\n<p>In questo articolo discuteremo alcuni modi migliori per risolvere il problema con il pulsante centrale del mouse che non funziona su YouTube. Iniziamo.<\/p>\n<h2><span id=\"Middle_Mouse_Button_Not_Working_on_YouTube_9_Ways_to_Fix_it\"><strong>Il pulsante centrale del mouse non funziona su YouTube? 9 modi per risolverlo<\/strong><\/span><\/h2>\n<p>Il pulsante centrale del mouse che non funziona su YouTube di solito \u00e8 un segno di un componente hardware difettoso o di un problema con il browser web. Poich\u00e9 il motivo effettivo non \u00e8 chiaro, dovremo eseguire una serie di procedure di risoluzione dei problemi per risolverlo.<\/p>\n<h3><span id=\"1_Restart_the_Web_Browser\"><strong>1. Riavviare il browser Web<\/strong><\/span><\/h3>\n<p>Che si tratti del browser Google Chrome o Microsoft Edge, dovresti riavviare il browser web se il pulsante centrale del mouse funziona su altri siti ma non su YouTube.<\/p>\n<p>Il pulsante centrale del mouse che non funziona su YouTube di solito \u00e8 un segno di un bug o di un problema tecnico, che verr\u00e0 risolto con un semplice riavvio del browser.<\/p>\n<p>Chiudi il browser web e riaprilo. Una volta aperto, visita YouTube.com e prova nuovamente il pulsante centrale del mouse.<\/p>\n<h3><span id=\"2_Restart_your_computer\"><strong>2. Riavvia il computer<\/strong><\/span><\/h3>\n<figure class=\"wp-block-image\"><img alt=\"Riavvia il tuo computer\" class=\"wp-image\" decoding=\"async\" height=\"571\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Restart-your-computer-1.webp\" title=\"Riavvia il tuo computer\" width=\"600\"\/><\/figure>\n<p>Se il riavvio del browser web non ha risolto il problema, puoi provare a riavviare il computer. Il riavvio del computer potrebbe rimuovere tutti i bug e i problemi. problemi che potrebbero interferire con la funzione di clic centrale del mouse.<\/p>\n<p>Pertanto, prima di provare i successivi suggerimenti per la risoluzione dei problemi, \u00e8 meglio riavviare il computer Windows. Basta fare clic sul pulsante Start di Windows e fare clic sul menu Alimentazione. Nelle opzioni del menu Alimentazione, seleziona Riavvia.<\/p>\n<p>Dopo il riavvio, visita YouTube.com e controlla se il pulsante centrale del mouse funziona.<\/p>\n<h3><span id=\"3_Check_Whether_the_Middle_Mouse_Button_is_Working\"><strong>3. Controlla se il pulsante centrale del mouse funziona<\/strong><\/span><\/h3>\n<p>Se il pulsante centrale del mouse continua a non funzionare, \u00e8 importante verificare se il mouse funziona correttamente. Per iniziare, controlla i problemi hardware e cerca i difetti fisici.<\/p>\n<p>Se tutto va bene, controlla il cavo che collega il mouse al PC. Puoi collegare qualsiasi mouse di riserva al tuo computer e verificare se il clic centrale funziona.<\/p>\n<p>In alternativa, puoi collegare il mouse problematico a qualsiasi altro computer e verificare se funziona. Se il mouse non funziona anche su altri computer, dovrai sostituire il mouse. L&#8217;obiettivo finale \u00e8 confermare che il problema non riguarda il mouse.<\/p>\n<h3><span id=\"4_Run_the_Hardware_Devices_Troubleshooter\"><strong>4. Esegui il programma Hardware &amp; Risoluzione dei problemi dei dispositivi<\/strong><\/span><\/h3>\n<p>Molti utenti di Microsoft Store hanno affermato di aver risolto il problema con il pulsante centrale del mouse che non funzionava sul problema di YouTube semplicemente eseguendo lo strumento di risoluzione dei problemi hardware. Quindi, puoi provare a farlo anche tu. Ecco cosa devi fare.<\/p>\n<p>1. Digita PowerShell nella ricerca di Windows. Successivamente, fai clic con il pulsante destro del mouse sull&#8217;utilit\u00e0 <strong>PowerShell<\/strong> e seleziona <strong>Esegui come amministratore<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui come amministratore\" class=\"wp-image\" decoding=\"async\" height=\"553\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/PowerShell-11.webp\" title=\"Esegui come amministratore\" width=\"640\"\/><\/figure>\n<p>2. Quando si apre l&#8217;utilit\u00e0 PowerShell, eseguire questo comando:<\/p>\n<p> <code><strong>msdt.exe -id DeviceDiagnostic<\/strong><\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"msdt.exe -id DeviceDiagnostic\" class=\"wp-image\" decoding=\"async\" height=\"306\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/PowerShell-1.webp\" title=\"msdt.exe -id DeviceDiagnostic\" width=\"800\"\/><\/figure>\n<p>3. Verr\u00e0 avviato lo strumento di risoluzione dei problemi hardware e dispositivi. Fai clic su <strong>Avanti<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Prossimo\" class=\"wp-image\" decoding=\"async\" height=\"388\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/PowerShell-2.webp\" title=\"Prossimo\" width=\"500\"\/><\/figure>\n<p>4. Ora, <strong>segui le istruzioni visualizzate sullo schermo<\/strong> per completare il processo di risoluzione dei problemi hardware.<\/p>\n<p>Questo \u00e8 tutto! Ecco come puoi risolvere il problema del mancato funzionamento del pulsante centrale del mouse eseguendo l&#8217;hardware &amp; strumento di risoluzione dei problemi dei dispositivi.<\/p>\n<h3><span id=\"5_Update_the_Mouse_Drivers\"><strong>5. Aggiorna i driver del mouse<\/strong><\/span><\/h3>\n<p>I driver del mouse obsoleti sono un altro motivo importante per cui il clic centrale del mouse non funziona sul problema di YouTube. In questo metodo, \u00e8 necessario aggiornare i driver del mouse su Windows tramite Gestione dispositivi. Ecco cosa devi fare.<\/p>\n<p>1. Digita Gestione dispositivi nella ricerca di Windows. Successivamente, apri l&#8217;app <strong>Gestione dispositivi<\/strong> nell&#8217;elenco.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Gestore dispositivi\" class=\"wp-image\" decoding=\"async\" height=\"518\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-1.webp\" title=\"Gestore dispositivi\" width=\"600\"\/><\/figure>\n<p>2. Quando si apre Gestione dispositivi, espandere Mouse e altri dispositivi di puntamento.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Mouse e altri dispositivi di puntamento\" class=\"wp-image\" decoding=\"async\" height=\"470\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-2.webp\" title=\"Mouse e altri dispositivi di puntamento\" width=\"640\"\/><\/figure>\n<p>3. Fai clic con il pulsante destro del mouse sul mouse collegato e seleziona <strong>Aggiorna driver<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Aggiorna driver\" class=\"wp-image\" decoding=\"async\" height=\"466\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-3.webp\" title=\"Aggiorna driver\" width=\"640\"\/><\/figure>\n<p>4. Nella richiesta visualizzata, seleziona <strong>Cerca automaticamente conducenti<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cerca automaticamente i conducenti\" class=\"wp-image\" decoding=\"async\" height=\"468\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-4.webp\" title=\"Cerca automaticamente i conducenti\" width=\"640\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ora Windows controller\u00e0 automaticamente la versione pi\u00f9 recente dei driver del mouse e scaricher\u00e0 &amp; installarlo.<\/p>\n<h3><span id=\"6_Reinstall_the_Mouse\"><strong>6. Reinstallare il mouse<\/strong><\/span><\/h3>\n<p>Se l&#8217;aggiornamento dei driver del mouse non ha funzionato, puoi provare a reinstallare il mouse da Gestione dispositivi. Ecco cosa devi fare.<\/p>\n<p>1. Digita Gestione dispositivi nella ricerca di Windows. Successivamente, apri l&#8217;app <strong>Gestione dispositivi<\/strong> nell&#8217;elenco.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Gestore dispositivi\" class=\"wp-image\" decoding=\"async\" height=\"518\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-1-1.webp\" title=\"Gestore dispositivi\" width=\"600\"\/><\/figure>\n<p>2. Quando si apre Gestione dispositivi, espandi<strong> Mouse e altri dispositivi di puntamento<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Mouse e altri dispositivi di puntamento\" class=\"wp-image\" decoding=\"async\" height=\"470\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-2-1.webp\" title=\"Mouse e altri dispositivi di puntamento\" width=\"640\"\/><\/figure>\n<p>3. Fai clic con il pulsante destro del mouse sul mouse collegato e seleziona<strong>Disinstalla dispositivo<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Mouse e seleziona Disinstalla dispositivo\" class=\"wp-image\" decoding=\"async\" height=\"468\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-5.webp\" title=\"Mouse e seleziona Disinstalla dispositivo\" width=\"640\"\/><\/figure>\n<p>4. Alla richiesta di disinstallazione del dispositivo, seleziona <strong>Disinstalla<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Disinstallare\" class=\"wp-image\" decoding=\"async\" height=\"467\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Reinstall-the-Mouse-Drivers-6.webp\" title=\"Disinstallare\" width=\"640\"\/><\/figure>\n<p>Questo \u00e8 tutto! Dopo la disinstallazione, riavvia il computer. Windows installer\u00e0 di nuovo automaticamente il mouse.<\/p>\n<h3><span id=\"7_Update_your_Web_Browser\"><strong>7. Aggiorna il tuo browser web<\/strong><\/span><\/h3>\n<figure class=\"wp-block-image\"><img alt=\"\" class=\"wp-image\" decoding=\"async\" height=\"247\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Update-chrome.webp\" title=\"\" width=\"600\"\/><\/figure>\n<p>Un altro motivo importante che fa s\u00ec che il clic centrale non funzioni su YouTube sono i problemi di compatibilit\u00e0. Se il tuo browser non \u00e8 compatibile con le funzioni del clic centrale, dovrai affrontare questi problemi.<\/p>\n<p>Sebbene i browser Web moderni come Chrome, Edge supporti immediatamente le funzioni di clic centrale, \u00e8 comunque consigliabile aggiornare il browser Web alla versione pi\u00f9 recente.<\/p>\n<p>Mantenere aggiornato il browser non solo apporta importanti patch di sicurezza ma introduce anche nuove funzionalit\u00e0. Quindi, se utilizzi Google Chrome, vai su Impostazioni &gt; Informazioni su Chrome per aggiornare il browser.<\/p>\n<h3><span id=\"8_Disable_the_Browser_Extensions\"><strong>8. Disabilitare le estensioni del browser<\/strong><\/span><\/h3>\n<figure class=\"wp-block-image\"><img alt=\"abilitare\/disabilitare l'estensione\" class=\"wp-image\" decoding=\"async\" height=\"383\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Disable-the-Chrome-Extensions-3.webp\" title=\"abilitare\/disabilitare l'estensione\" width=\"600\"\/><\/figure>\n<p>Se il pulsante centrale del mouse non funziona solo su YouTube, devi effettuare un controllo incrociato di tutte le estensioni installate sul tuo browser.<\/p>\n<p>\u00c8 possibile che alcune estensioni impediscano il corretto funzionamento del pulsante centrale del mouse.<\/p>\n<p>Quindi, apri Extension Manager del tuo browser web e disabilita tutte le estensioni una per una. Una volta disabilitato, prova ad accedere nuovamente a YouTube; le funzioni del clic centrale dovrebbero funzionare ora.<\/p>\n<h3><span id=\"9_Clear_Browser_Cache_And_Cookies\"><strong>9. Cancella cache e cookie del browser<\/strong><\/span><\/h3>\n<p>Se il pulsante centrale del mouse continua a non funzionare nonostante tutti i metodi sopra menzionati, \u00e8 ora di svuotare la cache del browser e svuotare la cache. biscotti.<\/p>\n<p>Se utilizzi Google Chrome e ritieni che il browser presenti problemi specifici, puoi provare a svuotare la cache e amp; biscotti. Ecco cosa devi fare.<\/p>\n<p>1. Fai clic sui tre punti nell&#8217;angolo in alto a destra. Nel menu visualizzato, seleziona <strong>Impostazioni<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Impostazioni\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Settings-1.webp\" title=\"Impostazioni\" width=\"317\"\/><\/figure>\n<p>2. Nella pagina Impostazioni, fai clic su<strong> Privacy e sicurezza<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Privacy e sicurezza\" class=\"wp-image\" decoding=\"async\" height=\"392\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Privacy-and-Security.webp\" title=\"Privacy e sicurezza\" width=\"351\"\/><\/figure>\n<p>3. Sul lato destro, fai clic su <strong>Cancella dati di navigazione<\/strong>.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cancella dati di navigazione\" class=\"wp-image\" decoding=\"async\" height=\"437\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clear-Browsing-Cache-1.webp\" title=\"Cancella dati di navigazione\" width=\"600\"\/><\/figure>\n<p>4. Alla richiesta Cancella dati di navigazione, seleziona <strong>Tutto il tempo<\/strong> su Intervallo di tempo, controlla <strong>Cookie e altri dati collaterali<\/strong>.<strong>Cancella dati<\/strong>. Una volta terminato, fai clic su <strong>Immagini e file memorizzati nella cache<\/strong>, <strong><\/strong><\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cancella i dati\" class=\"wp-image\" decoding=\"async\" height=\"500\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/01\/Clear-Browsing-Cache-2.webp\" title=\"Cancella i dati\" width=\"417\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ecco come puoi svuotare la cache del browser Chrome per risolvere i problemi relativi al mouse su YouTube.<\/p>\n<p>Quindi, questa guida riguarda la risoluzione del problema del pulsante centrale del mouse che non funziona sul problema di YouTube. Facci sapere se hai bisogno di ulteriore aiuto per risolvere questo problema sul tuo computer. Inoltre, se questo articolo ti ha aiutato a risolvere il problema, condividilo con i tuoi amici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il mouse e la tastiera sono i due componenti hardware pi\u00f9 cruciali di un computer, poich\u00e9 senza di essi non \u00e8 possibile utilizzare il computer desktop. Recentemente, molti utenti hanno riscontrato problemi durante l&#8217;utilizzo del mouse su sistemi basati su Windows. Gli utenti hanno affermato che la funzione di clic centrale del mouse non funziona [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-514","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/514\/revisions"}],"predecessor-version":[{"id":515,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/514\/revisions\/515"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}