{"id":8119,"date":"2025-02-05T10:35:25","date_gmt":"2025-02-05T10:35:25","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=8119"},"modified":"2025-02-05T10:35:25","modified_gmt":"2025-02-05T10:35:25","slug":"fixing-errorwaslocked-717-0x2cd-on-windows-a-comprehensive-guide","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/fixing-errorwaslocked-717-0x2cd-on-windows-a-comprehensive-guide\/","title":{"rendered":"Correzione di ERROR_WAS_LOCKED 717 (0x2CD) su Windows: una guida completa"},"content":{"rendered":"<p>Incontrare l&#8217;ERROR_WAS_LOCKED, noto anche come errore di sistema Windows 717, pu\u00f2 essere piuttosto frustrante. Questo errore indica che \u00e8 stato effettuato un tentativo di bloccare una pagina in memoria che \u00e8 gi\u00e0 bloccata, spesso a causa di file di sistema corrotti, applicazioni in conflitto o persino RAM difettosa.<\/p>\n<p>Il messaggio di errore esatto recita: {Pagina bloccata} Una delle pagine da bloccare era gi\u00e0 bloccata, il che segnala un problema di fondo che richiede la tua attenzione.<\/p>\n<p>Prima di immergerti in soluzioni dettagliate, \u00e8 consigliabile riavviare il PC, assicurarsi che tutti gli aggiornamenti Windows e le installazioni software in sospeso siano completati ed eseguire una scansione completa del sistema per rilevare malware. Sorprendentemente, questi semplici passaggi risolvono questo problema per molti utenti!<\/p>\n<h2 id=\"h-how-can-i-fix-error-was-locked-in-windows\">Modi per risolvere ERROR_WAS_LOCKED in Windows<\/h2>\n<h3 id=\"h-1-repair-the-system-files\">1. Riparare i file di sistema danneggiati<\/h3>\n<ol>\n<li>Premere <kbd>Windows<\/kbd>+ <kbd>S<\/kbd>per aprire lo strumento di ricerca, digitare <strong>Prompt dei comandi<\/strong> e selezionare &#8220;Esegui come amministratore&#8221;.<\/li>\n<li>Confermare eventuali richieste di Controllo dell&#8217;account utente (UAC) facendo clic su <strong>S\u00ec<\/strong>.<\/li>\n<li>Immettere i seguenti comandi in sequenza, premendo <kbd>Enter<\/kbd>dopo ciascuno:  <code><strong>DISM \/Online \/Cleanup-Image \/CheckHealth<\/strong><\/code>, <code><strong>DISM \/Online \/Cleanup-Image \/ScanHealth<\/strong><\/code>, <code><strong>DISM \/Online \/Cleanup-Image \/RestoreHealth<\/strong><\/code>.<\/li>\n<li>Quindi, eseguire questo comando di scansione SFC: <code><strong>sfc \/scannow<\/strong><\/code><img alt=\"scansione sfc per correggere ERROR_WAS_LOCKED\" class=\"wp-image\" decoding=\"async\" height=\"622\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/sfc-scan-1.webp\" title=\"scansione sfc per correggere ERROR_WAS_LOCKED\" width=\"1025\"\/><\/li>\n<li>Riavviare il computer per rendere effettive le modifiche.<\/li>\n<\/ol>\n<p>I file di sistema corrotti sono la causa principale dell&#8217;errore ERROR_WAS_LOCKED. L&#8217;utilizzo delle scansioni DISM e SFC ripara questi file danneggiati sostituendoli con le loro versioni memorizzate nella cache, un passaggio cruciale per risolvere questo errore.<\/p>\n<h3 id=\"h-2-perform-a-clean-boot\">2. Eseguire un avvio pulito<\/h3>\n<ol>\n<li>Per accedere alla ricerca, premere <kbd>Windows<\/kbd>+ <kbd>S<\/kbd>, digitare <strong>Configurazione di sistema<\/strong> e fare clic sul risultato corrispondente.<\/li>\n<li>Nella scheda <strong>Servizi<\/strong>, seleziona la casella &#8220;Nascondi tutti i servizi Microsoft&#8221;, quindi fai clic su <strong>Disabilita tutto<\/strong>.<img alt=\"disabilitare tutti i servizi\" class=\"wp-image\" decoding=\"async\" height=\"557\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/disable-services.webp\" title=\"disabilitare tutti i servizi\" width=\"854\"\/><\/li>\n<li>Vai alla scheda Avvio e fai clic <strong>su Apri Task Manager<\/strong>.<\/li>\n<li>In Task Manager, fai clic con il pulsante destro del mouse su tutte le applicazioni non critiche abilitate e seleziona <strong>Disabilita<\/strong>.<img alt=\"disabilitare le app di avvio\" class=\"wp-image\" decoding=\"async\" height=\"791\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/startup-app-disable.webp\" title=\"disabilitare le app di avvio\" width=\"1283\"\/><\/li>\n<li>Torna a Configurazione di sistema, fai clic su <strong>Applica<\/strong> e quindi su <strong>OK<\/strong>. Riavvia il sistema alla richiesta di conferma.<img alt=\"avvio pulito per correggere ERROR_WAS_LOCKED\" class=\"wp-image\" decoding=\"async\" height=\"209\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/restart-clean-boot.webp\" title=\"avvio pulito per correggere ERROR_WAS_LOCKED\" width=\"522\"\/><\/li>\n<li>Dopo il riavvio, controlla se ERROR_WAS_LOCKED si verifica ancora. Se scompare, \u00e8 probabile che un componente disabilitato sia la fonte del problema.<\/li>\n<\/ol>\n<p>Riattivare gradualmente i servizi e le app di avvio. Quando l&#8217;errore riemerge, spesso la causa \u00e8 l&#8217;ultimo servizio o applicazione riconfigurata. Se un servizio viene identificato come problematico, lascialo disabilitato e prendi in considerazione la disinstallazione del software problematico.<\/p>\n<h3 id=\"h-3-uninstall-conflicting-applications\">3. Rimuovere le applicazioni in conflitto<\/h3>\n<ol>\n<li>Premere <kbd>Windows<\/kbd>+ <kbd>R<\/kbd>per avviare la finestra di dialogo Esegui, digitare <strong>appwiz.cpl<\/strong>, quindi premere <kbd>Enter<\/kbd>.<\/li>\n<li>Identifica qualsiasi software installato di recente che ha coinciso con l&#8217;insorgenza dell&#8217;errore e selezionalo. Procedi cliccando su <strong>Disinstalla<\/strong>.<img alt=\"disinstallare le app in conflitto\" class=\"wp-image\" decoding=\"async\" height=\"831\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/uninstall-app.webp\" title=\"disinstallare le app in conflitto\" width=\"1331\"\/><\/li>\n<li>Seguire le istruzioni visualizzate sullo schermo per completare la disinstallazione, quindi riavviare il PC.<\/li>\n<\/ol>\n<p>Se la rimozione dell&#8217;applicazione non risolve ERROR_WAS_LOCKED, i file residui o le voci del Registro di sistema potrebbero ancora creare conflitti. In questo caso, prendi in considerazione l&#8217;utilizzo di programmi di disinstallazione software affidabili per rimuovere completamente qualsiasi traccia dell&#8217;applicazione.<\/p>\n<h3 id=\"h-4-run-windows-memory-diagnostic\">4. Eseguire la diagnostica della memoria di Windows<\/h3>\n<ol>\n<li>Premere <kbd>Windows<\/kbd>+ <kbd>S<\/kbd>per accedere alla Ricerca, digitare <strong>Diagnostica memoria Windows<\/strong> e selezionare il risultato corretto.<\/li>\n<li>Fare clic su <strong>Riavvia ora e verificare la presenza di problemi<\/strong>.<img alt=\"diagnostica della memoria\" class=\"wp-image\" decoding=\"async\" height=\"489\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/Windows-Memory-Diagnostic.webp\" title=\"diagnostica della memoria\" width=\"629\"\/><\/li>\n<li>Dopo la scansione, controlla i registri mdsched.exe per individuare eventuali problemi segnalati con la memoria.<\/li>\n<\/ol>\n<p>Se Windows Memory Diagnostic non identifica problemi, potresti voler usare uno strumento completo come <strong><a href=\"https:\/\/www.memtest.org\/\" rel=\"noreferrer noopener\" target=\"_blank\">Memtest86+<\/a><\/strong> per eseguire controlli approfonditi su ogni modulo di memoria. Se vengono rilevati guasti, preparati a sostituire la RAM stick difettosa!<\/p>\n<h3 id=\"h-5-perform-a-system-restore\">5. Eseguire un ripristino del sistema<\/h3>\n<ol>\n<li>Premere <kbd>Windows<\/kbd>+ <kbd>S<\/kbd>, digitare <strong>Crea un punto di ripristino<\/strong> e fare clic sulla voce pertinente.<\/li>\n<li>Selezionare <strong>Ripristino configurazione di sistema<\/strong>.<img alt=\"ripristinare per correggere ERROR_WAS_LOCKED\" class=\"wp-image\" decoding=\"async\" height=\"710\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/system-restore-1-2.webp\" title=\"ripristinare per correggere ERROR_WAS_LOCKED\" width=\"615\"\/><\/li>\n<li>Se proposto, seleziona <strong>Scegli un punto di ripristino diverso<\/strong> e fai clic su <strong>Avanti<\/strong>.<img alt=\"scegli un punto di ripristino diverso\" class=\"wp-image\" decoding=\"async\" height=\"672\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/different-restore-point-1.webp\" title=\"scegli un punto di ripristino diverso\" width=\"851\"\/><\/li>\n<li>Selezionare il punto di ripristino pi\u00f9 vecchio disponibile e fare clic su <strong>Avanti<\/strong>.<img alt=\"punto di ripristino pi\u00f9 vecchio\" class=\"wp-image\" decoding=\"async\" height=\"672\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2025\/02\/pick-restore-point.webp\" title=\"punto di ripristino pi\u00f9 vecchio\" width=\"851\"\/><\/li>\n<li>Verificare le selezioni, fare clic su <strong>Fine<\/strong> e accettare la richiesta di conferma.<\/li>\n<li>Attendere il completamento del processo di ripristino del sistema, che in genere richiede circa 15-45 minuti.<\/li>\n<\/ol>\n<p>Se i precedenti passaggi di risoluzione dei problemi non hanno risolto ERROR_WAS_LOCKED (717), eseguire un ripristino del sistema pu\u00f2 spesso porre rimedio alla situazione. Se continua a persistere, potrebbe essere necessario chiedere assistenza a uno specialista hardware o recarsi in un&#8217;officina per un controllo diagnostico. A questo punto, un problema hardware potrebbe essere probabilmente l&#8217;origine del codice di errore 717.<\/p>\n<p>Sentiti libero di condividere le tue esperienze, porre domande o commentare qui sotto quale metodo ha risolto efficacemente il tuo problema!<\/p>\n<h2>Domande frequenti<\/h2>\n<h3><strong>1. Cosa causa l&#8217;errore ERROR_WAS_LOCKED in Windows?<\/strong><\/h3>\n<p>L&#8217;ERROR_WAS_LOCKED, o errore di sistema Windows 717, si verifica in genere quando Windows tenta di bloccare una pagina di memoria che \u00e8 gi\u00e0 bloccata. Questa situazione spesso deriva da file di sistema corrotti, applicazioni incompatibili o RAM difettosa.<\/p>\n<h3><strong>2.\u00c8 sicuro eseguire un avvio pulito in Windows?<\/strong><\/h3>\n<p>S\u00ec, eseguire un avvio pulito \u00e8 sicuro ed \u00e8 una tecnica utile per la risoluzione dei problemi. Avvia Windows con driver e programmi di avvio minimi, aiutandoti a identificare se i programmi in background stanno causando problemi, come l&#8217;errore ERROR_WAS_LOCKED.<\/p>\n<h3><strong>3. Quanto tempo richiede il ripristino del sistema?<\/strong><\/h3>\n<p>Un ripristino del sistema richiede solitamente dai 15 ai 45 minuti per essere completato, a seconda delle prestazioni del sistema e dell&#8217;entit\u00e0 delle modifiche ripristinate.\u00c8 essenziale non interrompere questo processo per ottenere i migliori risultati.<\/p>\n<p><a class=\"xiaomi\" href=\"https:\/\/windowsreport.com\/error-was-locked\/\" rel=\"noopener noreferrer nofollow\" target=\"_blank\">Fonte e immagini<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incontrare l&#8217;ERROR_WAS_LOCKED, noto anche come errore di sistema Windows 717, pu\u00f2 essere piuttosto frustrante. Questo errore indica che \u00e8 stato effettuato un tentativo di bloccare una pagina in memoria che \u00e8 gi\u00e0 bloccata, spesso a causa di file di sistema corrotti, applicazioni in conflitto o persino RAM difettosa. Il messaggio di errore esatto recita: {Pagina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-8119","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/8119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=8119"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/8119\/revisions"}],"predecessor-version":[{"id":8120,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/8119\/revisions\/8120"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=8119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=8119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=8119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}