{"id":8293,"date":"2025-02-08T14:07:59","date_gmt":"2025-02-08T14:07:59","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=8293"},"modified":"2025-02-08T14:07:59","modified_gmt":"2025-02-08T14:07:59","slug":"stepbystep-guide-to-access-devices-and-printers-in-windows-11","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/stepbystep-guide-to-access-devices-and-printers-in-windows-11\/","title":{"rendered":"Guida dettagliata per accedere a &#8220;Dispositivi e stampanti&#8221; in Windows 11"},"content":{"rendered":"<h2>Come accedere alla pagina Dispositivi e stampanti classici su Windows 11<\/h2>\n<p>Sebbene la classica sezione &#8220;Dispositivi e stampanti&#8221; non sia stata eliminata da Windows 11, Microsoft ne ha reso meno semplice l&#8217;accesso. Fortunatamente, puoi comunque raggiungere questa pagina importante con alcuni passaggi di navigazione aggiuntivi.<\/p>\n<h2><span id=\"1_Open_the_Old_Devices_and_Printers_from_the_RUN_dialog_box\"><strong>1. Aprire rapidamente Dispositivi e stampanti tramite la finestra di dialogo ESEGUI<\/strong><\/span><\/h2>\n<p>La finestra di dialogo RUN \u00e8 il percorso pi\u00f9 rapido per accedere alla pagina &#8216;Devices and Printers&#8217; (Dispositivi e stampanti).Segui questi semplici passaggi:<\/p>\n<ul>\n<li>Premere il <strong>tasto Windows + R<\/strong> sulla tastiera per aprire la finestra di dialogo ESEGUI.<\/li>\n<li><\/li>\n<li>Nella finestra di dialogo ESEGUI, incolla il seguente comando e premi Invio:<\/li>\n<p> <code><strong>shell:::{A8A91A66-3A7D-4424-8D24-04E180695C7A}<\/strong><\/code><\/p>\n<li><\/li>\n<li>Si aprir\u00e0 immediatamente la pagina classica <strong>Dispositivi e stampanti.<\/strong><\/li>\n<li><\/li>\n<\/ul>\n<h2><span id=\"2_Open_classic_Devices_and_Printers_from_the_Settings\"><strong>2. Accedi ai dispositivi e alle stampanti tramite le impostazioni<\/strong><\/span><\/h2>\n<p>Sebbene un po&#8217; nascosto, puoi comunque accedere a Dispositivi e stampanti tramite l&#8217;app Impostazioni di Windows eseguendo la seguente sequenza:<\/p>\n<ul>\n<li>Fare clic sul pulsante Start di Windows 11 e quindi selezionare <strong>Impostazioni<\/strong>.<\/li>\n<li><\/li>\n<li>Nelle Impostazioni, vai su <strong>Bluetooth e dispositivi<\/strong>.<\/li>\n<li><\/li>\n<li>Sul lato destro, fare clic su <strong>Dispositivi<\/strong>.<\/li>\n<li><\/li>\n<li>Scorri verso il basso fino alla sezione <strong>Impostazioni correlate<\/strong> e seleziona <strong>Altre impostazioni dispositivo e stampante<\/strong>.<\/li>\n<li><\/li>\n<li>Questa azione aprir\u00e0 la finestra Dispositivi e stampanti.<\/li>\n<li><\/li>\n<\/ul>\n<h2><span id=\"3_Create_a_Shortcut_to_open_classic_Devices_and_Printers\"><strong>3. Crea un collegamento sul desktop per un accesso rapido<\/strong><\/span><\/h2>\n<p>Questo metodo semplice consente di creare un collegamento sul desktop alla pagina classica Dispositivi e stampanti:<\/p>\n<ul>\n<li>Digita <strong>Pannello di controllo<\/strong> nella barra di ricerca di Windows 11 e fai clic per aprire il <strong>Pannello di controllo<\/strong> dai risultati della ricerca.<\/li>\n<li><\/li>\n<li>Una volta aperta, modifica la visualizzazione selezionando <strong>Icone piccole<\/strong> o <strong>Icone grandi<\/strong> dal menu a discesa Visualizza per.<\/li>\n<li><\/li>\n<li>Fare clic con il pulsante destro del mouse su <strong>Dispositivi e stampanti<\/strong>, quindi selezionare <strong>Crea collegamento<\/strong>.<\/li>\n<li><\/li>\n<li>Quando viene richiesto di creare un collegamento sul desktop, fare clic su <strong>S\u00ec<\/strong>.<\/li>\n<li><\/li>\n<\/ul>\n<h2><span id=\"4_Add_Devices_and_Printers_to_the_Navigation_Pane_of_File_Explorer\"><strong>4. Integrare dispositivi e stampanti nel riquadro di navigazione di Esplora file<\/strong><\/span><\/h2>\n<p>\u00c8 possibile aggiungere un collegamento alla pagina Dispositivi e stampanti direttamente nel riquadro di spostamento di Esplora file tramite il metodo seguente.<\/p>\n<p>Se ti senti a tuo agio nel modificare il registro, puoi scegliere di scaricare un file di registro per integrare Dispositivi e stampanti nel riquadro di navigazione. Ecco come:<\/p>\n<ul>\n<li>Scegli se desideri che il collegamento sia in <strong>alto<\/strong> o <strong>in basso<\/strong> nel riquadro di spostamento e scarica il file di registro corrispondente:<\/li>\n<ul>\n<li><strong><a href=\"https:\/\/www.elevenforum.com\/attachments\/add_devices_and_printers_to_top_of_navigation_pane_of_file_explorer-reg.34184\/?hash=dbed0abd82483a16b60c0662cd63e559\" rel=\"noopener noreferrer nofollow\" target=\"_blank\">Scarica il file del registro principale<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.elevenforum.com\/attachments\/add_devices_and_printers_to_bottom_of_navigation_pane_of_file_explorer-reg.45451\/?hash=ad17f75962fc2279204d0e0d0e58012b\" rel=\"noopener noreferrer nofollow\" target=\"_blank\">Scarica il file di registro in basso<\/a><\/strong><\/li>\n<\/ul>\n<li>Dopo il download, chiudere Esplora file.<\/li>\n<li>Fare doppio clic sul file di registro scaricato e confermare la richiesta di Controllo account utente (UAC) facendo clic su <strong>S\u00ec<\/strong>.<\/li>\n<li><\/li>\n<li>Il collegamento Dispositivi e stampanti verr\u00e0 aggiunto correttamente a Esplora file di Windows 11.<\/li>\n<li>Se in futuro volessi rimuovere questa scorciatoia, scarica ed esegui il <strong><a href=\"https:\/\/www.elevenforum.com\/attachments\/remove_devices_and_printers_from_navigation_pane_of_file_explorer-reg.34185\/?hash=dbed0abd82483a16b60c0662cd63e559\" rel=\"noopener noreferrer nofollow\" target=\"_blank\">file di rimozione del Registro di sistema<\/a><\/strong>.<\/li>\n<\/ul>\n<p>Questi metodi semplificano l&#8217;accesso ai classici Dispositivi e Stampanti in Windows 11. Se hai bisogno di ulteriore assistenza o riscontri problemi, non esitare a contattarci per ricevere aiuto!<\/p>\n<h2>Domande frequenti<\/h2>\n<h3><strong>1. Posso accedere a Dispositivi e Stampanti senza utilizzare la casella ESEGUI?<\/strong><\/h3>\n<p>S\u00ec, puoi accedere a Dispositivi e stampanti tramite l&#8217;app Impostazioni. Vai su Bluetooth e dispositivi, quindi seleziona Altre impostazioni dispositivo e stampante per aprirlo.<\/p>\n<h3><strong>2. Questi metodi funzionano anche sulle versioni precedenti di Windows?<\/strong><\/h3>\n<p>Questi metodi sono specificamente progettati per Windows 11. Mentre alcuni potrebbero funzionare su versioni precedenti, segui le istruzioni per la tua specifica versione di Windows per risultati ottimali.<\/p>\n<h3><strong>3. Esiste un rischio nel modificare il registro per aggiungere dispositivi e stampanti?<\/strong><\/h3>\n<p>La modifica del registro pu\u00f2 causare problemi di sistema se non eseguita correttamente. Assicurati di eseguire il backup del registro prima di apportare modifiche e utilizza solo fonti attendibili per scaricare i file del registro.<\/p>\n<p><a class=\"xiaomi\" href=\"https:\/\/techviral.net\/open-devices-and-printers-windows-11\/\" rel=\"noopener noreferrer nofollow\" target=\"_blank\">Fonte e immagini<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come accedere alla pagina Dispositivi e stampanti classici su Windows 11 Sebbene la classica sezione &#8220;Dispositivi e stampanti&#8221; non sia stata eliminata da Windows 11, Microsoft ne ha reso meno semplice l&#8217;accesso. Fortunatamente, puoi comunque raggiungere questa pagina importante con alcuni passaggi di navigazione aggiuntivi. 1. Aprire rapidamente Dispositivi e stampanti tramite la finestra di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-8293","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-windows"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/8293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=8293"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/8293\/revisions"}],"predecessor-version":[{"id":8294,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/8293\/revisions\/8294"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=8293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=8293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=8293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}