{"id":990,"date":"2024-02-16T04:49:08","date_gmt":"2024-02-16T04:49:08","guid":{"rendered":"https:\/\/howtogeek.blog\/it\/?p=990"},"modified":"2024-02-16T04:49:08","modified_gmt":"2024-02-16T04:49:08","slug":"google-keeps-asking-to-fill-image-captcha-7-ways-to-fix-it-it","status":"publish","type":"post","link":"https:\/\/howtogeek.blog\/it\/google-keeps-asking-to-fill-image-captcha-7-ways-to-fix-it-it\/","title":{"rendered":"Google continua a chiedere di compilare il captcha dell&#8217;immagine? 7 modi per risolverlo"},"content":{"rendered":"<p>Se utilizzi il motore di ricerca di Google per effettuare ricerche sul Web, potresti aver riscontrato il messaggio di errore <strong>&#8220;Il nostro sistema ha rilevato traffico insolito dalla rete del tuo computer&#8221;<\/strong> .<\/p>\n<p>Ti sei mai chiesto cosa significa l&#8217;errore &#8220;Traffico insolito&#8221; su Google e come risolverlo? Quando viene visualizzato l&#8217;errore, ti viene chiesto di verificare il captcha.<\/p>\n<p>Potresti riscontrare l&#8217;errore quando digiti una query nella casella di ricerca di Google e premi il pulsante di ricerca. Quando vedi la schermata di errore, ti viene chiesto di risolvere il CAPTCHA (test di Turing pubblico completamente automatizzato per distinguere i computer dagli esseri umani).<\/p>\n<h3><span id=\"Why_does_Unusual_traffic_from_your_computer_network_appear\"><strong>Perch\u00e9 viene visualizzato il messaggio &#8220;Traffico insolito dalla rete del tuo computer&#8221;?<\/strong><\/span><\/h3>\n<p>In genere viene visualizzata la schermata di errore quando Google rileva traffico automatizzato. Se utilizzi bot o script per inviare traffico automatizzato a Google, vedrai questa schermata.<\/p>\n<p><strong>Google considera il traffico automatizzato quando esegui queste operazioni:<\/strong><\/p>\n<ul>\n<li>Invio di ricerche da robot, software, servizi automatizzati o raschietto di ricerca.<\/li>\n<li>Utilizzo di programmi che inviano ricerche a Google per vedere come si posiziona un sito web o una pagina web su Google.<\/li>\n<\/ul>\n<p>Quindi, se stai facendo queste due cose, hai una ragione. Ma, oltre alle considerazioni di Google, altri fattori attivano l&#8217;errore &#8220;Traffico insolito dalla rete del tuo computer&#8221;. Ecco qui alcuni di loro.<\/p>\n<ul>\n<li>Stai cercando troppo velocemente.<\/li>\n<li>L&#8217;uso di estensioni del browser di terze parti.<\/li>\n<li>Esecuzione di ricerche Google su una rete condivisa.<\/li>\n<li>Stai utilizzando servizi VPN o proxy.<\/li>\n<li>Il tuo PC contiene malware.<\/li>\n<\/ul>\n<h2><span id=\"How_to_Fix_Google_Keeps_Asking_to_Fill_Image_Captcha_Issue\"><strong>Come risolvere il problema relativo al captcha delle immagini che Google continua a chiedere di compilare?<\/strong><\/span><\/h2>\n<p>Se utilizzi software o bot che inviano traffico automatizzato a Google, puoi smettere di utilizzarlo per risolvere il problema. Prova questi metodi se ricevi ancora traffico insolito dall&#8217;errore di rete del tuo computer.<\/p>\n<h3><span id=\"1_Resolve_the_CAPTCHA\"><strong>1. Risolvi il CAPTCHA<\/strong><\/span><\/h3>\n<figure class=\"wp-block-image\"><img alt=\"Risolvi il CAPTCHA\" class=\"wp-image\" decoding=\"async\" height=\"584\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/CAPTCHA.webp\" title=\"Risolvi il CAPTCHA\" width=\"404\"\/><\/figure>\n<p>Come tutti sappiamo, quando Google rileva un utente che invia traffico automatizzato, mostra l&#8217;errore &#8220;Traffico insolito&#8221;.<\/p>\n<p>Insieme all&#8217;errore, vedi anche un&#8217;opzione che ti chiede di confermare che non sei un robot. Puoi toccare <strong>&#8220;Non sono un robot&#8221;<\/strong> per rimuovere il messaggio di errore.<\/p>\n<p>Ti verr\u00e0 chiesto di risolvere un captcha immagine se non vedi l&#8217;opzione &#8220;Non sono un robot&#8221;. Supera il test, a seconda di quello visualizzato, per risolvere il messaggio di errore &#8220;Traffico insolito&#8221;.<\/p>\n<h3><span id=\"2_Slow_down_your_Search\"><strong>2. Rallenta la ricerca<\/strong><\/span><\/h3>\n<p>L&#8217;utilizzo troppo rapido della ricerca Google dimostra l&#8217;utilizzo di un bot o di programmi per inviare traffico automatizzato. Pertanto, se stai cercando su Google troppo velocemente, vedrai sicuramente la schermata &#8220;Traffico insolito dalla rete del tuo computer&#8221;.<\/p>\n<p>Nella maggior parte dei casi, gli utenti vedono l&#8217;errore solo perch\u00e9 stanno effettuando la ricerca troppo velocemente. In tali eventi, Google contrassegna tali ricerche come automatizzate.<\/p>\n<p>La cosa migliore che puoi fare \u00e8 riavviare il browser web e rallentarlo. Puoi utilizzare la ricerca Google per un tempo illimitato, ma assicurati che non sia cos\u00ec veloce da apparire come un bot.<\/p>\n<h3><span id=\"3_Disable_the_VPNProxy_Services\"><strong>3. Disabilitare i servizi VPN\/Proxy<\/strong><\/span><\/h3>\n<figure class=\"wp-block-image\"><img alt=\"Disabilita il client VPN\" class=\"wp-image\" decoding=\"async\" height=\"456\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Reinstall-the-VPN-Client.webp\" title=\"Disabilita il client VPN\" width=\"810\"\/><\/figure>\n<p>L&#8217;utilizzo di servizi VPN o proxy porta spesso all&#8217;errore &#8220;Traffico insolito&#8221; nella Ricerca Google. Ci\u00f2 accade a causa degli indirizzi IP contrassegnati assegnati dalle VPN e dai servizi proxy.<\/p>\n<p>Inoltre, la VPN reindirizza il tuo traffico attraverso un server crittografato, il che rende difficile per Google rilevare la tua posizione effettiva, costringendolo ad assumere la tua connessione come &#8220;Automatizzata&#8221; o &#8220;Bot&#8221;.<\/p>\n<p>Quindi, se vuoi risolvere il problema che <strong>Google continua a chiedere di riempire il<\/strong> problema Image Captcha, devi disattivare i servizi VPN o proxy che stai utilizzando.<\/p>\n<h3><span id=\"4_Flush_the_DNS_cache\"><strong>4. Svuotare la cache DNS<\/strong><\/span><\/h3>\n<p>Sebbene la cache DNS non abbia un collegamento diretto con l&#8217;errore di ricerca di Google, svuotare la cache DNS ha aiutato molti utenti ad affrontare lo stesso problema.<\/p>\n<p>\u00c8 facile svuotare la cache DNS su un PC. Per questo, segui alcuni dei semplici passaggi che abbiamo condiviso di seguito.<\/p>\n<p>1. Fare clic su Ricerca di Windows e digitare &#8221; <strong>Prompt dei comandi<\/strong> &#8220;. Successivamente, fai clic con il pulsante destro del mouse sul prompt dei comandi e seleziona &#8221; <strong>Esegui come amministratore<\/strong> &#8220;.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Esegui come amministratore\" class=\"wp-image\" decoding=\"async\" height=\"598\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Flush-the-DNS-cache-1.webp\" title=\"Esegui come amministratore\" width=\"700\"\/><\/figure>\n<p>2. Quando si apre il prompt dei comandi, eseguire il comando:<\/p>\n<p> <code><strong>ipconfig\/release<\/strong><\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"ipconfig\/release\" class=\"wp-image\" decoding=\"async\" height=\"325\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Command-Prompt-1-2.webp\" title=\"ipconfig\/release\" width=\"700\"\/><\/figure>\n<p>3. Successivamente, \u00e8 necessario eseguire questo comando:<\/p>\n<p> <code><strong>ipconfig\/renew<\/strong><\/code><\/p>\n<figure class=\"wp-block-image\"><img alt=\"ipconfig\/release\" class=\"wp-image\" decoding=\"async\" height=\"379\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Command-Prompt-2.webp\" title=\"ipconfig\/release\" width=\"700\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ora riavvia il browser web e utilizza nuovamente Ricerca Google. Questa volta non vedrai pi\u00f9 Google Image Captcha.<\/p>\n<h3><span id=\"5_Clear_the_Browsing_History\"><strong>5. Cancella la cronologia di navigazione<\/strong><\/span><\/h3>\n<p>Se il motore di ricerca continua a chiederti di inserire il captcha di testo o immagine ad ogni ricerca, devi cancellare la cronologia di navigazione. Poich\u00e9 il colosso della ricerca utilizza i cookie per rilevare bot e software automatizzato, cancellare la cronologia di navigazione e i cookie sarebbe utile.<\/p>\n<p>Di seguito, abbiamo dimostrato i passaggi per il browser Google Chrome. Devi fare lo stesso su qualsiasi altro browser web che utilizzi.<\/p>\n<p>1. Apri il browser Google Chrome e fai clic sui <strong>tre punti<\/strong> nell&#8217;angolo in alto a destra.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"tre punti\" class=\"wp-image\" decoding=\"async\" height=\"238\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Clear-the-Browsing-History-1.webp\" title=\"tre punti\" width=\"478\"\/><\/figure>\n<p>2. Dall&#8217;elenco di opzioni visualizzato, seleziona <strong>Altri strumenti<\/strong> &gt; <strong>Cancella dati di navigazione<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Altri strumenti &gt; Cancella dati di navigazione\u201d title=\u201dAltri strumenti &gt; Cancella dati di navigazione\u201d larghezza=\u201d457\u2033 altezza=\u201d500\u2033 caricamento=\u201dlazy\u201d class=\u201dwp-image\u201d src=\u201dhttps:\/\/cdn.howtogeek. blog\/wp-content\/uploads\/2024\/02\/Clear-the-Browsing-History-2.webp\u201d\/&gt;&lt;\/figure&gt; &lt;p&gt;3. Passa alla scheda &lt;strong&gt;Avanzate&lt;\/strong&gt; e seleziona &lt;strong&gt; &quot;Tutto il tempo&quot;&lt;\/strong&gt; nell'intervallo di tempo.&lt;\/p&gt; &lt;figure class=\" wp-block-image=\"\"\/><img alt=\"'Sempre'\" class=\"wp-image\" decoding=\"async\" height=\"334\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Clear-the-Browsing-History-3.webp\" title=\"'Sempre'\" width=\"514\"\/><\/figure>\n<p>4. Seleziona Cronologia esplorazioni, Cookie e altri dati dei siti, Immagini e file memorizzati nella cache. Una volta terminato, fai clic sul pulsante <strong>Cancella dati<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Cancella i dati\" class=\"wp-image\" decoding=\"async\" height=\"600\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Clear-the-Browsing-History-4.webp\" title=\"Cancella i dati\" width=\"498\"\/><\/figure>\n<p>Questo \u00e8 tutto! Ecco come puoi cancellare i dati di navigazione e i cookie del browser web Google Chrome.<\/p>\n<h3><span id=\"6_Run_an_Antivirus_Scan\"><strong>6. Eseguire una scansione antivirus<\/strong><\/span><\/h3>\n<p>Il malware pu\u00f2 essere eseguito in background e tenere traccia di tutte le query di ricerca. Potrebbe persino acquisire i dati di navigazione e le informazioni del PC.<\/p>\n<p>Pertanto, \u00e8 necessario eseguire una scansione completa con Sicurezza di Windows per rimuovere il malware nascosto che attiva l&#8217;errore &#8220;Traffico insolito dalla rete del computer&#8221; nel motore di ricerca. Ecco cosa devi fare.<\/p>\n<p>1. Innanzitutto, fai clic su Ricerca di Windows e digita <strong>Sicurezza di Windows<\/strong> . Successivamente, apri l&#8217;app Sicurezza di Windows dall&#8217;elenco.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Sicurezza di Windows\" class=\"wp-image\" decoding=\"async\" height=\"657\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Run-an-Antivirus-Scan-1-2.webp\" title=\"Sicurezza di Windows\" width=\"773\"\/><\/figure>\n<p>2. Quando si apre l&#8217;app Sicurezza di Windows, passa alla scheda <strong>Protezione da virus e minacce<\/strong> .<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Protezione da virus e minacce\" class=\"wp-image\" decoding=\"async\" height=\"591\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Run-an-Antivirus-Scan-2.webp\" title=\"Protezione da virus e minacce\" width=\"876\"\/><\/figure>\n<p>3. Sul lato destro, fare clic su &#8221; <strong>Opzioni di scansione<\/strong> &#8220;.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Opzioni di scansione\" class=\"wp-image\" decoding=\"async\" height=\"590\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Run-an-Antivirus-Scan-3-1.webp\" title=\"Opzioni di scansione\" width=\"654\"\/><\/figure>\n<p>4. Selezionare &#8220;Scansione completa&#8221; e fare clic sul pulsante &#8221; <strong>Scansione ora<\/strong> &#8220;.<\/p>\n<figure class=\"wp-block-image\"><img alt=\"Scannerizza adesso\" class=\"wp-image\" decoding=\"async\" height=\"585\" loading=\"lazy\" src=\"https:\/\/cdn.howtogeek.blog\/wp-content\/uploads\/2024\/02\/Run-an-Antivirus-Scan-4.webp\" title=\"Scannerizza adesso\" width=\"792\"\/><\/figure>\n<p>Questo \u00e8 tutto! Il completamento della scansione completa potrebbe richiedere un&#8217;ora. Quindi, non riavviare o spegnere il computer se il processo sembra bloccato.<\/p>\n<h3><span id=\"7_Switch_to_a_Different_Web_Browser\"><strong>7. Passa a un browser Web diverso<\/strong><\/span><\/h3>\n<p>Se il problema riguarda il tuo indirizzo IP, ti verr\u00e0 chiesto di risolvere il CAPTCHA dell&#8217;immagine indipendentemente dal browser web che utilizzi.<\/p>\n<p>Tuttavia, se ti viene chiesto di dimostrare che non sei un bot a causa di impostazioni errate del browser, cambiare browser web potrebbe essere d&#8217;aiuto.<\/p>\n<p>Il passaggio al browser Web ha avvantaggiato molti utenti nel risolvere il problema relativo al CAPTCHA dell&#8217;immagine che Google continua a chiedere. Quindi, se fino ad ora non ha funzionato nulla, puoi anche provare a farlo. Oppure puoi aspettare finch\u00e9 Google non rimuover\u00e0 gli interruttori di velocit\u00e0 per te.<\/p>\n<p>Google continua a chiederti di compilare il captcha dell&#8217;immagine pu\u00f2 essere problematico, soprattutto se fai eccessivo affidamento sul motore di ricerca di Google. Nella maggior parte dei casi, un riavvio, un ripristino del router o i metodi che abbiamo condiviso risolveranno il problema. Se hai bisogno di ulteriore aiuto per risolvere l&#8217;errore &#8220;Traffico insolito&#8221; di Google, faccelo sapere nei commenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se utilizzi il motore di ricerca di Google per effettuare ricerche sul Web, potresti aver riscontrato il messaggio di errore &#8220;Il nostro sistema ha rilevato traffico insolito dalla rete del tuo computer&#8221; . Ti sei mai chiesto cosa significa l&#8217;errore &#8220;Traffico insolito&#8221; su Google e come risolverlo? Quando viene visualizzato l&#8217;errore, ti viene chiesto di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[56],"class_list":["post-990","post","type-post","status-publish","format-standard","hentry","category-how-to","tag-tips"],"acf":[],"_links":{"self":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/comments?post=990"}],"version-history":[{"count":1,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/990\/revisions"}],"predecessor-version":[{"id":991,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/posts\/990\/revisions\/991"}],"wp:attachment":[{"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/categories?post=990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtogeek.blog\/it\/wp-json\/wp\/v2\/tags?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}